{"id":134125,"date":"2024-05-03T20:00:27","date_gmt":"2024-05-03T17:00:27","guid":{"rendered":"http:\/\/walltopia.com\/unkategorisiert\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/"},"modified":"2026-01-15T18:13:40","modified_gmt":"2026-01-15T15:13:40","slug":"besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/","title":{"rendered":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8220;&#8220;]\n<p>Wir freuen uns, auf dem <a href=\"https:\/\/www.cwasummit.org\/\">CWA Summit 2024<\/a> in Portland, Oregon, ausstellen zu k\u00f6nnen &#8211; Nordamerikas wichtigstem Indoor-Kletterevent des Jahres. Wir freuen uns darauf, mit aktuellen und potenziellen Kunden, Partnern und Freunden pers\u00f6nlich in Kontakt zu treten.<\/p>\n<p>Besuchen Sie Walltopia am Stand 901 und treffen Sie unser Expertenteam, das Ihnen gerne Fragen beantwortet und Ihnen von unseren neuesten Produkten und Innovationen erz\u00e4hlt (oder \u00fcber gute Rockmusik spricht). Wir werden Muster einer breiten Palette von Kletterwandplatten in einer Vielzahl von Designoptionen sowie unsere neuesten Halte- und Makroformen ausstellen. Sie werden auch Beispiele f\u00fcr unser SmartGate, Self Belay und Boulder- und Seilb\u00f6den sehen &#8211; alles M\u00f6glichkeiten, wie wir Ihnen helfen k\u00f6nnen, die Risiken in Ihrer Einrichtung zu kontrollieren.<\/p>\n<p><strong>Unten k\u00f6nnen Sie sehen, was wir in Portland pr\u00e4sentieren werden:<\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1708973217612{margin-top: 50px !important;}&#8220;][vc_column][vc_custom_heading text=&#8220;NEW Thermoplastische Makros&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; link=&#8220;url:https%3A%2F%2Fwalltopia.com%2Fnewsroom%2F100-recyclable-walltopia-thermoplastic-climbing-macros-and-volumes%2F%20%20|target:_blank|&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Wir bei Walltopia entwickeln mit Leidenschaft Produkte, die nicht nur das Klettererlebnis des Endverbrauchers verbessern, sondern auch die Abl\u00e4ufe f\u00fcr Fitnessstudiobesitzer und -manager rationalisieren. Kommen Sie und sehen Sie sich die neuen 100% recycelbaren <a href=\"http:\/\/walltopia.com\/newsroom\/100-recyclable-walltopia-thermoplastic-climbing-macros-and-volumes\/\">thermoplastischen Makros und Volumen<\/a> an. Optimieren Sie die Arbeitsabl\u00e4ufe und die Effizienz Ihres Fitnessstudios, indem Sie sich f\u00fcr die Routenplanung entscheiden:<\/p>\n<p>\ud83d\udc4dAu\u00dfergew\u00f6hnliche Griffigkeit f\u00fcr ein verbessertes Klettererlebnis<br \/>\n\ud83d\udc4dMinimales Gewicht f\u00fcr m\u00fcheloses Einrichten von Routen<br \/>\n\ud83d\udc4dAugenf\u00e4lliges Design f\u00fcr charakteristische Routen<br \/>\n\ud83d\udc4dSchnelle Produktion f\u00fcr effizientes Nachf\u00fcllen<br \/>\n\ud83d\udc4dVollst\u00e4ndig recycelbar und aus recyceltem Kunststoff hergestellt<\/p>\n<p>Das neue Sortiment kann im <a href=\"https:\/\/holdtopia.com\/Volumes?material=Plastic&amp;page=1\">Holdtopia Online-Shop<\/a> bestellt werden.[\/vc_column_text][vc_gallery interval=&#8220;3&#8243; images=&#8220;118237,118265,110190,118244,118251,118258&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1714496986189{margin-top: 30px !important;}&#8220;][vc_column_text css=&#8220;&#8220;]\n<p>Nachhaltigkeit geht f\u00fcr uns \u00fcber die Verwendung recycelbarer Materialien hinaus. Es geht darum, robuste, strapazierf\u00e4hige Produkte herzustellen, die den Abfall und die Umweltbelastung minimieren. Wir ziehen es vor, in Qualit\u00e4t zu investieren, die zu langlebigen Produkten f\u00fchrt und den Bedarf an Ersatzprodukten und den Ressourcenverbrauch reduziert.<br \/>\nErfahren Sie mehr dar\u00fcber in <a href=\"http:\/\/walltopia.com\/newsroom\/sustainability-through-quality-and-durability-the-walltopia-way\/\">dem Artikel hier.<\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1708973128805{margin-top: 50px !important;}&#8220;][vc_column][vc_custom_heading text=&#8220;Unsere Kletterwandpaneele &#8211; die beste Wahl auf dem Markt&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1715187330467{margin-top: 50px !important;}&#8220;][vc_column_text css=&#8220;&#8220;]\n<p><a href=\"https:\/\/youtu.be\/iqpEFP5WFxE\"><strong>Schmutzabweisende Beschichtung<\/strong><\/a><\/p>\n<p>Bei Walltopia sind wir Sauberkeitsfanatiker. Wir waren der erste Wandlieferant, der sich auf die Entwicklung einer Beschichtung konzentrierte, die das frische Aussehen der W\u00e4nde l\u00e4nger bewahrt, indem sie verhindert, dass der Schuhgummi an der Wand haftet, und wir sind stolz auf unser Ergebnis. Unsere spezielle schmutzabweisende Beschichtung erm\u00f6glicht eine einfache Reinigung und Pflege der Wandoberfl\u00e4che. Kommen Sie und testen Sie es selbst am Stand! Markieren Sie eine Musterplatte mit einem Kletterschuh und b\u00fcrsten Sie sie ab.<br \/>\nWir haben daf\u00fcr gesorgt, dass Sie gen\u00fcgend Schuhe zum Zerst\u00f6ren mitbringen.<\/p>\n[\/vc_column_text][vc_video link=&#8220;https:\/\/youtu.be\/iqpEFP5WFxE&#8220; css=&#8220;.vc_custom_1714755684423{margin-top: 30px !important;}&#8220;][vc_column_text css=&#8220;.vc_custom_1714755695929{margin-top: 30px !important;}&#8220;]\n<p><em>*Bitte beachten Sie, dass es noch andere Faktoren gibt, die zur Sauberkeit der W\u00e4nde beitragen. Um die Vorteile unserer schmutzabweisenden Beschichtung voll auszunutzen, raten wir dringend dazu, Teppichb\u00f6den zu verwenden, die Turnhalle insgesamt sauber zu halten, t\u00e4glich zu staubsaugen und Reinigungsmittel auf Alkoholbasis auf dem Boden oder den W\u00e4nden zu vermeiden. Reinigungsmittel auf Alkoholbasis l\u00f6sen das Gummi der Kletterschuhe an, machen es viel klebriger und f\u00fchren so zu schmutzigen W\u00e4nden.*<\/em><\/p>\n[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1714755708687{margin-top: 30px !important;}&#8220;]\n<p><strong>Naturholz<\/strong><\/p>\n<p>Wir haben eine <em>gro\u00dfe<\/em> Anzahl von Naturholzmustern mitgebracht, die eine Vielzahl von Furnieren und Kombinationsm\u00f6glichkeiten zeigen. Spielen Sie mit Texturen, Volltonfarben, LED-Lichtern, Furnieren, Karbonfasern und Split-Color-Formen &#8211; Sie k\u00f6nnen kreativ werden. Besuchen Sie unseren Galerie-Stand auf der CWA und sehen Sie sich unsere Panel-Muster an. Lassen Sie sich inspirieren, um ein Gef\u00fchl von Gem\u00fctlichkeit, Raffinesse und Eleganz in die Einrichtung Ihrer Kletterhalle zu bringen.<\/p>\n[\/vc_column_text][vc_gallery interval=&#8220;3&#8243; images=&#8220;120445,120453&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1714753319660{margin-top: 30px !important;}&#8220;][vc_column_text css=&#8220;&#8220;]\n<p><strong>St\u00e4rke der Beschichtung<\/strong><\/p>\n<p>Testen Sie die Festigkeit der Sperrholz-Kletterplatten von Walltopia.<br \/>\nUnsere Platten sind aus starkem Birkensperrholz gefertigt und mit einem hochwertigen Finish versehen, um extrem verschlei\u00dffest zu sein. Sie k\u00f6nnen viel mehr Schrauben aushalten als viele andere Platten auf dem Markt. Das gibt den Streckenplanern die kreative Freiheit, aufregende und herausfordernde Bewegungen f\u00fcr die Besucher des Fitnessstudios zu entwerfen.<\/p>\n<p>Kommen Sie an unseren Stand, um ein paar Schrauben in eine Musterplatte zu bohren, und \u00fcberzeugen Sie sich selbst!<\/p>\n[\/vc_column_text][vc_gallery interval=&#8220;3&#8243; images=&#8220;120421,120429,120405,120397,120389,120437,120413&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1714752744685{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8220;Holdtopia&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1711013372097{margin-top: 50px !important;}&#8220; link=&#8220;url:https%3A%2F%2Fyoutu.be%2FjaAoZamS38c|target:_blank|&#8220;][vc_column_text css=&#8220;.vc_custom_1715188386170{margin-top: 30px !important;}&#8220;]\n<p><a href=\"http:\/\/www.holdtopia.com\">Holdtopia<\/a> ist unsere Plattform, auf der wir 53 verschiedene Marken und B\u00e4nde im gr\u00f6\u00dften Online-Store der Branche anbieten. Navigieren Sie durch eine gro\u00dfe Auswahl an Marken, Gr\u00f6\u00dfen und Farben, einschlie\u00dflich der von der IFSC zugelassenen Marken im Katalog f\u00fcr Paris 2024. Mit unserer Funktion f\u00fcr Gro\u00dfbestellungen ist es ein Kinderspiel, eine gro\u00dfe Auswahl an Klettergriffen zusammenzustellen. So erhalten Sie genau das, was Sie brauchen, um Ihre Kreativit\u00e4t bei der erstmaligen Einrichtung von Kletterrouten oder bei der regelm\u00e4\u00dfigen Neueinrichtung und Erneuerung zu inspirieren.<\/p>\n<p>Erfahren Sie im folgenden Video mehr \u00fcber die UX-Funktionen von Holdtopia und wie Sie sie optimal f\u00fcr sich nutzen k\u00f6nnen.<\/p>\n[\/vc_column_text][vc_video link=&#8220;https:\/\/www.youtube.com\/watch?v=jaAoZamS38c&#8220; css=&#8220;.vc_custom_1714755789363{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1715200664302{margin-top: 30px !important;}&#8220;][vc_column][vc_custom_heading text=&#8220;Srandard Vorgefertigte Boulderwand Designs&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1715289728911{margin-top: 50px !important;}&#8220; link=&#8220;url:https%3A%2F%2Fyoutu.be%2FjaAoZamS38c|target:_blank|&#8220;][vc_column_text css=&#8220;.vc_custom_1715290668340{margin-top: 30px !important;}&#8220;]\n<p>Wir haben eine Reihe von gut durchdachten Boulderwandmodulen entworfen, die Teil unseres Standardkatalogs sind. Diese vorgefertigten und vorgefertigten W\u00e4nde sind perfekt gestaltete Felsbl\u00f6cke, die f\u00fcr verschiedene Routen geeignet sind. Sie sind f\u00fcr eine Vielzahl von Veranstaltungsorten geeignet und werden zu einem fairen Preis angeboten, da das Design und die Technik bereits fertiggestellt sind! Kommen Sie zu unserem Stand, um mehr zu erfahren und ein Angebot einzuholen.<\/p>\n[\/vc_column_text][vc_gallery interval=&#8220;3&#8243; images=&#8220;120566,120574,120582,120590,120598,120606,120614&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1715197332386{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1714755960656{margin-top: 50px !important;}&#8220;][vc_column][vc_custom_heading text=&#8220;Das Sicherheitsgespr\u00e4ch&#8220; font_container=&#8220;tag:h1|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1715188225961{margin-top: 50px !important;}&#8220;][vc_custom_heading text=&#8220;Eine weitere Sicherheitsmatte&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1711013706811{margin-top: 50px !important;}&#8220;][vc_column_text css=&#8220;&#8220;]\n<p><a href=\"http:\/\/www.climbmat.com\">Climbmat<\/a>, die Bodenbelagsmarke von Walltopia, entwickelt und testet alle seine Bodenbelagsl\u00f6sungen unter Einhaltung <em>und \u00dcbertreffen<\/em> der weltweiten Sicherheitsanforderungen und -standards.<\/p>\n<p>Was Seilw\u00e4nde betrifft, so gibt es keine verbindlichen Vorschriften f\u00fcr den Bodenbelag bei Kletteraktivit\u00e4ten \u00fcber 5 m, aber wir halten es f\u00fcr unsere moralische Pflicht, darauf hinzuweisen, wie wichtig es ist, W\u00e4nde und Kletterattraktionen mit geeigneten Matten auszustatten. Deshalb haben wir eine spezielle Bodenl\u00f6sung namens One More Life entwickelt, die das Risiko schwerer Verletzungen im Falle eines Sturzes aus einer H\u00f6he zwischen 7 m und 17 m deutlich verringert. One More Life soll f\u00fcr den Kletterer so funktionieren wie der Airbag in einem Auto f\u00fcr den Beifahrer. Im Falle eines Sturzes ist One More Life so konzipiert, dass es einen Gro\u00dfteil der kinetischen Energie absorbiert und die Abbremskraft verringert, um das Risiko schwerer Verletzungen zu reduzieren.<\/p>\n[\/vc_column_text][vc_video link=&#8220;https:\/\/youtu.be\/Giandpyrmto&#8220; css=&#8220;.vc_custom_1715338991543{padding-top: 20px !important;padding-bottom: 20px !important;}&#8220; title=&#8220;Falltest aus 55 ft auf One More Life Matte&#8220;][vc_column_text css=&#8220;&#8220;]\n<p>Mit Hilfe von Dummy-an &#8211; unserem Crashtest-Dummy aus der Automobilindustrie &#8211; haben wir im Walltopia-Hauptquartier k\u00fcrzlich eine Reihe von Falltests von der Spitze der Kletterwand aus 55 Fu\u00df H\u00f6he durchgef\u00fchrt. Besuchen Sie unseren Stand und erfahren Sie mehr \u00fcber die Tests und die Ergebnisse, die durch Diagramme, Grafiken und eine Menge Daten \u00fcber die Aufpralltests unterst\u00fctzt werden.<\/p>\n<p>Muster der One More Life Matte und unserer verschiedenen Bodenl\u00f6sungen f\u00fcr Seilw\u00e4nde und Boulder werden an unserem Stand erh\u00e4ltlich sein. Treten und springen Sie auf die Matten oder setzen Sie sich auf sie, um sich mit uns zu unterhalten.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1714755960656{margin-top: 50px !important;}&#8220;][vc_column][vc_custom_heading text=&#8220;Intelligentes Tor&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; link=&#8220;url:https%3A%2F%2Fsafetyeng.eu%2Fproduct%2Fsmartgate%2F|target:_blank|&#8220;][vc_column_text css=&#8220;&#8220;]\n<p>Da das Klettern immer beliebter wird, ist es wichtig, die Sicherheit aller Kletterer &#8211; vom Anf\u00e4nger bis zum Profi &#8211; zu maximieren. <a href=\"https:\/\/safetyeng.eu\/product\/smartgate\/\">SmartGate<\/a> bietet sowohl den Betreibern von Kletterhallen als auch den Kletterern ein beruhigendes Gef\u00fchl der Sicherheit, indem es Risiken reduziert und das gesamte Klettererlebnis verbessert.<\/p>\n<p>SmartGate wurde von unserer Schwesterfirma <a href=\"https:\/\/safetyeng.eu\/product\/smartgate\/\">Safety Engineering<\/a> entwickelt und ist ein System zur \u00dcberwachung der Sicherung, das sicherstellt, dass die Kletterer sicher mit den Sicherungsger\u00e4ten verbunden sind. Es gibt einen akustischen und visuellen Alarm aus, wenn ein Kletterer nicht angeschnallt ist. Es ist einfach zu implementieren und kann an neuen oder bereits bestehenden Kletterw\u00e4nden installiert werden. Erfahren Sie mehr in <a href=\"http:\/\/walltopia.com\/newsroom\/upscale-the-safety-in-your-climbing-gym-with-smartgate-the-belay-attachment-monitoring-system\">dem Artikel hier.<\/a><\/p>\n[\/vc_column_text][vc_gallery interval=&#8220;3&#8243; images=&#8220;114215&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1711014598238{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8220;Self Belay&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1711013226339{margin-top: 50px !important;}&#8220; link=&#8220;url:https%3A%2F%2Fsafetyeng.eu%2Fproduct%2Fself-belay-2-0%2F|target:_blank|&#8220;][vc_video link=&#8220;https:\/\/youtu.be\/fARPiyMuaHc&#8220; css=&#8220;.vc_custom_1714755814349{margin-top: 30px !important;}&#8220;][vc_column_text css=&#8220;&#8220;]\n<p>Self Belay ist ein Kletterverbinder, der die Sicherheit erh\u00f6ht, indem er das Risiko menschlichen Versagens beim Einklinken in automatische Sicherungsger\u00e4te minimiert. Die patentierte Technologie vereinfacht die Bedienung und verringert die Anzahl der Mitarbeiter, die f\u00fcr die \u00dcberwachung ben\u00f6tigt werden. Die neueste Version von <a href=\"https:\/\/safetyeng.eu\/product\/self-belay-2-0\/\">Self Belay 2.0<\/a> mit doppelter Redundanz ist jetzt verf\u00fcgbar:<\/p>\n<p>\ud83d\udc4d Torsystem &#8211; zus\u00e4tzliches Tor als zus\u00e4tzliche Sicherheitsschicht<br \/>\n\ud83d\udc4d Schl\u00fcsselschutz &#8211; ein zus\u00e4tzlicher Schutz verhindert das Anschlagen der Schl\u00fcsselbolzen. Verhindert ein unbefugtes L\u00f6sen der Verbindung, selbst in dem unwahrscheinlichen Fall, dass ein abgebrochener Schl\u00fcssel verwendet wird.<br \/>\n\ud83d\udc4d Breiteres Drehgelenk &#8211; um die neuesten Gurtb\u00e4nder auf dem Markt vollst\u00e4ndig aufzunehmen<br \/>\n\ud83d\udc4d Verst\u00e4rkte Abdeckungen &#8211; ein spezieller Metalleinsatz, der in die neuen Abdeckungen eingebettet ist, um ihre Langlebigkeit zu maximieren<br \/>\n\ud83d\udc4d St\u00e4rkere Nieten, Bolzen und Clips<\/p>\n<p>Sie k\u00f6nnen es <a href=\"https:\/\/safetyeng.eu\/product\/self-belay-2-0\/\">hier<\/a> bestellen.<\/p>\n[\/vc_column_text][vc_images_carousel images=&#8220;112983&#8243; img_size=&#8220;full&#8220; css=&#8220;.vc_custom_1711014627644{margin-top: 50px !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Wir freuen uns, auf dem CWA Summit 2024 in Portland, Oregon, ausstellen zu k\u00f6nnen &#8211; Nordamerikas wichtigstem Indoor-Kletterevent des Jahres.","protected":false},"author":5,"featured_media":118229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[869,870],"tags":[],"class_list":["post-134125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-klettern","category-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon | Walltopia<\/title>\n<meta name=\"description\" content=\"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon\" \/>\n<meta property=\"og:description\" content=\"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T17:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T15:13:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon\",\"datePublished\":\"2024-05-03T17:00:27+00:00\",\"dateModified\":\"2026-01-15T15:13:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/\"},\"wordCount\":1931,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240424225444\\\/CWA-announce-2024_1920x1080-scaled.jpg\",\"articleSection\":[\"Klettern\",\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/\",\"name\":\"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240424225444\\\/CWA-announce-2024_1920x1080-scaled.jpg\",\"datePublished\":\"2024-05-03T17:00:27+00:00\",\"dateModified\":\"2026-01-15T15:13:40+00:00\",\"description\":\"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240424225444\\\/CWA-announce-2024_1920x1080-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20240424225444\\\/CWA-announce-2024_1920x1080-scaled.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Walltopia attending CWA summit 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon | Walltopia","description":"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/","og_locale":"de_DE","og_type":"article","og_title":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon","og_description":"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.","og_url":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2024-05-03T17:00:27+00:00","article_modified_time":"2026-01-15T15:13:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon","datePublished":"2024-05-03T17:00:27+00:00","dateModified":"2026-01-15T15:13:40+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/"},"wordCount":1931,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg","articleSection":["Klettern","Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/","url":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/","name":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg","datePublished":"2024-05-03T17:00:27+00:00","dateModified":"2026-01-15T15:13:40+00:00","description":"Wir erwarten Sie an Stand 901 mit unserem Expertenteam, das Sie gerne ausf\u00fchrlich \u00fcber unser neuestes breites Produktsortiment informieren wird.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20240424225444\/CWA-announce-2024_1920x1080-scaled.jpg","width":1200,"height":675,"caption":"Walltopia attending CWA summit 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/besuchen-sie-walltopia-auf-dem-cwa-gipfel-2024-in-portland-oregon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Besuchen Sie Walltopia auf dem CWA-Gipfel 2024 in Portland, Oregon"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/134125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=134125"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/134125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/118229"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=134125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=134125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=134125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}