{"id":181989,"date":"2021-06-17T14:58:09","date_gmt":"2021-06-17T11:58:09","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/"},"modified":"2026-01-15T16:56:05","modified_gmt":"2026-01-15T13:56:05","slug":"walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/","title":{"rendered":"Walltopia &#8211; der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8220;Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass Walltopia und die &quot;F\u00e9d\u00e9ration Fran\u00e7aise de la Montagne et de l&apos;Escalade&quot; gerade eine neue Partnerschaft unterzeichnet haben.&#8220; font_container=&#8220;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Wir werden f\u00fcr die n\u00e4chsten 4 Jahre offizieller Lieferant des FFME f\u00fcr Kletterw\u00e4nde sein &#8211; eine Zeit der gro\u00dfen Klettersaisonen f\u00fcr den franz\u00f6sischen Verband, voller internationaler Veranstaltungen. FFME ist der gr\u00f6\u00dfte nationale Verband der Welt und wir freuen uns sehr \u00fcber diese neue Partnerschaft, vor allem im Hinblick auf die n\u00e4chsten gro\u00dfen internationalen Veranstaltungen &#8211; wie die Kletterweltmeisterschaften 2016 -, die in Frankreich stattfinden werden. <\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8220;fadeInUp&#8220;]\n<blockquote>\n<p style=\"font-size: 19px; line-height: 1.8em;\"><span style=\"font-size: 17px;\">&#8222;Die Entscheidung f\u00fcr diese Partnerschaft war ganz klar. Walltopia ist eine vision\u00e4re Marke. Genau wie die Strategie von FFME: immer nach vorne zu gehen. Au\u00dferdem mussten wir einen soliden Partner mit internationalem Know-how finden, der die Entwicklungsstrategie der FFME f\u00fcr die kommenden Saisons unterst\u00fctzen will&#8220;, erkl\u00e4rt Marie-Anne MIDY, die bei der FFME f\u00fcr Kommunikation und Marketing zust\u00e4ndig ist.<\/span><\/p>\n<\/blockquote>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1623930730548{padding-top: 2% !important;}&#8220;][vc_column][vc_column_text css_animation=&#8220;fadeInUp&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Das erste Ereignis, das wir gemeinsam vorbereiten, ist der kommende Weltcup in Chamonix vom<strong> 10. bis 12. Juli<\/strong>.<\/p>\n[\/vc_column_text][vc_column_text css_animation=&#8220;fadeInUp&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>\u00dcber die <a href=\"https:\/\/www.ffme.fr\/\">FFME<\/a>:<\/strong> Die 1945 gegr\u00fcndete F\u00e9d\u00e9ration Fran\u00e7aise de la Montagne et de l&#8217;Escalade f\u00f6rdert 6 Aktivit\u00e4ten: Klettern, Bergsteigen, Schneeschuhwandern, Bergwandern, Canyoning und Skibergsteigen. Die FFME, die seit 2005 von Pierre-Henri Paillasson geleitet wird, hat mehr als 86 000 Mitglieder und mehr als 1000 Vereine. <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass Walltopia und die &#8222;F\u00e9d\u00e9ration Fran\u00e7aise de la Montagne et de l&#8217;Escalade&#8220; gerade eine neue Partnerschaft unterzeichnet haben.","protected":false},"author":10,"featured_media":21692,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[870],"tags":[2044,1964],"class_list":["post-181989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-ffme","tag-walltopia-klettern"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre\" \/>\n<meta property=\"og:description\" content=\"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T11:58:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia &#8211; der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre\",\"datePublished\":\"2021-06-17T11:58:09+00:00\",\"dateModified\":\"2026-01-15T13:56:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/\"},\"wordCount\":327,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090657\\\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg\",\"keywords\":[\"FFME\",\"Walltopia Klettern\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/\",\"name\":\"Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090657\\\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg\",\"datePublished\":\"2021-06-17T11:58:09+00:00\",\"dateModified\":\"2026-01-15T13:56:05+00:00\",\"description\":\"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090657\\\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090657\\\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia &#8211; der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre | Walltopia","description":"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/","og_locale":"de_DE","og_type":"article","og_title":"Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre","og_description":"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.","og_url":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-17T11:58:09+00:00","article_modified_time":"2026-01-15T13:56:05+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia &#8211; der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre","datePublished":"2021-06-17T11:58:09+00:00","dateModified":"2026-01-15T13:56:05+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/"},"wordCount":327,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg","keywords":["FFME","Walltopia Klettern"],"articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/","url":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/","name":"Walltopia - der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg","datePublished":"2021-06-17T11:58:09+00:00","dateModified":"2026-01-15T13:56:05+00:00","description":"Walltopia ist seit 4 Jahren offizieller Lieferant von FFME und verk\u00f6rpert damit eine gemeinsame Vision von Fortschritt und Innovation.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090657\/9fadb6d3e28e2be47da4c87e012c5962_XL.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/walltopia-der-offizielle-lieferant-von-ffme-fuer-die-naechsten-4-jahre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Walltopia &#8211; der offizielle Lieferant von FFME f\u00fcr die n\u00e4chsten 4 Jahre"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/181989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=181989"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/181989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/21692"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=181989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=181989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=181989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}