{"id":183950,"date":"2021-06-18T15:09:20","date_gmt":"2021-06-18T12:09:20","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/"},"modified":"2026-01-15T17:01:53","modified_gmt":"2026-01-15T14:01:53","slug":"walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/","title":{"rendered":"Walltopia pr\u00e4sentiert &#8222;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&#8220; auf der MIPIM Japan"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8220;W\u00e4hrend Einkaufszentren, Familienunterhaltungszentren und andere Vergn\u00fcgungseinrichtungen nach neuen Wegen suchen, um mehr Kunden anzulocken, sind Menschen auf der ganzen Welt hungrig nach einer neuen Art von Unterhaltung und die hei\u00dft Active Entertainment.&#8220; font_container=&#8220;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220; link=&#8220;url:https%3A%2F%2Fadventure.walltopia.com%2F|title:Active%20Entertainment|target:_blank|&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Kletterhallen, Vergn\u00fcgungszentren, Abenteuerfahrten und Attraktionen erfreuen sich immer gr\u00f6\u00dferer Beliebtheit. Es ist keine \u00dcberraschung, dass das Klettern mit der Aufnahme in das Programm der Olympischen Spiele die ultimative Anerkennung erhalten hat. Wir k\u00f6nnen Tokio 2020 kaum erwarten und bis dahin werden wir sicherlich aktiv am Wachstum der Kletter- und Unterhaltungsindustrie nicht nur in Japan, sondern weltweit teilnehmen. Seien Sie bei unserer Pr\u00e4sentation <strong>&#8222;Aktive Unterhaltung: ein Magnet f\u00fcr Kunden&#8220;<\/strong> auf der <a href=\"https:\/\/www.mipim.com\/\">MIPIM<\/a> Japan dabei, wenn unser Leiter f\u00fcr Design und Architektur, Vasil Sharlanov, unsere Ideen und Erfahrungen beim Bau von Kletter- und Vergn\u00fcgungszentren mit Ihnen teilt.   <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery interval=&#8220;3&#8243; images=&#8220;21962,21968,21974&#8243; img_size=&#8220;full&#8220; css_animation=&#8220;fadeInUp&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Wann:<\/strong> 11:30 &#8211; 12:30, 09. September 2016<br \/>\n<strong>Wo:<\/strong> Agora Saal<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=&#8220;W\u00e4hrend Einkaufszentren, Familienunterhaltungszentren und andere Vergn\u00fcgungseinrichtungen nach neuen Wegen suchen, um mehr Kunden anzulocken, sind Menschen auf der ganzen&#8230;","protected":false},"author":10,"featured_media":21956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[870],"tags":[970,2346],"class_list":["post-183950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-aktive-unterhaltung","tag-mipim-2016"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia pr\u00e4sentiert &quot;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&quot; auf der MIPIM Japan | Walltopia<\/title>\n<meta name=\"description\" content=\"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia&#039;s Active Entertainment. Entdecken Sie mehr auf der MIPIM.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia pr\u00e4sentiert &quot;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&quot; auf der MIPIM Japan\" \/>\n<meta property=\"og:description\" content=\"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia&#039;s Active Entertainment. Entdecken Sie mehr auf der MIPIM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T12:09:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:01:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia pr\u00e4sentiert &#8222;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&#8220; auf der MIPIM Japan\",\"datePublished\":\"2021-06-18T12:09:20+00:00\",\"dateModified\":\"2026-01-15T14:01:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090003\\\/mipim-japan.jpg\",\"keywords\":[\"aktive Unterhaltung\",\"MIPIM 2016\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/\",\"name\":\"Walltopia pr\u00e4sentiert \\\"Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden\\\" auf der MIPIM Japan | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090003\\\/mipim-japan.jpg\",\"datePublished\":\"2021-06-18T12:09:20+00:00\",\"dateModified\":\"2026-01-15T14:01:53+00:00\",\"description\":\"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia's Active Entertainment. Entdecken Sie mehr auf der MIPIM.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090003\\\/mipim-japan.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090003\\\/mipim-japan.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia pr\u00e4sentiert &#8220;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&#8221; auf der MIPIM Japan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia pr\u00e4sentiert \"Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden\" auf der MIPIM Japan | Walltopia","description":"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia's Active Entertainment. Entdecken Sie mehr auf der MIPIM.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/","og_locale":"de_DE","og_type":"article","og_title":"Walltopia pr\u00e4sentiert \"Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden\" auf der MIPIM Japan","og_description":"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia's Active Entertainment. Entdecken Sie mehr auf der MIPIM.","og_url":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T12:09:20+00:00","article_modified_time":"2026-01-15T14:01:53+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia pr\u00e4sentiert &#8222;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&#8220; auf der MIPIM Japan","datePublished":"2021-06-18T12:09:20+00:00","dateModified":"2026-01-15T14:01:53+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/"},"wordCount":238,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg","keywords":["aktive Unterhaltung","MIPIM 2016"],"articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/","url":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/","name":"Walltopia pr\u00e4sentiert \"Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden\" auf der MIPIM Japan | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg","datePublished":"2021-06-18T12:09:20+00:00","dateModified":"2026-01-15T14:01:53+00:00","description":"Erf\u00fcllen Sie die Nachfrage nach Unterhaltung in der heutigen hektischen Welt mit Walltopia's Active Entertainment. Entdecken Sie mehr auf der MIPIM.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090003\/mipim-japan.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/walltopia-praesentiert-aktive-unterhaltung-ein-magnet-fuer-kunden-auf-der-mipim-japan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Walltopia pr\u00e4sentiert &#8220;Aktive Unterhaltung: Ein Magnet f\u00fcr Kunden&#8221; auf der MIPIM Japan"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/183950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=183950"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/183950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/21956"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=183950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=183950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=183950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}