{"id":187205,"date":"2021-06-21T15:54:56","date_gmt":"2021-06-21T12:54:56","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/"},"modified":"2026-01-15T17:35:03","modified_gmt":"2026-01-15T14:35:03","slug":"walltopia-ifsc-zertifizierter-hersteller-von-speedwalls","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/","title":{"rendered":"Walltopia &#8211; IFSC-zertifizierter Hersteller von Speedwalls"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=&#8220;Walltopia ist stolz darauf, bekannt geben zu k\u00f6nnen, dass das Unternehmen nun als IFSC-zertifizierter Speedwall-Hersteller zugelassen ist.&#8220; font_container=&#8220;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Bis heute haben wir mehr als 30 Speed Walls hergestellt und installiert, die den Anforderungen der IFSC entsprechen. Dennoch musste die IFSC uns inspizieren und an jedem Ort einzeln zertifizieren. Als das Klettern bei den Olympischen Spielen begann, bemerkten wir eine h\u00f6here Nachfrage nach Speedwalls. Wir erkannten das Bed\u00fcrfnis unserer Kunden nach einer schnelleren und effizienteren M\u00f6glichkeit, eine zertifizierte Wand zu bekommen. Deshalb ist Walltopia seit dem 20. Februar 2021 ein <a href=\"https:\/\/www.ifsc-climbing.org\/index.php\/2-uncategorised\/79-manufacturers\">von der IFSC zertifizierter Hersteller von Speedwalls<\/a>.    <\/p>\n[\/vc_column_text][vc_custom_heading text=&#8220;Was bedeutet das im Einzelnen?&#8220; font_container=&#8220;tag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][vc_row_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia hat weltweit \u00fcber 30 Speedwalls hergestellt. Bis vor kurzem musste jedoch jede dieser Anlagen, um als offizielle IFSC-Wettkampfanlage anerkannt zu werden, von unabh\u00e4ngigen Homologationsinspektoren der IFSC separat inspiziert werden. Sie mussten alle Eigenschaften der Anlage messen und sicherstellen, dass sie den IFSC-Standards f\u00fcr Speed Climbing entspricht. Dies garantiert, dass jede offizielle IFSC-Wettkampfanlage den Athleten die M\u00f6glichkeit bietet, einen neuen Speed-Weltrekord zu versuchen.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Deshalb haben wir bei Walltopia beschlossen, uns die M\u00fche zu machen, die Lizenz zu erhalten. Seit dem 20. Februar hat uns die IFSC den Status IFSC Certified Speed Wall Manufacturer verliehen. Das bedeutet, dass Walltopia nun lizenziert ist, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche verwendet werden k\u00f6nnen. Es ist unsere vertragliche Verpflichtung, eine Wand zu liefern, die vom ersten St\u00fcck Stahlrahmen bis zur letzten T-Mutter dem IFSC-Standard entspricht.   <\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_images_carousel images=&#8220;22460,22466,22472&#8243; img_size=&#8220;full&#8220; speed=&#8220;3500&#8243; autoplay=&#8220;yes&#8220; hide_pagination_control=&#8220;yes&#8220; hide_prev_next_buttons=&#8220;yes&#8220; wrap=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][vc_images_carousel images=&#8220;22478,22484,22490&#8243; img_size=&#8220;full&#8220; speed=&#8220;3500&#8243; autoplay=&#8220;yes&#8220; hide_pagination_control=&#8220;yes&#8220; hide_prev_next_buttons=&#8220;yes&#8220; wrap=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220; css=&#8220;.vc_custom_1624280078181{padding-top: 4% !important;}&#8220;][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220;]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Sportklettern ist <a href=\"https:\/\/www.ifsc-climbing.org\/index.php\/news\/14-paris-2024-news\/160-sport-climbing-provisionally-included-in-a-second-olympic-games\">vorl\u00e4ufig f\u00fcr die Olympischen Spiele 2024 best\u00e4tigt<\/a> worden. Das Speedklettern wird in Paris 2024 wahrscheinlich seine eigene Goldmedaille holen. Walltopia ist bereit, eine Anlage zu bauen, die unsere Kunden dabei unterst\u00fctzt, die Athleten besser zu betreuen und ihnen zu helfen, ihre F\u00e4higkeiten zu entwickeln, um H\u00f6chstleistungen zu erbringen.  <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat. ","protected":false},"author":10,"featured_media":22454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[869,870],"tags":[1962,2812,2813,1960],"class_list":["post-187205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-klettern","category-nachrichten","tag-ifsc","tag-speed-wall","tag-speedwande","tag-sportklettern"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia - IFSC-zertifizierter Hersteller von Speedwalls | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia - IFSC-zertifizierter Hersteller von Speedwalls\" \/>\n<meta property=\"og:description\" content=\"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T12:54:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:35:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia &#8211; IFSC-zertifizierter Hersteller von Speedwalls\",\"datePublished\":\"2021-06-21T12:54:56+00:00\",\"dateModified\":\"2026-01-15T14:35:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/\"},\"wordCount\":459,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085245\\\/certified-speedwall-man.jpg\",\"keywords\":[\"IFSC\",\"Speed Wall\",\"Speedw\u00e4nde\",\"Sportklettern\"],\"articleSection\":[\"Klettern\",\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/\",\"name\":\"Walltopia - IFSC-zertifizierter Hersteller von Speedwalls | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085245\\\/certified-speedwall-man.jpg\",\"datePublished\":\"2021-06-21T12:54:56+00:00\",\"dateModified\":\"2026-01-15T14:35:03+00:00\",\"description\":\"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085245\\\/certified-speedwall-man.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085245\\\/certified-speedwall-man.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia &#8211; IFSC-zertifizierter Hersteller von Speedwalls\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia - IFSC-zertifizierter Hersteller von Speedwalls | Walltopia","description":"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/","og_locale":"de_DE","og_type":"article","og_title":"Walltopia - IFSC-zertifizierter Hersteller von Speedwalls","og_description":"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.","og_url":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-21T12:54:56+00:00","article_modified_time":"2026-01-15T14:35:03+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia &#8211; IFSC-zertifizierter Hersteller von Speedwalls","datePublished":"2021-06-21T12:54:56+00:00","dateModified":"2026-01-15T14:35:03+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/"},"wordCount":459,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg","keywords":["IFSC","Speed Wall","Speedw\u00e4nde","Sportklettern"],"articleSection":["Klettern","Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/","url":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/","name":"Walltopia - IFSC-zertifizierter Hersteller von Speedwalls | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg","datePublished":"2021-06-21T12:54:56+00:00","dateModified":"2026-01-15T14:35:03+00:00","description":"Walltopia ist nun lizenziert, Speed Walls zu produzieren und zu installieren, die f\u00fcr offizielle Weltrekordversuche dienen k\u00f6nnen. Erfahren Sie hier, wie die IFSC uns zertifiziert hat.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085245\/certified-speedwall-man.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/walltopia-ifsc-zertifizierter-hersteller-von-speedwalls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Walltopia &#8211; IFSC-zertifizierter Hersteller von Speedwalls"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/187205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=187205"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/187205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/22454"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=187205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=187205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=187205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}