{"id":190377,"date":"2017-02-10T07:51:22","date_gmt":"2017-02-10T04:51:22","guid":{"rendered":"https:\/\/walltopia.com\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/"},"modified":"2026-01-15T17:42:50","modified_gmt":"2026-01-15T14:42:50","slug":"treffen-sie-uns-in-indien-auf-der-iaapi-2017","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/","title":{"rendered":"Treffen Sie uns in Indien auf der IAAPI 2017"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8220;fadeInUp&#8220;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia Adventure wird erneut offizieller Aussteller auf der <a href=\"https:\/\/www.iaapi.org\/\" target=\"_blank\" rel=\"noopener\">IAAPI Amusement Expo<\/a> sein. Treffen Sie uns dieses Jahr vom <strong> 22. bis 24. Februar <\/strong> am <strong>Stand C6 in Halle 5<\/strong> des Bombay Exhibition Centre in Mumbai. Wir freuen uns darauf, Ihnen unsere neuesten Produkte vorzustellen und Ihnen Videos zu zeigen, die zeigen, was wir im letzten Jahr so alles gemacht haben.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Wir werden Ihnen unsere neueste Marke vorstellen &#8211; <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\" target=\"_blank\" rel=\"noopener\">Ninja Course<\/a>. Wettbewerb, k\u00f6rperliche Herausforderungen und jede Menge Spannung &#8211; Ninja Course bietet all das. Es handelt sich um eine Reihe von Hindernisparcours, die Kraft, Ausdauer, Koordination, Beweglichkeit und Gleichgewicht der Teilnehmer testen, w\u00e4hrend sie in einer sicheren Umgebung trainieren, wetteifern und sich entspannen k\u00f6nnen.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">M\u00f6chten Sie mehr \u00fcber den Rest unserer Produkte erfahren? Besuchen Sie die Seiten <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\" target=\"_blank\" rel=\"noopener\">Rollglider<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\" target=\"_blank\" rel=\"noopener\">Fun Walls<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">Hochseilgarten<\/a> und <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\" target=\"_blank\" rel=\"noopener\">Walltopia H\u00f6hlen<\/a> auf unserer Website. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Kontaktieren Sie uns unter <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com<\/a>, um ein Treffen im Voraus zu vereinbaren. Wir hoffen, Sie bald zu sehen! <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia Adventure wird wieder offizieller Aussteller auf der IAAPI Amusement Expo sein.","protected":false},"author":5,"featured_media":95357,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[867],"tags":[3456,1821],"class_list":["post-190377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktive-unterhaltung","tag-iaapi-2017","tag-iaapi-vergnugungsmesse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Treffen Sie uns in Indien auf der IAAPI 2017 | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Treffen Sie uns in Indien auf der IAAPI 2017\" \/>\n<meta property=\"og:description\" content=\"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T04:51:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Treffen Sie uns in Indien auf der IAAPI 2017\",\"datePublished\":\"2017-02-10T04:51:22+00:00\",\"dateModified\":\"2026-01-15T14:42:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/\"},\"wordCount\":182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145716\\\/Walltopia-IAAPI-2017.jpg\",\"keywords\":[\"IAAPI 2017\",\"IAAPI Vergn\u00fcgungsmesse\"],\"articleSection\":[\"Aktive Unterhaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/\",\"name\":\"Treffen Sie uns in Indien auf der IAAPI 2017 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145716\\\/Walltopia-IAAPI-2017.jpg\",\"datePublished\":\"2017-02-10T04:51:22+00:00\",\"dateModified\":\"2026-01-15T14:42:50+00:00\",\"description\":\"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145716\\\/Walltopia-IAAPI-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145716\\\/Walltopia-IAAPI-2017.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Treffen Sie uns in Indien auf der IAAPI 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Treffen Sie uns in Indien auf der IAAPI 2017 | Walltopia","description":"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Treffen Sie uns in Indien auf der IAAPI 2017","og_description":"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.","og_url":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-02-10T04:51:22+00:00","article_modified_time":"2026-01-15T14:42:50+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Treffen Sie uns in Indien auf der IAAPI 2017","datePublished":"2017-02-10T04:51:22+00:00","dateModified":"2026-01-15T14:42:50+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/"},"wordCount":182,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg","keywords":["IAAPI 2017","IAAPI Vergn\u00fcgungsmesse"],"articleSection":["Aktive Unterhaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/","url":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/","name":"Treffen Sie uns in Indien auf der IAAPI 2017 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg","datePublished":"2017-02-10T04:51:22+00:00","dateModified":"2026-01-15T14:42:50+00:00","description":"Walltopia Adventure wird ein offizieller Aussteller auf der IAAPI Amusement Expo sein. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, was wir vorstellen werden, lesen Sie den Artikel.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145716\/Walltopia-IAAPI-2017.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/treffen-sie-uns-in-indien-auf-der-iaapi-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Treffen Sie uns in Indien auf der IAAPI 2017"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/190377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=190377"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/190377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/95357"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=190377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=190377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=190377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}