{"id":191510,"date":"2016-06-01T05:59:15","date_gmt":"2016-06-01T02:59:15","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/"},"modified":"2026-01-15T17:45:07","modified_gmt":"2026-01-15T14:45:07","slug":"walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/","title":{"rendered":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8220;fadeInUp&#8220;][vc_column_text]\n<p style=\"font-size:18px; line-height: 1.8em;\">Walltopia Adventure ist in diesem Jahr offizieller Aussteller auf der <a href=\"https:\/\/www.iaapa.org\/\">IAAPA Asian Attractions Expo<\/a> in Shanghai. Die Veranstaltung findet vom <strong>14. bis 16. Juni<\/strong> auf dem <strong>Shanghai New International Expo Centre in China statt.<\/strong> <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Treffen Sie uns am <strong>Stand 2618 in Halle N2<\/strong> und erfahren Sie, wie wir mit unserem neuen Produkt &#8211; dem <a href=\"https:\/\/staging-3.walltopia.com\/products\/ninja-course\/\">Ninja Course &#8211;<\/a> Hindernisparcours auf die n\u00e4chste Stufe gehoben haben. Wir werden auch den neuesten Trend in der Adventure-Branche vorstellen &#8211; unsere Seilrutschen-Achterbahn, <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\">den Rollglider<\/a>, sowie alle unsere Adventure-Marken &#8211; <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>, <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\">Ropes Course<\/a> und <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves.<\/a> <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Kontaktieren Sie uns unter <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a>, um im Voraus einen Termin mit unserem Team zu vereinbaren. Kostenlose Besucherausweise sind auf Anfrage erh\u00e4ltlich. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Wir sehen uns dort!<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia Adventure ist ein offizieller Aussteller auf der IAAPA Asian Attractions Expo in Shanghai.","protected":false},"author":5,"featured_media":95234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[867],"tags":[3705,3706],"class_list":["post-191510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktive-unterhaltung","tag-asien-attraktionen-anzeigen","tag-iaapa-ausstellung-fur-asiatische-attraktionen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia Abenteuer auf der IAAPA Asian Attractions Expo | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo\" \/>\n<meta property=\"og:description\" content=\"Walltopia Adventure ist ein offizieller Aussteller auf der IAAPA Asian Attractions Expo in Shanghai.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-01T02:59:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo\",\"datePublished\":\"2016-06-01T02:59:15+00:00\",\"dateModified\":\"2026-01-15T14:45:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/\"},\"wordCount\":142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145950\\\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg\",\"keywords\":[\"Asien Attraktionen anzeigen\",\"IAAPA Ausstellung f\u00fcr asiatische Attraktionen\"],\"articleSection\":[\"Aktive Unterhaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/\",\"name\":\"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145950\\\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg\",\"datePublished\":\"2016-06-01T02:59:15+00:00\",\"dateModified\":\"2026-01-15T14:45:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145950\\\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145950\\\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/","og_locale":"de_DE","og_type":"article","og_title":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo","og_description":"Walltopia Adventure ist ein offizieller Aussteller auf der IAAPA Asian Attractions Expo in Shanghai.","og_url":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2016-06-01T02:59:15+00:00","article_modified_time":"2026-01-15T14:45:07+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo","datePublished":"2016-06-01T02:59:15+00:00","dateModified":"2026-01-15T14:45:07+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/"},"wordCount":142,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg","keywords":["Asien Attraktionen anzeigen","IAAPA Ausstellung f\u00fcr asiatische Attraktionen"],"articleSection":["Aktive Unterhaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/","url":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/","name":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg","datePublished":"2016-06-01T02:59:15+00:00","dateModified":"2026-01-15T14:45:07+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145950\/Walltopia-IAAPA-Asian-Attractions-Expo-2016.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/walltopia-abenteuer-auf-der-iaapa-asian-attractions-expo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Walltopia Abenteuer auf der IAAPA Asian Attractions Expo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/191510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=191510"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/191510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/95234"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=191510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=191510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=191510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}