{"id":192214,"date":"2018-03-21T09:41:18","date_gmt":"2018-03-21T06:41:18","guid":{"rendered":"https:\/\/walltopia.com\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/"},"modified":"2026-01-15T17:46:41","modified_gmt":"2026-01-15T14:46:41","slug":"treffen-sie-walltopia-bei-aaa-in-guangzhou","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/","title":{"rendered":"Treffen Sie Walltopia bei AAA in Guangzhou"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=&#8220;fadeInUp&#8220;][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia wird zum ersten Mal auf der Asia Amusement and Attraction Expo (AAA) in <b>Guangzhou<\/b> ausstellen! Besuchen Sie den <b>Stand J103<\/b> vom <b>3. bis 5. April im Bereich A des China Import &amp; Export Fair Complex<\/b>, um mehr \u00fcber unsere <a href=\"https:\/\/staging-3.walltopia.com\/products\/\" target=\"_blank\" rel=\"noopener\">aktiven Unterhaltungsprodukte<\/a> zu erfahren und unsere lokalen Vertreter zu treffen. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Guagzhou ist die Heimat von <a href=\"https:\/\/staging-3.walltopia.com\/projects\/clifford-wonderland\/\" target=\"_blank\" rel=\"noopener\">Clifford Wonderland<\/a>, wo sich eines unserer neuesten <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider-Projekte<\/a> befindet. Ein Mitglied unseres Teams bringt Sie gerne dorthin, damit Sie das actionreiche Fahrgesch\u00e4ft mit eigenen Augen sehen k\u00f6nnen! <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Haben Sie viel zu tun? <a href=\"https:\/\/staging-3.walltopia.com\/contact-us\/\" target=\"_blank\" rel=\"noopener\">Kontaktieren Sie uns<\/a> im Voraus, um einen Termin zu vereinbaren, der in Ihre Agenda passt.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia wird zum ersten Mal auf der Asia Amusement and Attraction Expo (AAA) in Guangzhou ausstellen!","protected":false},"author":5,"featured_media":95584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[867],"tags":[3829],"class_list":["post-192214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktive-unterhaltung","tag-asia-amusement-and-attraction-expo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Treffen Sie Walltopia bei AAA in Guangzhou | Walltopia<\/title>\n<meta name=\"description\" content=\"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Treffen Sie Walltopia bei AAA in Guangzhou\" \/>\n<meta property=\"og:description\" content=\"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-21T06:41:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Treffen Sie Walltopia bei AAA in Guangzhou\",\"datePublished\":\"2018-03-21T06:41:18+00:00\",\"dateModified\":\"2026-01-15T14:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/\"},\"wordCount\":126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145332\\\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg\",\"keywords\":[\"Asia Amusement and Attraction Expo\"],\"articleSection\":[\"Aktive Unterhaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/\",\"name\":\"Treffen Sie Walltopia bei AAA in Guangzhou | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145332\\\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg\",\"datePublished\":\"2018-03-21T06:41:18+00:00\",\"dateModified\":\"2026-01-15T14:46:41+00:00\",\"description\":\"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145332\\\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145332\\\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/treffen-sie-walltopia-bei-aaa-in-guangzhou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Treffen Sie Walltopia bei AAA in Guangzhou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Treffen Sie Walltopia bei AAA in Guangzhou | Walltopia","description":"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/","og_locale":"de_DE","og_type":"article","og_title":"Treffen Sie Walltopia bei AAA in Guangzhou","og_description":"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.","og_url":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2018-03-21T06:41:18+00:00","article_modified_time":"2026-01-15T14:46:41+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Treffen Sie Walltopia bei AAA in Guangzhou","datePublished":"2018-03-21T06:41:18+00:00","dateModified":"2026-01-15T14:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/"},"wordCount":126,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg","keywords":["Asia Amusement and Attraction Expo"],"articleSection":["Aktive Unterhaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/","url":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/","name":"Treffen Sie Walltopia bei AAA in Guangzhou | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg","datePublished":"2018-03-21T06:41:18+00:00","dateModified":"2026-01-15T14:46:41+00:00","description":"Guagzhou ist die Heimat von Clifford Wonderland, wo sich eines unserer neuesten Rollglider-Projekte befindet. Kontaktieren Sie uns im Voraus, um einen Termin zu vereinbaren.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145332\/Walltopia-Asia-Amusement-and-Attraction-Expo-2018.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/treffen-sie-walltopia-bei-aaa-in-guangzhou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Treffen Sie Walltopia bei AAA in Guangzhou"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/192214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=192214"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/192214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/95584"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=192214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=192214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=192214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}