{"id":197270,"date":"2019-12-09T07:42:13","date_gmt":"2019-12-09T04:42:13","guid":{"rendered":"https:\/\/walltopia.com\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/"},"modified":"2026-01-15T17:59:43","modified_gmt":"2026-01-15T14:59:43","slug":"testen-des-feuerhemmenden-gfk-unserer-hoehlen","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/","title":{"rendered":"Testen des feuerhemmenden GFK unserer H\u00f6hlen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css_animation=&#8220;fadeInUp&#8220;][vc_column][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia entwickelt die <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\" target=\"_blank\" rel=\"noopener noreferrer\">k\u00fcnstlichen H\u00f6hlen<\/a>, die wir anbieten, st\u00e4ndig weiter, damit sie mehr Spa\u00df machen und das Erlebnis f\u00fcr die Endbenutzer verbessern. Wir entwickeln neue Hindernisse (wie die k\u00fcrzlich hinzugef\u00fcgte Br\u00fccke und das Spinnennetz) und wir f\u00fcgen <a href=\"https:\/\/staging-3.walltopia.com\/gamification\/\" target=\"_blank\" rel=\"noopener\">Spielfunktionen<\/a> hinzu &#8211; unsere H\u00f6hlen sind derzeit die einzigen auf dem Markt, die die Option eingebauter Lernspiele bieten. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Aber das Wichtigste, worauf wir uns konzentrieren, ist die Sicherheit. K\u00fcnstliche H\u00f6hlen sind von Haus aus komplexe Strukturen und erfordern viel Liebe zum Detail, um alles richtig zu machen. Deshalb sorgen unsere Teams daf\u00fcr, dass jedes Element einer potenziellen Gefahr von vornherein beseitigt wird.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Die Sicherheit unserer H\u00f6hlen wird unter anderem durch die sorgf\u00e4ltige Auswahl der f\u00fcr die Glasfaserstruktur verwendeten Materialien gew\u00e4hrleistet. <strong>Jede H\u00f6hle, die Walltopia herstellt<\/strong>, besteht aus <strong>feuerhemmendem GFK<\/strong>, <strong>das das Risiko einer Brandausbreitung<\/strong> in den Tunneln und H\u00f6hlen <strong>erheblich reduziert<\/strong>. Aus diesem Grund erf\u00fcllen unsere H\u00f6hlen die europ\u00e4ische Norm EN 13501-1:2018. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">In dem Video unten testen wir dies in der Realit\u00e4t. Sehen Sie sich den Vergleich zwischen einer normalen Platte und unserem feuerhemmenden GFK an, um zu sehen, was passiert, wenn beide Platten mit Feuer behandelt werden. <\/p>\n[\/vc_column_text][vc_video link=&#8220;https:\/\/www.youtube.com\/watch?v=T0XqWygEcP0&#8243;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia entwickelt die k\u00fcnstlichen H\u00f6hlen, die wir anbieten, st\u00e4ndig weiter, um sie noch unterhaltsamer zu machen und das Erlebnis f\u00fcr die Endbenutzer zu verbessern.","protected":false},"author":5,"featured_media":95840,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[867],"tags":[4846,4037,4039,1768],"class_list":["post-197270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktive-unterhaltung","tag-feuerhemmendes-grp","tag-hohlen","tag-kunstliche-hohlen-2","tag-walltopia-hohlen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Testen des feuerhemmenden GFK unserer H\u00f6hlen | Walltopia<\/title>\n<meta name=\"description\" content=\"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testen des feuerhemmenden GFK unserer H\u00f6hlen\" \/>\n<meta property=\"og:description\" content=\"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-09T04:42:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:59:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Testen des feuerhemmenden GFK unserer H\u00f6hlen\",\"datePublished\":\"2019-12-09T04:42:13+00:00\",\"dateModified\":\"2026-01-15T14:59:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144923\\\/fire-retardant-panels.jpg\",\"keywords\":[\"feuerhemmendes GRP\",\"H\u00f6hlen\",\"k\u00fcnstliche H\u00f6hlen\",\"Walltopia-H\u00f6hlen\"],\"articleSection\":[\"Aktive Unterhaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/\",\"name\":\"Testen des feuerhemmenden GFK unserer H\u00f6hlen | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144923\\\/fire-retardant-panels.jpg\",\"datePublished\":\"2019-12-09T04:42:13+00:00\",\"dateModified\":\"2026-01-15T14:59:43+00:00\",\"description\":\"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144923\\\/fire-retardant-panels.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027144923\\\/fire-retardant-panels.jpg\",\"width\":900,\"height\":474},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testen des feuerhemmenden GFK unserer H\u00f6hlen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Testen des feuerhemmenden GFK unserer H\u00f6hlen | Walltopia","description":"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/","og_locale":"de_DE","og_type":"article","og_title":"Testen des feuerhemmenden GFK unserer H\u00f6hlen","og_description":"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.","og_url":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2019-12-09T04:42:13+00:00","article_modified_time":"2026-01-15T14:59:43+00:00","og_image":[{"width":900,"height":474,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Testen des feuerhemmenden GFK unserer H\u00f6hlen","datePublished":"2019-12-09T04:42:13+00:00","dateModified":"2026-01-15T14:59:43+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg","keywords":["feuerhemmendes GRP","H\u00f6hlen","k\u00fcnstliche H\u00f6hlen","Walltopia-H\u00f6hlen"],"articleSection":["Aktive Unterhaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/","url":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/","name":"Testen des feuerhemmenden GFK unserer H\u00f6hlen | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg","datePublished":"2019-12-09T04:42:13+00:00","dateModified":"2026-01-15T14:59:43+00:00","description":"Artikel \u00fcber das feuerbest\u00e4ndige GFK, das beim Bau der Walltopia-H\u00f6hlen verwendet wurde.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027144923\/fire-retardant-panels.jpg","width":900,"height":474},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/testen-des-feuerhemmenden-gfk-unserer-hoehlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Testen des feuerhemmenden GFK unserer H\u00f6hlen"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/197270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=197270"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/197270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/95840"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=197270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=197270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=197270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}