{"id":198493,"date":"2023-10-12T13:48:31","date_gmt":"2023-10-12T10:48:31","guid":{"rendered":"https:\/\/walltopia.com\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/"},"modified":"2026-01-15T18:04:04","modified_gmt":"2026-01-15T15:04:04","slug":"von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/","title":{"rendered":"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen &#8211; Walltopia erweitert sein Active Entertainment Portfolio"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text css=&#8220;&#8220;]Heute treffen wir uns mit <strong>Magdalena Markova<\/strong>, einer der Produktmanagerinnen bei Walltopia. Maggy beaufsichtigt das Produktmanagement von acht der Active Entertainment-Produkte von Walltopia, darunter auch Trampoline. Vor kurzem hat sie die Verantwortung f\u00fcr die neue Produktlinie &#8211; Walltopia Playgrounds &#8211; \u00fcbernommen.  <\/p>\n<p><strong>Was hat Sie dazu bewogen, die Active Entertainment-Linie um Spielpl\u00e4tze zu erweitern?<\/strong><\/p>\n<p>Magdalena: In den letzten Jahren haben sich die Vorlieben von Family Entertainment Centern deutlich in Richtung ungeschirmter Aktivit\u00e4ten verschoben. Der Spielplatzbereich bietet die perfekte M\u00f6glichkeit, Spa\u00df f\u00fcr die Besucher zu schaffen und gleichzeitig die Wartungskosten und die Anzahl der Betreiber zu senken. <\/p>\n<h5>Das Netzlabyrinth<\/h5>\n<p>Im August 2022 haben wir das Netzlabyrinth eingef\u00fchrt, ein innovatives, einfach zu bedienendes Produkt, das sowohl f\u00fcr den Innen- als auch f\u00fcr den Au\u00dfenbereich geeignet ist. Es wurde von unseren Kunden sehr gut aufgenommen. Bislang wurde das Net Maze in verschiedenen Umgebungen installiert, darunter klassische FECs, Schulen, Erlebnisparks, Stadien, \u00f6ffentliche Schwimmb\u00e4der und Parks im Freien. W\u00e4hrend diese Netze an den meisten Orten typischerweise f\u00fcr Sport und Spa\u00df genutzt werden, haben wir auch ein Design entwickelt, das es Erwachsenen erm\u00f6glicht, sich auf dem Netz zu entspannen und zu unterhalten.   <\/p>\n<p><strong>Wie passen die Kunden diese Attraktion in ihren Raum? Richten sie sich nur an j\u00fcngere Kinder? <\/strong><\/p>\n<p>Magdalena: Nicht unbedingt. Die meisten unserer Kunden bevorzugen es, so viele Altersgruppen wie m\u00f6glich anzusprechen. Deshalb f\u00fcgen sie gesch\u00fctzte Attraktionen wie den Hochseilgarten, die Fun Walls und den Rollglider hinzu, mit denen sie sich von den \u00f6rtlichen Vergn\u00fcgungszentren abheben, und f\u00fcllen dann den Rest des Raums mit ungesch\u00fctzten Attraktionen. Walltopia Spielpl\u00e4tze sind der perfekte Weg, um die Kapazit\u00e4t des Veranstaltungsortes zu erh\u00f6hen und gleichzeitig die Raumnutzung zu optimieren.  <\/p>\n<p><strong>Was stellen Sie sich unter der neuen Produktlinie vor?<\/strong><\/p>\n<p>Magdalena: In der Spielplatzbranche gibt es noch viel Raum f\u00fcr Verbesserungen und wir setzen uns daf\u00fcr ein, diesen Wandel voranzutreiben. Wir wollen Mini-Fantasiewelten f\u00fcr Kinder schaffen, in denen sie ihre Fantasie im Freien entfalten und gleichzeitig ihre k\u00f6rperlichen und sozialen F\u00e4higkeiten entwickeln k\u00f6nnen.<br \/>\nWir k\u00f6nnen dies erreichen, indem wir die verschiedenen Produkte, die wir anbieten, wie Cloud Climb, Rutschen, Netzlabyrinthe, Trampoline und Abenteuerpfad-H\u00e4user und -Tunnel, thematisieren und miteinander verbinden. <\/p>\n<h5>Die neuen Modelle<\/h5>\n<p>Das Unternehmen hat bereits einige der Modelle, die wir entwickeln, herausgebracht, darunter Soft Play, Bloc Play, Puff Play und Signature Playgrounds. Wir planen, viele weitere Varianten dieser Modelle f\u00fcr den Innen- und Au\u00dfenbereich zu entwickeln. Das Team arbeitet derzeit an einigen v\u00f6llig neuen Modellen wie gebogenen Netzspielpl\u00e4tzen, Rutschent\u00fcrmen und mobilen, umbaubaren Spielpl\u00e4tzen. Die Gestaltungsm\u00f6glichkeiten sind endlos.   <\/p>\n<p><strong>Was denken Sie, ist der n\u00e4chste Schritt f\u00fcr Walltopia Active Entertainment Produkte?<\/strong><\/p>\n<p>Magdalena: Wir weiten unsere Marktpr\u00e4senz aus und dringen in Bereiche wie Skigebiete, Zoos, Flugh\u00e4fen und \u00f6ffentliche Pl\u00e4tze vor. Au\u00dferdem wollen wir durch die Integration interaktiver Elemente in jede Attraktion das wettbewerbsorientierte Element im Spiel der Kinder f\u00f6rdern. Walltopia entwirft au\u00dferdem jedes Produkt mit dem Schwerpunkt auf Do-It-Yourself-Montage und modularen Komponenten, um sicherzustellen, dass die Kunden ihre Attraktionen in Zukunft problemlos verbessern und erweitern k\u00f6nnen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space][vc_gallery interval=&#8220;3&#8243; images=&#8220;109123,81672,103800&#8243; img_size=&#8220;full&#8220;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text css=&#8220;&#8220;]Heute treffen wir uns mit Magdalena Markova, einer der Produktmanagerinnen bei Walltopia. Maggy beaufsichtigt das Produktmanagement von acht der&#8230;","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[867,870],"tags":[5050,5053,1008,2572,5052,4985,5051,1000],"class_list":["post-198493","post","type-post","status-publish","format-standard","hentry","category-aktive-unterhaltung","category-nachrichten","tag-activeentertainment","tag-erweiterung","tag-familieunterhaltung","tag-innovation","tag-kinderspiel","tag-spielplatze","tag-ungezahmteattraktionen","tag-walltopia-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Neue Produktlinien im Active Entertainment Portfolio von Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen - Walltopia erweitert sein Active Entertainment Portfolio\" \/>\n<meta property=\"og:description\" content=\"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-12T10:48:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T15:04:04+00:00\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen &#8211; Walltopia erweitert sein Active Entertainment Portfolio\",\"datePublished\":\"2023-10-12T10:48:31+00:00\",\"dateModified\":\"2026-01-15T15:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/\"},\"wordCount\":584,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"keywords\":[\"ActiveEntertainment\",\"Erweiterung\",\"FamilieUnterhaltung\",\"Innovation\",\"KinderSpiel\",\"Spielpl\u00e4tze\",\"Ungez\u00e4hmteAttraktionen\",\"walltopia\"],\"articleSection\":[\"Aktive Unterhaltung\",\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/\",\"name\":\"Neue Produktlinien im Active Entertainment Portfolio von Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"datePublished\":\"2023-10-12T10:48:31+00:00\",\"dateModified\":\"2026-01-15T15:04:04+00:00\",\"description\":\"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen &#8211; Walltopia erweitert sein Active Entertainment Portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Neue Produktlinien im Active Entertainment Portfolio von Walltopia","description":"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/","og_locale":"de_DE","og_type":"article","og_title":"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen - Walltopia erweitert sein Active Entertainment Portfolio","og_description":"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.","og_url":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-10-12T10:48:31+00:00","article_modified_time":"2026-01-15T15:04:04+00:00","author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen &#8211; Walltopia erweitert sein Active Entertainment Portfolio","datePublished":"2023-10-12T10:48:31+00:00","dateModified":"2026-01-15T15:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/"},"wordCount":584,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"keywords":["ActiveEntertainment","Erweiterung","FamilieUnterhaltung","Innovation","KinderSpiel","Spielpl\u00e4tze","Ungez\u00e4hmteAttraktionen","walltopia"],"articleSection":["Aktive Unterhaltung","Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/","url":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/","name":"Neue Produktlinien im Active Entertainment Portfolio von Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"datePublished":"2023-10-12T10:48:31+00:00","dateModified":"2026-01-15T15:04:04+00:00","description":"Walltopia erweitert sein Active Entertainment-Portfolio um Spielpl\u00e4tze. Magdalena Markova, Produktmanagerin bei Walltopia, berichtet \u00fcber die spannenden Entwicklungen.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/von-fun-walls-und-rollgleitern-bis-hin-zu-spielplaetzen-und-trampolinen-walltopia-erweitert-sein-active-entertainment-portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Von Fun Walls und Rollgleitern bis hin zu Spielpl\u00e4tzen und Trampolinen &#8211; Walltopia erweitert sein Active Entertainment Portfolio"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/198493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=198493"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/198493\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=198493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=198493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=198493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}