{"id":198782,"date":"2023-07-26T17:56:13","date_gmt":"2023-07-26T14:56:13","guid":{"rendered":"https:\/\/walltopia.com\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/"},"modified":"2026-01-15T18:05:06","modified_gmt":"2026-01-15T15:05:06","slug":"veranstaltungen-der-abteilung-klettern-im-herbst-2023","status":"publish","type":"post","link":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/","title":{"rendered":"Veranstaltungen der Abteilung Klettern im Herbst 2023"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]<strong>Der Herbst 2023 wird f\u00fcr die Kletterabteilung von Walltopia sehr arbeitsreich werden, da sie an Veranstaltungen in ganz Europa teilnehmen wird!<\/strong>  Wir beginnen Mitte September in Sheffield, Gro\u00dfbritannien, mit der Jahreskonferenz von ABC Walls, gefolgt vom Salon de l&#8217;Escalade in Grenoble, Frankreich, und, last but not least, der Vertical Pro ganz am Ende des Novembers, kurz bevor wir uns auf die Weihnachtsfeiertage vorbereiten.[\/vc_column_text][vc_separator css=&#8220;.vc_custom_1690383205560{margin-top: 30px !important;}&#8220;][vc_row_inner css=&#8220;.vc_custom_1690382728011{margin-top: 50px !important;}&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;101161&#8243; img_size=&#8220;full&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_custom_heading text=&#8220;ABC-Konferenz&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_custom_heading text=&#8220;14-15, September 2023<br \/>\nSheffield, UK&#8220; font_container=&#8220;tag:h5|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1690381712057{border-bottom-width: 50px !important;}&#8220;][vc_column][vc_column_text]\n<p>Im September, noch bevor unsere Sonnenbr\u00e4une aus dem Sommerurlaub verschwunden ist, werden wir uns in Sheffield, Gro\u00dfbritannien, bei der j\u00e4hrlichen <a href=\"https:\/\/www.abcwalls.co.uk\/about\/conference-2023\/\">Konferenz der Association of British Climbing Walls<\/a> abk\u00fchlen. Wir freuen uns, dass wir dieses Jahr Titelsponsor sind! Wir nehmen an der Veranstaltung teil, seit sie noch eine kleine Halle mit einem Tisch und einem Stuhl f\u00fcr jeden Anbieter war, und wir haben miterlebt, wie sie sich zusammen mit der Kletterindustrie zu einer etablierten Gesch\u00e4ftskonferenz entwickelt und professionalisiert hat. Als f\u00fchrender Hersteller f\u00fchlen wir uns verantwortlich und geehrt, das Wachstum der Branche durch solche Veranstaltungen unterst\u00fctzen zu k\u00f6nnen.<\/p>\n[\/vc_column_text][vc_separator css=&#8220;.vc_custom_1690383212544{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1690382975046{margin-top: 50px !important;}&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;101168&#8243; img_size=&#8220;full&#8220;][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_custom_heading text=&#8220;Salon de l&apos;Escalade&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_custom_heading text=&#8220;29-30, September 2023<br \/>\nGrenoble, Frankreich&#8220; font_container=&#8220;tag:h5|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1690381731689{border-bottom-width: 50px !important;}&#8220;][vc_column][vc_column_text]\n<p>Gleich nach der ABC-Konferenz in Gro\u00dfbritannien geht es in das Herz der franz\u00f6sischen Alpen: Grenoble &#8211; zum Klettern und f\u00fcr guten Wein. Das war nur ein Scherz, wir fahren dorthin f\u00fcr die 4. Ausgabe des <a href=\"https:\/\/www.salon-escalade.com\/\">Salon de l&#8217;Escalade<\/a>. Wir freuen uns darauf, all unsere Freunde, Kunden und Partner aus Frankreich und den umliegenden L\u00e4ndern zu treffen und w\u00fcrden uns freuen, neue Leute aus der professionellen Kletterbranche kennenzulernen, mit denen wir zusammenarbeiten k\u00f6nnen.<\/p>\n[\/vc_column_text][vc_separator css=&#8220;.vc_custom_1690383219723{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1690382922003{margin-top: 50px !important;}&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;101175&#8243; img_size=&#8220;full&#8220;][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_custom_heading text=&#8220;Vertikal Pro&#8220; font_container=&#8220;tag:h3|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_custom_heading text=&#8220;24-25, November 2023<br \/>\nFriedrichshafen, Deutschland&#8220; font_container=&#8220;tag:h5|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1690382646255{border-bottom-width: 50px !important;}&#8220;]\n<p>In der dunklen und grauen Zeit des Jahres Ende November gibt es eine Veranstaltung, die die Stimmung aufhellt und die Kletterprofis motiviert &#8211; <a href=\"https:\/\/www.vertical-pro.com\/\">Vertical Pro<\/a>. Genau wie bei den beiden vorangegangenen Veranstaltungen sind wir seit den Anf\u00e4ngen von Halls&#8217;n&#8217;Walls als kleines Treffen f\u00fcr Indoor-Kletterprofis dabei und haben miterlebt, wie sich die Veranstaltung zu dem gro\u00dfen professionellen Treffpunkt f\u00fcr alle Vertical Pro&#8217;s entwickelt hat, der sie heute ist.<\/p>\n[\/vc_column_text][vc_separator css=&#8220;.vc_custom_1690383225629{margin-top: 30px !important;}&#8220;][vc_custom_heading text=&#8220;Treffen Sie uns dort&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1690382875580{margin-top: 50px !important;}&#8220;][vc_column_text css=&#8220;.vc_custom_1691079110851{border-bottom-width: 50px !important;}&#8220;]\n<p>Besuchen Sie uns an unseren St\u00e4nden w\u00e4hrend dieser Veranstaltungen, erkunden Sie unser Angebot an Kletterwandprodukten und besprechen Sie m\u00f6gliche Projekte und Partnerschaften. An unserem Stand stellen wir aus:<\/p>\n<ul>\n<li><strong>Steigbare Kletterwandpaneele und Dual-Textur-Paneele:<\/strong> Testen Sie das Aussehen und die Reibung der verschiedenen Optionen f\u00fcr die Kletterwandoberfl\u00e4che<\/li>\n<li><strong>Naturholz, Bambuspaneele und Furniere:<\/strong> Entdecken Sie die Vielfalt der von der Natur inspirierten Designs der Walltopia Kletterwand-Paneele und sehen Sie sich verschiedene Kombinationen mit Unifarben an<\/li>\n<li><strong>Zweifach strukturierte Holzvolumina:<\/strong> Entdecken Sie, wie unsere neuesten Volumendesigns das Klettererlebnis verbessern k\u00f6nnen.<\/li>\n<li><strong>Climbmat Bodenbelag-Muster:<\/strong> Testen Sie die Sicherheit und Leistungsf\u00e4higkeit der Climbmat-Bodenbel\u00e4ge, die perfekt f\u00fcr Kletterhallen und Abenteuerzentren geeignet sind.<\/li>\n<\/ul>\n[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1690382913921{margin-top: 30px !important;border-bottom-width: 50px !important;}&#8220;]\n<p>Unser Team aus Kletterenthusiasten und Branchenexperten wird vor Ort sein, um mit Ihnen ins Gespr\u00e4ch zu kommen, Ihre Fragen zu beantworten und m\u00f6gliche Projekte oder Partnerschaften zu erkunden. Ganz gleich, ob Sie eine Kletterhalle, ein Outdoor-Abenteuerzentrum oder ein anderes Unternehmen im Bereich Klettern vertreten, wir freuen uns darauf, mit Ihnen dar\u00fcber zu sprechen, wie unsere Produkte Ihr Angebot erweitern und Ihren Kunden unvergessliche Klettererlebnisse bieten k\u00f6nnen.<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1690383134324{margin-top: 30px !important;border-bottom-width: 50px !important;}&#8220;]\n<p>Wenn Sie ein Treffen buchen m\u00f6chten, f\u00fcllen Sie bitte das Formular rechts aus, folgen Sie dem unten stehenden Link oder senden Sie einfach eine E-Mail an <strong>sales [at] walltopia.com<\/strong><\/p>\n[\/vc_column_text][vc_btn title=&#8220;Buchen Sie ein Treffen&#8220; style=&#8220;classic&#8220; color=&#8220;danger&#8220; link=&#8220;url:https%3A%2F%2Fwalltopia.com%2Fde%2Fkontakt%2F|title:Contact%20Us|&#8220; css=&#8220;.vc_custom_1690383119358{margin-top: 30px !important;}&#8220;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[869,870],"tags":[],"class_list":["post-198782","post","type-post","status-publish","format-standard","hentry","category-klettern","category-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Veranstaltungen der Abteilung Klettern im Herbst 2023 | Walltopia<\/title>\n<meta name=\"description\" content=\"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen der Abteilung Klettern im Herbst 2023\" \/>\n<meta property=\"og:description\" content=\"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-26T14:56:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T15:05:06+00:00\" \/>\n<meta name=\"author\" content=\"Ani Manova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/\"},\"author\":{\"name\":\"Ani Manova\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\"},\"headline\":\"Veranstaltungen der Abteilung Klettern im Herbst 2023\",\"datePublished\":\"2023-07-26T14:56:13+00:00\",\"dateModified\":\"2026-01-15T15:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/\"},\"wordCount\":937,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"articleSection\":[\"Klettern\",\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/\",\"name\":\"Veranstaltungen der Abteilung Klettern im Herbst 2023 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"datePublished\":\"2023-07-26T14:56:13+00:00\",\"dateModified\":\"2026-01-15T15:05:06+00:00\",\"description\":\"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen der Abteilung Klettern im Herbst 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\",\"name\":\"Ani Manova\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Veranstaltungen der Abteilung Klettern im Herbst 2023 | Walltopia","description":"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen der Abteilung Klettern im Herbst 2023","og_description":"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.","og_url":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-07-26T14:56:13+00:00","article_modified_time":"2026-01-15T15:05:06+00:00","author":"Ani Manova","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/"},"author":{"name":"Ani Manova","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1"},"headline":"Veranstaltungen der Abteilung Klettern im Herbst 2023","datePublished":"2023-07-26T14:56:13+00:00","dateModified":"2026-01-15T15:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/"},"wordCount":937,"publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"articleSection":["Klettern","Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/","url":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/","name":"Veranstaltungen der Abteilung Klettern im Herbst 2023 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"datePublished":"2023-07-26T14:56:13+00:00","dateModified":"2026-01-15T15:05:06+00:00","description":"Treffen Sie uns auf diesen internationalen Veranstaltungen der Indoor-Kletterbranche.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/veranstaltungen-der-abteilung-klettern-im-herbst-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen der Abteilung Klettern im Herbst 2023"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/de\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1","name":"Ani Manova"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/198782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/comments?post=198782"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/posts\/198782\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=198782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/categories?post=198782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/tags?post=198782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}