{"id":205361,"date":"2025-02-13T18:08:44","date_gmt":"2025-02-13T15:08:44","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/hex-ropes-course\/"},"modified":"2026-02-17T16:06:11","modified_gmt":"2026-02-17T13:06:11","slug":"hex-ropes-course","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/","title":{"rendered":"Hex Ropes Course"},"content":{"rendered":"<p>Merkmale:<\/p>\n<ul>\n<li>Modularer Aufbau &#8211; einfache vertikale und horizontale Erweiterung<\/li>\n<li>Einzelner oder mehrstufiger Kurs<\/li>\n<li>Bestes multidirektionales Layout<\/li>\n<li>Gro\u00dfartige, eigenst\u00e4ndige Attraktion<\/li>\n<li>H\u00f6chstes Verh\u00e4ltnis von G\u00e4sten zu Fu\u00dfabdruck<\/li>\n<li>Verschiedene Standard-Farbkombinationen<\/li>\n<li>Individuelle Thematisierungsm\u00f6glichkeiten<\/li>\n<\/ul>\n<p>Dieses Produkt ist in den folgenden RAL-Farbkombinationen erh\u00e4ltlich:<\/p>\n<div class=\"info-block-container\">\n<div class=\"content width-50\">\n<h4>Wald<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1020\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1020<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-8003\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">8003<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-6018\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">6018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-8003\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">8003<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-6029\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">6029<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>Fr\u00fchling<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-5012\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">5012<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-6018\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">6018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1023\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1023<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>Industriell<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-7035\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">7035<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-7009\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">7009<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>S\u00fc\u00dfigkeiten<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-4010\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">4010<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-5018\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">5018<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>Sommer<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-5018\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">5018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1023\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1023<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-3018\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">3018<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>Marine<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-6027\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">6027<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-5015\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">5015<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1033\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1033<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content width-50\">\n<h4>Sonnenuntergang<\/h4>\n<div class=\"ral-grid\">\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Seile<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1018\">\n<div class=\"element-label\">Hindernisse<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1018<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-1037\">\n<div class=\"element-label\">Balken<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">1037<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-29050-40\">\n<div class=\"element-label\">S\u00e4ulen &amp; Splitter<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">29050-40<\/div>\n<\/div>\n<\/div>\n<div class=\"ral-card r-3020\">\n<div class=\"element-label\">Plattformen &amp; Treppen<\/div>\n<div class=\"ral-swatch\"><\/div>\n<div class=\"ral-text\">\n<div class=\"ral-brand\"><\/div>\n<div class=\"ral-number\">3020<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Merkmale: Modularer Aufbau &#8211; einfache vertikale und horizontale Erweiterung Einzelner oder mehrstufiger Kurs Bestes multidirektionales Layout Gro\u00dfartige, eigenst\u00e4ndige Attraktion H\u00f6chstes&#8230;","protected":false},"featured_media":156388,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[5725],"product_tag":[],"class_list":["post-205361","product","type-product","status-publish","has-post-thumbnail","product_cat-hochseilgarten-standardmodelle","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hex Ropes Course | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hex Ropes Course\" \/>\n<meta property=\"og:description\" content=\"Merkmale: Modularer Aufbau &#8211; einfache vertikale und horizontale Erweiterung Einzelner oder mehrstufiger Kurs Bestes multidirektionales Layout Gro\u00dfartige, eigenst\u00e4ndige Attraktion H\u00f6chstes...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T13:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213180902\/hex-2lvl-forest-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/\",\"name\":\"Hex Ropes Course | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250213180902\\\/hex-2lvl-forest-1-scaled.webp\",\"datePublished\":\"2025-02-13T15:08:44+00:00\",\"dateModified\":\"2026-02-17T13:06:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250213180902\\\/hex-2lvl-forest-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250213180902\\\/hex-2lvl-forest-1-scaled.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/hochseilgarten\\\/hochseilgarten-standardmodelle\\\/hex-ropes-course\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hex Ropes Course\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hex Ropes Course | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/","og_locale":"de_DE","og_type":"article","og_title":"Hex Ropes Course","og_description":"Merkmale: Modularer Aufbau &#8211; einfache vertikale und horizontale Erweiterung Einzelner oder mehrstufiger Kurs Bestes multidirektionales Layout Gro\u00dfartige, eigenst\u00e4ndige Attraktion H\u00f6chstes...","og_url":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-02-17T13:06:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213180902\/hex-2lvl-forest-1-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/","url":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/","name":"Hex Ropes Course | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213180902\/hex-2lvl-forest-1-scaled.webp","datePublished":"2025-02-13T15:08:44+00:00","dateModified":"2026-02-17T13:06:11+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213180902\/hex-2lvl-forest-1-scaled.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213180902\/hex-2lvl-forest-1-scaled.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/hochseilgarten\/hochseilgarten-standardmodelle\/hex-ropes-course\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Hex Ropes Course"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/205361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/205361\/revisions"}],"predecessor-version":[{"id":388898,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/205361\/revisions\/388898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/156388"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=205361"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=205361"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=205361"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=205361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}