{"id":205600,"date":"2025-02-17T15:15:37","date_gmt":"2025-02-17T12:15:37","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/smiley-faces\/"},"modified":"2025-02-17T15:15:37","modified_gmt":"2025-02-17T12:15:37","slug":"smiley-faces","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/","title":{"rendered":"Smiley Faces"},"content":{"rendered":"<p>*Die Smiley Faces Fun Wall bietet drei verschiedene Routen, wobei der Schwierigkeitsgrad durch die geometrische Form der Griffe bestimmt wird, die das Kind zum Klettern w\u00e4hlt.<\/p>\n<p><strong>Technische Spezifikation:<\/strong><\/p>\n<h4>Art der Struktur<\/h4>\n<p>Die Smiley Faces Fun Wall wird mit unserer Standard-Stahlkonstruktion geliefert, die im Boden und an der Oberseite des Rahmens verankert werden muss. Die Struktur f\u00fcr den Au\u00dfenbereich ist feuerverzinkt, was ihre Haltbarkeit und Widerstandsf\u00e4higkeit gegen Witterungseinfl\u00fcsse auf der ganzen Welt gew\u00e4hrleistet. <\/p>\n<h4>Verankerung<\/h4>\n<p>Sie m\u00fcssen zwei Basis-Stahlplatten mit jeweils vier Ankern an der Unterseite verankern und au\u00dferdem zwei Befestigungspunkte an der Oberseite sichern. Die oberen Befestigungspunkte k\u00f6nnen je nach Installationsraum variieren, um Ihre Smiley Faces richtig zu st\u00fctzen. Die Struktur sollte in einer soliden Betonplatte mit einer Mindestdicke von 15 cm verankert werden. Um sicherzugehen, dass Ihr Boden die Smiley Faces Funwall tragen kann <strong>, finden Sie im Anhang die statischen Berechnungen der Lasten<\/strong> <em>Walltopia Standard Loads File<\/em> <strong>im Download-Bereich und konsultieren Sie immer Ihren Ingenieur oder einen qualifizierten Fachmann.<\/strong>   <\/p>\n<h4>Platzierung<\/h4>\n<p>Smiley Faces sollten nicht in der N\u00e4he von harten Gegenst\u00e4nden wie Geb\u00e4udes\u00e4ulen, Gel\u00e4ndern, M\u00f6beln oder anderen platziert werden. Die Abmessungen der Sicherheitszone sind auf den Produktbildern angegeben. Dies ist die Zone, die Sie unbedingt von allen Hindernissen fernhalten m\u00fcssen.  <\/p>\n<h4>Seitenverkleidungen<\/h4>\n<p>Bitte beachten Sie, dass die Seitenw\u00e4nde <strong>NICHT<\/strong> im Produktpreis <strong>enthalten<\/strong> sind. Wenn Sie Seitenw\u00e4nde f\u00fcr Ihre Fun Walls kaufen m\u00f6chten, besuchen Sie bitte unsere <em><span style=\"text-decoration: underline;\">Produktseite Seitenteile<\/span><\/em> und sprechen Sie mit einem unserer Ingenieure. <\/p>\n<h4>Fallschutzmatte<\/h4>\n<p>Wir empfehlen dringend, in der Sicherheitszone um jede Kletterwand herum einen Sicherheitsboden zu verlegen. Sie k\u00f6nnen 15 cm dicke Rope Wall Mat mit grauer Teppichoberfl\u00e4che oder One More Life Safety Flooring von Walltopia kaufen oder einen anderen sto\u00dfd\u00e4mpfenden Bodenbelag installieren. <\/p>\n<h4>Zus\u00e4tzliche Produkte<\/h4>\n<p>Dieses Produkt kann nicht ohne ein automatisches R\u00fcckholsystem verwendet werden!<\/p>\n<p>Unsere Fun Walls Structure sind kompatibel mit dem Tru Blue Auto Belay von Headrush und dem Perfect Descend Auto Belay Device<\/p>\n<p>Vergessen Sie nicht, sich hier unser Sicherheitszubeh\u00f6r anzusehen. Safety Gates erleichtern die Bedienung und vermindern das Risiko des ungesicherten Kletterns. Wenn niemand klettert, wird ein Selbstsicherungsgurt daran befestigt. Das Gurtband f\u00fcr die automatische Sicherung ist daran befestigt, wenn niemand klettert.   <\/p>\n<p>Entscheiden Sie sich f\u00fcr die Installation unseres Smart Gate und reduzieren Sie das Risiko von Zwischenf\u00e4llen auf ein Minimum. Wir empfehlen auch unser Selbstsicherungssystem, das nicht nur zur Sicherheit beim Klettern beitr\u00e4gt, sondern auch den Betrieb unterst\u00fctzt, indem es die Anzahl der ben\u00f6tigten Mitarbeiter reduziert &#8211; Teilnehmer ab 5 Jahren k\u00f6nnen das Ger\u00e4t selbst\u00e4ndig und ohne Aufsicht verwenden! <\/p>\n<h4>Elektronische Komponenten<\/h4>\n<p>Bitte beachten Sie, dass die Spielfunktionalit\u00e4t und die elektronischen Komponenten von Smiley Faces <strong>ausschlie\u00dflich f\u00fcr die Verwendung in Innenr\u00e4umen<\/strong> konzipiert sind. Wenn Sie sich daf\u00fcr entscheiden, die Kletterwand im Freien zu installieren, beh\u00e4lt sie ihr Aussehen, aber die Spielfunktionen <strong>sind nicht enthalten<\/strong>. <\/p>\n<h4>Versandoptionen<\/h4>\n<p>Dieses Produkt wird in Teilen geliefert und muss bei Lieferung zusammengebaut werden. Alle Komponenten, einschlie\u00dflich der Stahlkonstruktion, sind f\u00fcr eine einfache Montage ausgelegt. Detaillierte Anleitungen werden mitgeliefert, um sicherzustellen, dass das Endprodukt sicher zu bedienen ist und ein ausgezeichnetes Aussehen und Finish aufweist.  <\/p>\n<h4>F\u00fcr die Montage ben\u00f6tigte Maschinen<\/h4>\n<p>Liste der Werkzeuge: Schlagschrauber, Bohrmaschine, Winkelschleifer, Schlagschrauber &#8211; Steckschl\u00fcsseleins\u00e4tze 17\/ 19, Stichs\u00e4ge, Handschl\u00fcssel &#8211; 13 \/ 17 \/ 19 \/ 24, Pfeiler, Ma\u00dfb\u00e4nder<\/p>\n<p>Maschinenpark: Scherenhebeb\u00fchne, die 260 kg bis zu 8 Meter hoch heben kann, Gabelstapler 2T &#8211; f\u00fcr die Entladung, Palettenheber<\/p>\n","protected":false},"excerpt":{"rendered":"*Die Smiley Faces Fun Wall bietet drei verschiedene Routen, wobei der Schwierigkeitsgrad durch die geometrische Form der Griffe bestimmt wird,&#8230;","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6707],"product_tag":[],"class_list":["post-205600","product","type-product","status-publish","product_cat-interaktive-fun-walls","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Smiley Faces | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smiley Faces\" \/>\n<meta property=\"og:description\" content=\"*Die Smiley Faces Fun Wall bietet drei verschiedene Routen, wobei der Schwierigkeitsgrad durch die geometrische Form der Griffe bestimmt wird,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250220105251\/FW_smiley_faces_1.5x8m_cam2_for_woocommerce_catalog-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/interaktive-fun-walls\\\/smiley-faces\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/interaktive-fun-walls\\\/smiley-faces\\\/\",\"name\":\"Smiley Faces | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"datePublished\":\"2025-02-17T12:15:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/interaktive-fun-walls\\\/smiley-faces\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/interaktive-fun-walls\\\/smiley-faces\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/interaktive-fun-walls\\\/smiley-faces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Smiley Faces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Smiley Faces | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/","og_locale":"de_DE","og_type":"article","og_title":"Smiley Faces","og_description":"*Die Smiley Faces Fun Wall bietet drei verschiedene Routen, wobei der Schwierigkeitsgrad durch die geometrische Form der Griffe bestimmt wird,...","og_url":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":526,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250220105251\/FW_smiley_faces_1.5x8m_cam2_for_woocommerce_catalog-1-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/","url":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/","name":"Smiley Faces | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"datePublished":"2025-02-17T12:15:37+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/interaktive-fun-walls\/smiley-faces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Smiley Faces"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/205600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/205600\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=205600"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=205600"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=205600"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=205600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}