{"id":206294,"date":"2025-02-17T12:13:56","date_gmt":"2025-02-17T09:13:56","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/wood-stack-farben\/"},"modified":"2026-02-17T19:13:32","modified_gmt":"2026-02-17T16:13:32","slug":"wood-stack-farben","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/","title":{"rendered":"Wood Stack Farben"},"content":{"rendered":"<p>*Die Routen sind vorgegeben und haben einen dritten Schwierigkeitsgrad<\/p>\n<p><strong>Technische Spezifikation:<\/strong><\/p>\n<h4>Art der Struktur<\/h4>\n<p>Wood Stack Colors wird mit unserer standardm\u00e4\u00dfigen selbststehenden Stahlkonstruktion geliefert, die im Boden verankert werden muss. Die Struktur f\u00fcr den Au\u00dfenbereich ist feuerverzinkt, was ihre Haltbarkeit und Widerstandsf\u00e4higkeit gegen\u00fcber Witterungseinfl\u00fcssen auf der ganzen Welt gew\u00e4hrleistet.<\/p>\n<h4>Verankerung<\/h4>\n<p>Sie m\u00fcssen eine Basisstahlplatte mit zw\u00f6lf Ankern am Boden verankern. Die Struktur sollte in einer soliden Betonplatte mit einer Mindestst\u00e4rke von 15 cm verankert werden. Um sicherzustellen, dass Ihr Fu\u00dfboden die Wood Stack Colors tragen kann <strong>, finden Sie die statischen Berechnungen der Lasten<\/strong> <em>Walltopia Standard Loads File<\/em> <strong>im Download-Bereich und konsultieren Sie immer Ihren Ingenieur oder einen qualifizierten Fachmann.<\/strong><\/p>\n<h4>Platzierung<\/h4>\n<p>Wood Stack Colors sollte nicht in der N\u00e4he von harten Gegenst\u00e4nden wie Geb\u00e4udes\u00e4ulen, Gel\u00e4ndern, M\u00f6beln oder anderen platziert werden. Die Abmessungen der Sicherheitszone sind in den Produktbildern definiert. Dies ist die Zone, die Sie unbedingt von allen Hindernissen freihalten m\u00fcssen.<\/p>\n<h4>Fallschutzmatte<\/h4>\n<p>Wir empfehlen dringend, in der Sicherheitszone um jede Kletterwand herum einen Sicherheitsboden zu verlegen. Sie k\u00f6nnen 15 cm dicke Rope Wall Mat mit grauer Teppichoberfl\u00e4che oder One More Life Safety Flooring von Walltopia kaufen oder einen anderen sto\u00dfd\u00e4mpfenden Bodenbelag installieren. <\/p>\n<h4>Zus\u00e4tzliche Produkte<\/h4>\n<p>Dieses Produkt kann nicht ohne ein automatisches R\u00fcckholsystem verwendet werden!<\/p>\n<p>Unsere Fun Walls Structure sind kompatibel mit dem Tru Blue Auto Belay von Headrush und dem Perfect Descend Auto Belay Device<\/p>\n<p>Vergessen Sie nicht, hier unser Sicherheitszubeh\u00f6r zu pr\u00fcfen. Sicherheitsgitter erleichtern die Bedienung und vermindern das Risiko eines ungesicherten Aufstiegs. Das Gurtband f\u00fcr die automatische Sicherung ist daran befestigt, wenn niemand klettert. Das Gurtband f\u00fcr die automatische Sicherung ist daran befestigt, wenn niemand klettert.<\/p>\n<p>Entscheiden Sie sich f\u00fcr die Installation unseres Smart Gate und reduzieren Sie das Risiko von Zwischenf\u00e4llen auf ein Minimum. Wir empfehlen auch unser Selbstsicherungssystem, das nicht nur zur Sicherheit beim Klettern beitr\u00e4gt, sondern auch den Betrieb unterst\u00fctzt, indem es die Anzahl der ben\u00f6tigten Mitarbeiter reduziert &#8211; Teilnehmer ab 5 Jahren k\u00f6nnen das Ger\u00e4t selbst\u00e4ndig und ohne Aufsicht verwenden! <\/p>\n<h4>Versandoptionen<\/h4>\n<p>Dieses Produkt wird in gr\u00f6\u00dferen vormontierten Teilen geliefert, die bei Lieferung zusammengebaut werden m\u00fcssen. Alle Komponenten sind f\u00fcr eine einfache Montage ausgelegt. Detaillierte Anleitungen stellen sicher, dass das Endprodukt sicher zu bedienen ist und ein hervorragendes Aussehen und Finish hat.<\/p>\n<h4>F\u00fcr die Montage ben\u00f6tigte Maschinen<\/h4>\n<p>Liste der Werkzeuge: Schlagschrauber, Bohrmaschine, Winkelschleifer, Schlagschrauber &#8211; Steckschl\u00fcsseleins\u00e4tze 17\/ 19, Stichs\u00e4ge, Handschl\u00fcssel &#8211; 13 \/ 17 \/ 19 \/ 24, Pfeiler, Ma\u00dfb\u00e4nder<\/p>\n<p>Maschinenpark: Scherenhebeb\u00fchne, die 260 kg bis zu 8 Meter hoch heben kann, Gabelstapler 2T &#8211; f\u00fcr die Entladung, Palettenheber<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"flex flex-col items-start\">\n<div class=\"flex items-center text-xs rounded p-3 text-gray-900 bg-gray-100\">\n<div>\n<div class=\"flex items-center gap-3\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"657a2499-85b3-44fc-80ac-df77e319da55\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n\n \n\n<\/div>\n<\/div>","protected":false},"featured_media":393791,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6862],"product_tag":[],"class_list":["post-206294","product","type-product","status-publish","has-post-thumbnail","product_cat-3d-fun-walls","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wood Stack Farben | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wood Stack Farben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T16:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217121559\/Walltopia-Fun-Walls-Stack-Up-Colorful-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/\",\"name\":\"Wood Stack Farben | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260806151316\\\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp\",\"datePublished\":\"2025-02-17T09:13:56+00:00\",\"dateModified\":\"2026-02-17T16:13:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260806151316\\\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20260806151316\\\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp\",\"width\":600,\"height\":1200,\"caption\":\"Fun Walls by Walltopia - Stack Up Colour 8m\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/3d-fun-walls\\\/wood-stack-farben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wood Stack Farben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wood Stack Farben | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/","og_locale":"de_DE","og_type":"article","og_title":"Wood Stack Farben","og_url":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-02-17T16:13:32+00:00","og_image":[{"width":600,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217121559\/Walltopia-Fun-Walls-Stack-Up-Colorful-1-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/","url":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/","name":"Wood Stack Farben | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260806151316\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp","datePublished":"2025-02-17T09:13:56+00:00","dateModified":"2026-02-17T16:13:32+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260806151316\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20260806151316\/Fun-Walls-by-Walltopia-Jenga-8m-Color-1.webp","width":600,"height":1200,"caption":"Fun Walls by Walltopia - Stack Up Colour 8m"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/3d-fun-walls\/wood-stack-farben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Wood Stack Farben"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/206294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/206294\/revisions"}],"predecessor-version":[{"id":389330,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/206294\/revisions\/389330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/393791"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=206294"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=206294"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=206294"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=206294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}