{"id":207208,"date":"2025-02-18T11:22:10","date_gmt":"2025-02-18T08:22:10","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/getriebe-traverse\/"},"modified":"2025-02-18T11:22:10","modified_gmt":"2025-02-18T08:22:10","slug":"getriebe-traverse","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/","title":{"rendered":"Getriebe Traverse"},"content":{"rendered":"<p>Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt. Die einzigartigen, bauchigen Formen bieten vielf\u00e4ltige Griffm\u00f6glichkeiten, w\u00e4hrend die unterschiedlichen Gr\u00f6\u00dfen und Strukturen die Kletterer dazu anregen, verschiedene Klettertechniken und Probleml\u00f6sungsans\u00e4tze zu erkunden. <\/p>\n","protected":false},"excerpt":{"rendered":"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert&#8230;","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6981],"product_tag":[],"class_list":["post-207208","product","type-product","status-publish","product_cat-traverse-fun-walls","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Getriebe Traverse | Walltopia<\/title>\n<meta name=\"description\" content=\"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Getriebe Traverse\" \/>\n<meta property=\"og:description\" content=\"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250218112315\/FW_traverse_gearhead_for_woocommerce_catalog-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/traverse-fun-walls\\\/getriebe-traverse\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/traverse-fun-walls\\\/getriebe-traverse\\\/\",\"name\":\"Getriebe Traverse | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"datePublished\":\"2025-02-18T08:22:10+00:00\",\"description\":\"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/traverse-fun-walls\\\/getriebe-traverse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/traverse-fun-walls\\\/getriebe-traverse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/traverse-fun-walls\\\/getriebe-traverse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Getriebe Traverse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Getriebe Traverse | Walltopia","description":"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/","og_locale":"de_DE","og_type":"article","og_title":"Getriebe Traverse","og_description":"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.","og_url":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1200,"height":546,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250218112315\/FW_traverse_gearhead_for_woocommerce_catalog-1-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/","url":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/","name":"Getriebe Traverse | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"datePublished":"2025-02-18T08:22:10+00:00","description":"Inspiriert von den Formen von Zahnr\u00e4dern und R\u00e4dchen, ist die Gearhead Traverse eine visuell beeindruckende Kletterwand, die junge Kletterer herausfordert und fesselt.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/traverse-fun-walls\/getriebe-traverse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Getriebe Traverse"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/207208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/207208\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=207208"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=207208"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=207208"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=207208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}