{"id":208811,"date":"2025-02-17T16:51:46","date_gmt":"2025-02-17T13:51:46","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/pacific-turtle\/"},"modified":"2025-02-17T16:51:46","modified_gmt":"2025-02-17T13:51:46","slug":"pacific-turtle","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/","title":{"rendered":"Pacific Turtle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":157319,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7118],"product_tag":[],"class_list":["post-208811","product","type-product","status-publish","has-post-thumbnail","product_cat-kinder-boulders","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pacific Turtle | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacific Turtle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217165159\/turtle-kids-boulder-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/\",\"name\":\"Pacific Turtle | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250217165159\\\/turtle-kids-boulder-1-scaled.webp\",\"datePublished\":\"2025-02-17T13:51:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250217165159\\\/turtle-kids-boulder-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250217165159\\\/turtle-kids-boulder-1-scaled.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/kinder-boulders\\\/pacific-turtle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pacific Turtle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pacific Turtle | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/","og_locale":"de_DE","og_type":"article","og_title":"Pacific Turtle","og_url":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217165159\/turtle-kids-boulder-1-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/","url":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/","name":"Pacific Turtle | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217165159\/turtle-kids-boulder-1-scaled.webp","datePublished":"2025-02-17T13:51:46+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217165159\/turtle-kids-boulder-1-scaled.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217165159\/turtle-kids-boulder-1-scaled.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/kinder-boulders\/pacific-turtle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Pacific Turtle"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/208811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/208811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/157319"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=208811"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=208811"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=208811"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=208811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}