{"id":218384,"date":"2025-04-29T14:16:49","date_gmt":"2025-04-29T11:16:49","guid":{"rendered":"https:\/\/walltopia.com\/products\/unkategorisiert\/wolken-klettersteig\/"},"modified":"2026-01-22T14:20:38","modified_gmt":"2026-01-22T11:20:38","slug":"wolken-klettersteig","status":"publish","type":"product","link":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/","title":{"rendered":"Wolken-Klettersteig"},"content":{"rendered":"<p>Dieses Produkt ist in den folgenden Farbkombinationen erh\u00e4ltlich:<\/p>\n<h4>Zitrus-Splash<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-647-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">647 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1205-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1205 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-106-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">106 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-137-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">137 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-0821-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">0821 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7689-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7689 C<\/div>\n<\/div><\/div>\n<\/div>\n<h4>Riff<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-554-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">554 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7473-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7473 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7471-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7471 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-106-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">106 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1495-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1495 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-171-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">171 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-169-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">169 C<\/div>\n<\/div><\/div>\n<\/div>\n<h4>Koralle<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-7718-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7718 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-11-0601-tpx\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">11-0601 TPX<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-2024-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">2024 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-3546-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">3546 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-284-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">284 C<\/div>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Eine ruhige und ger\u00e4umige Anlage, die Kinder dazu einl\u00e4dt, in ihrem eigenen Tempo zu wandern und zu erkunden. Mit breiten Plattformen und erh\u00f6hter Aussicht verbindet dieses Modell Klettern mit Neugier, wie ein Pfad in den Wolken. ","protected":false},"featured_media":172506,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7918],"product_tag":[],"class_list":["post-218384","product","type-product","status-publish","has-post-thumbnail","product_cat-cloud-climb","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wolken-Klettersteig | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wolken-Klettersteig\" \/>\n<meta property=\"og:description\" content=\"Eine ruhige und ger\u00e4umige Anlage, die Kinder dazu einl\u00e4dt, in ihrem eigenen Tempo zu wandern und zu erkunden. Mit breiten Plattformen und erh\u00f6hter Aussicht verbindet dieses Modell Klettern mit Neugier, wie ein Pfad in den Wolken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:20:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002163748\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/\",\"name\":\"Wolken-Klettersteig | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002163748\\\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg\",\"datePublished\":\"2025-04-29T11:16:49+00:00\",\"dateModified\":\"2026-01-22T11:20:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002163748\\\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002163748\\\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/product\\\/cloud-climb\\\/wolken-klettersteig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ft\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wolken-Klettersteig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wolken-Klettersteig | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/","og_locale":"de_DE","og_type":"article","og_title":"Wolken-Klettersteig","og_description":"Eine ruhige und ger\u00e4umige Anlage, die Kinder dazu einl\u00e4dt, in ihrem eigenen Tempo zu wandern und zu erkunden. Mit breiten Plattformen und erh\u00f6hter Aussicht verbindet dieses Modell Klettern mit Neugier, wie ein Pfad in den Wolken.","og_url":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-22T11:20:38+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002163748\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/","url":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/","name":"Wolken-Klettersteig | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002163748\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg","datePublished":"2025-04-29T11:16:49+00:00","dateModified":"2026-01-22T11:20:38+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002163748\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002163748\/cloud-climb-trail-citrus-splash-01-1-scaled.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/product\/cloud-climb\/wolken-klettersteig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/walltopia.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Wolken-Klettersteig"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/218384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product\/218384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/172506"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=218384"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_brand?post=218384"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_cat?post=218384"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/product_tag?post=218384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}