{"id":151318,"date":"2024-12-04T18:46:24","date_gmt":"2024-12-04T15:46:24","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=151318"},"modified":"2024-12-04T18:46:24","modified_gmt":"2024-12-04T15:46:24","slug":"private-house-outdoor-climbing-wall","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/","title":{"rendered":"Private House &#8211; Outdoor Climbing Wall"},"content":{"rendered":"<p>A private house featured a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of GRP or in other words &#8211; fiberglass &#8211; meaning it is completely weather-resistant. The rocktopia climbing wall features two autobelay lines and a boulder\/traverse in the lower part.<\/p>\n","protected":false},"featured_media":151362,"template":"","wt_project_category":[761],"class_list":["post-151318","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Private House - Outdoor Climbing Wall | Walltopia<\/title>\n<meta name=\"description\" content=\"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Private House - Outdoor Climbing Wall\" \/>\n<meta property=\"og:description\" content=\"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20241204183403\/Rocktopia-by-Walltopia-Geneva-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1069\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/\",\"name\":\"Private House - Outdoor Climbing Wall | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20241204183403\\\/Rocktopia-by-Walltopia-Geneva-2.jpeg\",\"datePublished\":\"2024-12-04T15:46:24+00:00\",\"description\":\"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20241204183403\\\/Rocktopia-by-Walltopia-Geneva-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20241204183403\\\/Rocktopia-by-Walltopia-Geneva-2.jpeg\",\"width\":1069,\"height\":792,\"caption\":\"Walltopia outdoor climbing wall made of fiberglass in Rocktopia style\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/private-house-outdoor-climbing-wall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projekte\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Private House &#8211; Outdoor Climbing Wall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Private House - Outdoor Climbing Wall | Walltopia","description":"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/","og_locale":"de_DE","og_type":"article","og_title":"Private House - Outdoor Climbing Wall","og_description":"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.","og_url":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1069,"height":792,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20241204183403\/Rocktopia-by-Walltopia-Geneva-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/","url":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/","name":"Private House - Outdoor Climbing Wall | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20241204183403\/Rocktopia-by-Walltopia-Geneva-2.jpeg","datePublished":"2024-12-04T15:46:24+00:00","description":"A private house featuring a rocktopia style climbing wall on their facade. The outdoor climbing wall is made of weather-resistant fiberglass.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20241204183403\/Rocktopia-by-Walltopia-Geneva-2.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20241204183403\/Rocktopia-by-Walltopia-Geneva-2.jpeg","width":1069,"height":792,"caption":"Walltopia outdoor climbing wall made of fiberglass in Rocktopia style"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/projects\/private-house-outdoor-climbing-wall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Projekte","item":"https:\/\/walltopia.com\/de\/projects\/"},{"@type":"ListItem","position":3,"name":"Private House &#8211; Outdoor Climbing Wall"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project\/151318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/151362"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=151318"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project_category?post=151318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}