{"id":18026,"date":"2021-07-14T14:52:12","date_gmt":"2021-07-14T11:52:12","guid":{"rendered":"https:\/\/dev-three.agmastudio.com\/?post_type=wt_project&#038;p=18026"},"modified":"2024-02-23T10:31:42","modified_gmt":"2024-02-23T07:31:42","slug":"indoorwall-centers-vic","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/","title":{"rendered":"Indoorwall Centers: Vic"},"content":{"rendered":"","protected":false},"featured_media":18031,"template":"","wt_project_category":[881],"class_list":["post-18026","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Indoorwall Centers: Vic - Projects | Walltopia Climbing Walls<\/title>\n<meta name=\"description\" content=\"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indoorwall Centers: Vic\" \/>\n<meta property=\"og:description\" content=\"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-23T07:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230735\/IMG_20190301_112119-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/\",\"name\":\"Indoorwall Centers: Vic - Projects | Walltopia Climbing Walls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027230735\\\/IMG_20190301_112119-6.jpg\",\"datePublished\":\"2021-07-14T11:52:12+00:00\",\"dateModified\":\"2024-02-23T07:31:42+00:00\",\"description\":\"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027230735\\\/IMG_20190301_112119-6.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027230735\\\/IMG_20190301_112119-6.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/indoorwall-centers-vic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projekte\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indoorwall Centers: Vic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Indoorwall Centers: Vic - Projects | Walltopia Climbing Walls","description":"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/","og_locale":"de_DE","og_type":"article","og_title":"Indoorwall Centers: Vic","og_description":"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.","og_url":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-02-23T07:31:42+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230735\/IMG_20190301_112119-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/","url":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/","name":"Indoorwall Centers: Vic - Projects | Walltopia Climbing Walls","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230735\/IMG_20190301_112119-6.jpg","datePublished":"2021-07-14T11:52:12+00:00","dateModified":"2024-02-23T07:31:42+00:00","description":"Indoorwall Centers: Vic is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Training Boards based in Barcelona, Spain.","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230735\/IMG_20190301_112119-6.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230735\/IMG_20190301_112119-6.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/projects\/indoorwall-centers-vic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Projekte","item":"https:\/\/walltopia.com\/de\/projects\/"},{"@type":"ListItem","position":3,"name":"Indoorwall Centers: Vic"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project\/18026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/18031"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=18026"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project_category?post=18026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}