{"id":69025,"date":"2023-01-08T11:32:43","date_gmt":"2023-01-08T08:32:43","guid":{"rendered":"http:\/\/walltopia.com\/projects\/chengdu-kimcheon-sport-park\/"},"modified":"2024-04-05T19:41:27","modified_gmt":"2024-04-05T16:41:27","slug":"chengdu-kimcheon-sport-park","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/","title":{"rendered":"Chengdu Kimcheon Sport Park"},"content":{"rendered":"","protected":false},"featured_media":69026,"template":"","wt_project_category":[760],"class_list":["post-69025","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chengdu Kimcheon Sport Park | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chengdu Kimcheon Sport Park\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T16:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204739\/image_2020_10_29T11_34_26_155Z-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/\",\"name\":\"Chengdu Kimcheon Sport Park | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204739\\\/image_2020_10_29T11_34_26_155Z-2.jpg\",\"datePublished\":\"2023-01-08T08:32:43+00:00\",\"dateModified\":\"2024-04-05T16:41:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204739\\\/image_2020_10_29T11_34_26_155Z-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204739\\\/image_2020_10_29T11_34_26_155Z-2.jpg\",\"width\":1440,\"height\":1080,\"caption\":\"Chengdu Kimcheon Sport Park\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/chengdu-kimcheon-sport-park\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/startseite-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projekte\",\"item\":\"https:\\\/\\\/walltopia.com\\\/de\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chengdu Kimcheon Sport Park\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chengdu Kimcheon Sport Park | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/","og_locale":"de_DE","og_type":"article","og_title":"Chengdu Kimcheon Sport Park","og_url":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-04-05T16:41:27+00:00","og_image":[{"width":1440,"height":1080,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204739\/image_2020_10_29T11_34_26_155Z-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/","url":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/","name":"Chengdu Kimcheon Sport Park | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204739\/image_2020_10_29T11_34_26_155Z-2.jpg","datePublished":"2023-01-08T08:32:43+00:00","dateModified":"2024-04-05T16:41:27+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204739\/image_2020_10_29T11_34_26_155Z-2.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204739\/image_2020_10_29T11_34_26_155Z-2.jpg","width":1440,"height":1080,"caption":"Chengdu Kimcheon Sport Park"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/de\/projects\/chengdu-kimcheon-sport-park\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/de\/startseite-de\/"},{"@type":"ListItem","position":2,"name":"Projekte","item":"https:\/\/walltopia.com\/de\/projects\/"},{"@type":"ListItem","position":3,"name":"Chengdu Kimcheon Sport Park"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/de\/#website","url":"https:\/\/walltopia.com\/de\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/de\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project\/69025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media\/69026"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/media?parent=69025"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/de\/wp-json\/wp\/v2\/wt_project_category?post=69025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}