{"id":116201,"date":"2021-06-15T10:43:48","date_gmt":"2021-06-15T07:43:48","guid":{"rendered":"http:\/\/walltopia.com\/servicios\/establecimiento-de-rutas\/"},"modified":"2026-01-15T17:31:13","modified_gmt":"2026-01-15T14:31:13","slug":"establecimiento-de-rutas","status":"publish","type":"page","link":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/","title":{"rendered":"Establecimiento de rutas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_empty_space height=\u00bb50px\u00bb][vc_custom_heading text=\u00bbDESDE LA CONFIGURACI\u00d3N INICIAL HASTA EL RESTABLECIMIENTO: LO HACEMOS TODO\u00bb font_container=\u00bbtag:h3|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_empty_space height=\u00bb42px\u00bb][vc_custom_heading text=\u00bbPREPARE SU GIMNASIO PARA EL D\u00cdA DE LA INAUGURACI\u00d3N\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_empty_space height=\u00bb10px\u00bb][vc_column_text]El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo, que nuestro equipo de trazadores de rutas profesionales est\u00e1 dispuesto a asumir.<\/p>\n<p>Nuestro equipo ha realizado primeras v\u00edas en todo el mundo, desde el roc\u00f3dromo de 80 m de altura en el duro oto\u00f1o escandinavo hasta los calurosos gimnasios de escalada de Arabia Saud\u00ed. Pueden preparar su gimnasio para acoger y atender a los escaladores de la mejor manera posible el d\u00eda de la inauguraci\u00f3n.<\/p>\n<p>Adem\u00e1s de establecer las rutas iniciales, nuestro equipo tambi\u00e9n se encarga de reajustarlas. La reposici\u00f3n de rutas es el n\u00facleo de todo gimnasio de escalada. Nuestro equipo de routesetters est\u00e1 formado por profesionales con a\u00f1os de experiencia en el sector. Pueden responder a las necesidades de su gimnasio y de sus socios, no s\u00f3lo mejorando las habilidades de los escaladores, sino tambi\u00e9n la est\u00e9tica general del gimnasio, al tiempo que se aseguran de que haya suficiente variedad en el gimnasio.[\/vc_column_text][vc_empty_space height=\u00bb42px\u00bb][vc_empty_space height=\u00bb10px\u00bb][vc_video link=\u00bbhttps:\/\/www.youtube.com\/watch?v=6NFXySWtFCQ\u00bb css=\u00bb\u00bb title=\u00bbWalden, B\u00e9lgica &#8211; Establecimiento de rutas 2025&#8243;][vc_empty_space height=\u00bb42px\u00bb][vc_video link=\u00bbhttps:\/\/www.youtube.com\/watch?v=vdZHBVJRN0w\u00bb title=\u00bbLevel Up, B\u00e9lgica &#8211; Rutas iniciales 2022&#8243;][vc_empty_space height=\u00bb42px\u00bb][vc_video link=\u00bbhttps:\/\/www.youtube.com\/watch?v=D12iUkZHpCw\u00bb css=\u00bb\u00bb title=\u00bbTren SF, Abu Dhabi 2024&#8243;][vc_empty_space height=\u00bb42px\u00bb][vc_custom_heading text=\u00bbLOS TRAZADORES DE RUTAS\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101519,101526&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbEmiliyan Kolevski\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Emiliyan Kolevski lleva 20 a\u00f1os en el sector. Ha escalado en grandes lugares de todo el mundo y ha participado en numerosas competiciones nacionales e internacionales, como la primera edici\u00f3n de la Red Bull Creepers en Pamplona (Espa\u00f1a), donde compiti\u00f3 con algunos de los escaladores m\u00e1s fuertes del mundo.<\/p>\n<p>Ahora es uno de los jefes de rutas de Walltopia y trabaja en proyectos por todo el mundo.<\/p>\n<p>Si quer\u00e9is ver por vosotros mismos lo que ha estado haciendo Emiliyan, pod\u00e9is echar un vistazo aqu\u00ed:<\/p>\n<p><strong>Chamonix, Aiguille Du Midi &#8211; Agosto 2022<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Chamonix, Aiguille Du Midi, Operation: Electric Avenue trailer\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/5TeJVRY3khY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Opa Opa 8c, Bulgaria &#8211; Mayo 2021<\/strong><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=td9cTeIDlDg&amp;t=3s[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101534&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbNATALEIGH BELL\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Nataleigh es cofundadora de Blackbox Boulder y Atari Climbing. Es routesetter profesional y ha trabajado tanto en el \u00e1mbito de la computaci\u00f3n de alto nivel como en el comercial.<\/p>\n<p>Nataleigh forma parte del equipo nacional belga de colocadores y es una de las primeras colocadoras profesionales (aut\u00f3nomas) de B\u00e9lgica.<\/p>\n<p>Ha hecho todo lo relacionado con la escalada, desde repeticiones de presas de escalada, entrenamiento personal hasta establecimiento de rutas y talleres educativos para el establecimiento de rutas.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101541&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbJAN DE SMIT\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Jan De Smit es un rodador belga y cofundador de Blackbox Boulder, Atari climbing y BFIC (Federaci\u00f3n Belga de Escalada en Sala). Atari climbing ofrece las claves necesarias para poner en marcha un roc\u00f3dromo, dirigir y gestionar la creaci\u00f3n de rutas. Jan es uno de los rodadores y formadores con m\u00e1s experiencia de B\u00e9lgica. Ha formado parte del equipo nacional de montaje durante m\u00e1s de una d\u00e9cada. Como ex-competidor, entrenador, propietario de gimnasio y routeetter ve las cosas en todas las perspectivas.<\/p>\n<p>Jan ha creado el primer curso educativo de trazado de rutas en B\u00e9lgica (centrado en la seguridad) y actualmente trabaja en la publicaci\u00f3n de un libro sobre todo ello para finales de 2023.<\/p>\n<p>Foto de Andy Day.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101548&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbANDR\u00c9 NERES\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Andr\u00e9 lleva 23 a\u00f1os en el sector. Es escalador profesional, adem\u00e1s de trazador de rutas profesional.<br \/>\nLa combinaci\u00f3n de estar involucrado en m\u00faltiples proyectos de escalada comercial y seguir activo en la escena de la escalada de competici\u00f3n, proporciona una perspectiva muy rica del panorama de la trazada de rutas. Viajar por todo el mundo para escalar aporta una refrescante aportaci\u00f3n de inspiraci\u00f3n para satisfacer todas las necesidades de los gimnasios de escalada.<br \/>\nAdem\u00e1s, su pasi\u00f3n por la escalada al aire libre y la comunidad de escaladores es la principal fuente de su dedicaci\u00f3n a este deporte, intentando aportar ese sentimiento en todo momento a las actividades de interior.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb108787,108773,108780&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbC\u00e9sar Grosso\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Cesare vive en Arco, Italia. Su periplo escalador comenz\u00f3 en 1995 en Brasil, donde consigui\u00f3 11 t\u00edtulos nacionales y algunas victorias continentales. Es un veterano participante en m\u00faltiples Copas del Mundo. Como escalador profesional, ha escalado rutas desafiantes en todo el mundo, con una dificultad de hasta 9a. Su primer trabajo en el sector fue lavar bodegas, luego se hizo routesetter y empez\u00f3 a montar en gimnasios de toda Europa (sobre todo en Italia). Tambi\u00e9n ha trabajado como entrenador y asesor de gimnasios de escalada.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101819,101826&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbNIKOLA MIRCHEV\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Nikola es un miembro joven y muy motivado de nuestra tripulaci\u00f3n, que cuenta con una notable experiencia en el campo de la escalada para su edad. Durante los dos \u00faltimos a\u00f1os, ha sido parte integrante del mayor gimnasio de escalada de Bulgaria, donde se ha dedicado a trazar rutas, y durante un a\u00f1o ha destacado como entrenador de escalada. Adem\u00e1s, participa activamente en la organizaci\u00f3n de rutas y en la distribuci\u00f3n del trabajo en el gimnasio. Nikola ha desempe\u00f1ado papeles clave en la organizaci\u00f3n de varios eventos de escalada.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb42px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb101932&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbKALIN GARBOV\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Kalin Garbov lleva 30 a\u00f1os en el sector y ha desempe\u00f1ado muchas funciones durante este tiempo. Adem\u00e1s de ser uno de los mejores escaladores b\u00falgaros, Kalin tiene tambi\u00e9n una amplia experiencia como entrenador de escalada. Desarrolla programas de formaci\u00f3n para academias de escalada y ahora es el entrenador del equipo juvenil b\u00falgaro de escalada. Tiene m\u00e1s de 15 a\u00f1os de experiencia en el montaje de v\u00edas y es uno de los principales montadores del Centro de Escalada Walltopia.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb50px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_images_carousel images=\u00bb102224,102231&#8243; img_size=\u00bb600&#215;600&#8243; speed=\u00bb2500&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb2\/4&#8243;][vc_custom_heading text=\u00bbMartin Penkov\u00bb font_container=\u00bbtag:h4|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_column_text]Martin Penkov lleva m\u00e1s de 15 a\u00f1os en el mundo de la escalada. Martin no s\u00f3lo es entrenador de escalada, sino tambi\u00e9n escalador profesional, con premios en numerosas competiciones nacionales. Su talento y dedicaci\u00f3n tambi\u00e9n le valieron una plaza en varias competiciones europeas y mundiales por toda Europa.<\/p>\n<p>Adem\u00e1s, est\u00e1 especializado en la reparaci\u00f3n de pies de gato y es un valioso entrenador en uno de los mejores equipos de escalada del pa\u00eds. Su experiencia va m\u00e1s all\u00e1 del entrenamiento, ya que contribuye activamente a la organizaci\u00f3n y establecimiento de rutas para diversas competiciones dirigidas tanto a ni\u00f1os como a adultos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00bb100px\u00bb][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_empty_space height=\u00bb50px\u00bb][vc_custom_heading text=\u00bbDESDE LA CONFIGURACI\u00d3N INICIAL HASTA EL RESTABLECIMIENTO: LO HACEMOS TODO\u00bb font_container=\u00bbtag:h3|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][vc_empty_space height=\u00bb42px\u00bb][vc_custom_heading text=\u00bbPREPARE SU GIMNASIO PARA EL&#8230;","protected":false},"author":6,"featured_media":101511,"parent":83206,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-big-header.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-116201","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Establecimiento de rutas | Walltopia<\/title>\n<meta name=\"description\" content=\"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Establecimiento de rutas\" \/>\n<meta property=\"og:description\" content=\"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027133552\/SAM_0806-29-29-e1691072136539.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1092\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/\",\"name\":\"Establecimiento de rutas | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027133552\\\/SAM_0806-29-29-e1691072136539.jpg\",\"datePublished\":\"2021-06-15T07:43:48+00:00\",\"dateModified\":\"2026-01-15T14:31:13+00:00\",\"description\":\"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027133552\\\/SAM_0806-29-29-e1691072136539.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027133552\\\/SAM_0806-29-29-e1691072136539.jpg\",\"width\":1200,\"height\":1092,\"caption\":\"Emiliyan Routesetter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/establecimiento-de-rutas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/servicios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Establecimiento de rutas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Establecimiento de rutas | Walltopia","description":"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/","og_locale":"es_ES","og_type":"article","og_title":"Establecimiento de rutas","og_description":"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -","og_url":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T14:31:13+00:00","og_image":[{"width":1200,"height":1092,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027133552\/SAM_0806-29-29-e1691072136539.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/","url":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/","name":"Establecimiento de rutas | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027133552\/SAM_0806-29-29-e1691072136539.jpg","datePublished":"2021-06-15T07:43:48+00:00","dateModified":"2026-01-15T14:31:13+00:00","description":"El trazado inicial de rutas de todo un roc\u00f3dromo es un proyecto amplio y que requiere mucho tiempo. Los Walltopians est\u00e1n listos para enfrentarse a ella -","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027133552\/SAM_0806-29-29-e1691072136539.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027133552\/SAM_0806-29-29-e1691072136539.jpg","width":1200,"height":1092,"caption":"Emiliyan Routesetter"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/servicios\/establecimiento-de-rutas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/walltopia.com\/es\/servicios\/"},{"@type":"ListItem","position":3,"name":"Establecimiento de rutas"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/pages\/116201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=116201"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/pages\/116201\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/pages\/83206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/101511"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=116201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}