{"id":181079,"date":"2021-06-18T09:54:06","date_gmt":"2021-06-18T06:54:06","guid":{"rendered":"https:\/\/walltopia.com\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/"},"modified":"2026-01-15T16:53:49","modified_gmt":"2026-01-15T13:53:49","slug":"aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/","title":{"rendered":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbEste a\u00f1o, Walltopia Adventure ser\u00e1 expositor por primera vez en la Exposici\u00f3n de Atracciones de la IAAPI.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb link=\u00bburl:https%3A%2F%2Fadventure.walltopia.com%2F|title:Walltopia%20Adventure%20|target:_blank|\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">La exposici\u00f3n se celebrar\u00e1 del 3 al 5 de marzo en el <strong>Centro de Exposiciones de Bombay, India<\/strong>.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Obt\u00e9n m\u00e1s informaci\u00f3n sobre nuestros <a href=\"https:\/\/adventure.walltopia.com\/products\/ropes-course\/\">circuitos de cuerdas<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/fun-walls\/\">roc\u00f3dromos interactivos<\/a>, <a href=\"https:\/\/adventure.walltopia.com\/products\/walltopia-caves\/\">sistemas de espeleolog\u00eda<\/a> y nuestra nueva atracci\u00f3n, el <a href=\"https:\/\/adventure.walltopia.com\/products\/rollglider\/\">Rollglider<\/a>, en el stand A3, Pabell\u00f3n 5. Contacta con nosotros en <a href=\"mailto:sales@walltopia.com\">sales@walltopia.com<\/a> para concertar una reuni\u00f3n.<\/p>\n[\/vc_column_text]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/adventure.walltopia.com\/\" target=\"_blank\">Walltopia Adventure <\/a><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_images_carousel images=\u00bb21755,21761,21773&#8243; img_size=\u00bbfull\u00bb speed=\u00bb4000&#8243; autoplay=\u00bbyes\u00bb hide_pagination_control=\u00bbyes\u00bb wrap=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00bbEste a\u00f1o, Walltopia Adventure ser\u00e1 expositor por primera vez en la Exposici\u00f3n de Atracciones de la IAAPI.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb&#8230;","protected":false},"author":10,"featured_media":21749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[935],"tags":[1760,1037,1817,1820,1036],"class_list":["post-181079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-cuevas-de-walltopia","tag-curso-de-cuerdas","tag-exposicion-iaapi-amusement","tag-muros-interactivos","tag-planeador"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai | Walltopia<\/title>\n<meta name=\"description\" content=\"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai\" \/>\n<meta property=\"og:description\" content=\"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T06:54:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T13:53:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai\",\"datePublished\":\"2021-06-18T06:54:06+00:00\",\"dateModified\":\"2026-01-15T13:53:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/\"},\"wordCount\":215,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090610\\\/IAAPI-Mumbai.jpg\",\"keywords\":[\"cuevas de walltopia\",\"curso de cuerdas\",\"Exposici\u00f3n IAAPI Amusement\",\"Muros interactivos\",\"Planeador\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/\",\"name\":\"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090610\\\/IAAPI-Mumbai.jpg\",\"datePublished\":\"2021-06-18T06:54:06+00:00\",\"dateModified\":\"2026-01-15T13:53:49+00:00\",\"description\":\"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090610\\\/IAAPI-Mumbai.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090610\\\/IAAPI-Mumbai.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai | Walltopia","description":"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/","og_locale":"es_ES","og_type":"article","og_title":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai","og_description":"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.","og_url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T06:54:06+00:00","article_modified_time":"2026-01-15T13:53:49+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai","datePublished":"2021-06-18T06:54:06+00:00","dateModified":"2026-01-15T13:53:49+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/"},"wordCount":215,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg","keywords":["cuevas de walltopia","curso de cuerdas","Exposici\u00f3n IAAPI Amusement","Muros interactivos","Planeador"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/","url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/","name":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg","datePublished":"2021-06-18T06:54:06+00:00","dateModified":"2026-01-15T13:53:49+00:00","description":"Si quieres saber m\u00e1s sobre nuestros recorridos de cuerdas, roc\u00f3dromos interactivos y nuestros otros productos, lee el art\u00edculo para ver c\u00f3mo concertar una reuni\u00f3n.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090610\/IAAPI-Mumbai.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-la-exposicion-de-atracciones-de-la-iaapi-en-mumbai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Aventura Walltopia en la Exposici\u00f3n de Atracciones de la IAAPI en Mumbai"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/181079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=181079"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/181079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/21749"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=181079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=181079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=181079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}