{"id":183364,"date":"2021-06-21T09:49:54","date_gmt":"2021-06-21T06:49:54","guid":{"rendered":"https:\/\/walltopia.com\/le-crux-del-sueno-a-la-realidad\/"},"modified":"2026-01-15T17:00:16","modified_gmt":"2026-01-15T14:00:16","slug":"le-crux-del-sueno-a-la-realidad","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/","title":{"rendered":"Le Crux &#8211; del sue\u00f1o a la realidad"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbUna idea. Una idea que se convierte en un sue\u00f1o. Y un sue\u00f1o que se convierte en un proyecto. Un proyecto con muchas preguntas, variables y noches sin dormir.   \u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00c9ste es el punto de partida de muchos de los gimnasios de escalada que conocemos. A veces no hay un buen gimnasio de escalada en la zona, a veces hay uno pero no es suficiente para servir a la comunidad, a veces simplemente crees que puedes mejorarlo. O simplemente crees que el trabajo de 9 a 5 te ha servido bien hasta ahora. Y ahora es el momento de empezar a alimentar esa idea tuya, convertirla en un sue\u00f1o y luego en un proyecto.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Inspir\u00e1ndonos en la historia que hay detr\u00e1s de cada gimnasio de escalada y en las lecciones aprendidas a lo largo del camino, vamos a iniciar una serie de breves entrevistas con propietarios de gimnasios para explorar la fuerza motriz que hay detr\u00e1s de su decisi\u00f3n de crear y dirigir un gimnasio de escalada.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nos hace mucha ilusi\u00f3n compartir hoy la historia de Le Crux (Canad\u00e1), ya que ayer terminamos de montar all\u00ed sus nuevos muros de boulder. Nos encanta esta sensaci\u00f3n: meses y meses de planificaci\u00f3n y trabajo tanto por nuestra parte como por parte del cliente, y entonces llega el momento en que ves los resultados de todos los esfuerzos, los frutos del trabajo de todos y c\u00f3mo el edificio vac\u00edo se ha convertido en un hermoso lugar de escalada. Adem\u00e1s de la zona de boulder reci\u00e9n construida, Le Crux tambi\u00e9n cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo, y Jonathan s\u00ed que sabe lo que significa convertir un sue\u00f1o en realidad.   <\/p>\n[\/vc_column_text][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Una \u00faltima cosa antes de dejarte con la historia de Jon -una buena raz\u00f3n para hacer una visita si est\u00e1s cerca- es su invitado especial del 13 de marzo (lunes): Sean McColl. Todos hemos visto a Sean en acci\u00f3n y es impresionante: no parece obedecer mucho las leyes de la gravedad. <\/p>\n[\/vc_column_text][vc_custom_heading text=\u00bbWT: \u00bfRecuerdas c\u00f3mo se te ocurri\u00f3 la idea de tener un gimnasio de escalada? \u00bfQu\u00e9 te llev\u00f3 a ello? \u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jonathan:<\/strong> <em>El sue\u00f1o de tener un gimnasio de escalada fue una especie de fusi\u00f3n entre una pasi\u00f3n, la escalada, y una carrera, el esp\u00edritu empresarial. De adolescente, miraba a los empresarios y deseaba que alg\u00fan d\u00eda yo hiciera lo mismo, es decir, tener una visi\u00f3n y hacerla realidad. El hecho de haber tenido la oportunidad de tener un gimnasio de escalada como primer negocio es un sue\u00f1o hecho realidad. Mi socio y yo llev\u00e1bamos mucho tiempo trabajando en el proyecto cuando el propietario del gimnasio en el que sol\u00edamos escalar cuando \u00e9ramos ni\u00f1os nos pidi\u00f3 que nos reuni\u00e9ramos con \u00e9l para unificar nuestras fuerzas. Entonces naci\u00f3 Le CRUX.    <\/em><\/p>\n[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb22115&#8243; img_size=\u00bbfull\u00bb onclick=\u00bblink_image\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1624257309895{padding-top: 2% !important;}\u00bb][vc_single_image image=\u00bb22109&#8243; img_size=\u00bbfull\u00bb onclick=\u00bblink_image\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1624257318681{padding-top: 4% !important;}\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00bbWT: \u00bfCu\u00e1l ha sido el reto m\u00e1s dif\u00edcil en el camino del sue\u00f1o a la realidad?\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1624257508175{padding-top: 2% !important;}\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jonathan:<\/strong> <em>El proyecto ha tenido su parte dura, sin duda. La planificaci\u00f3n financiera fue bien, la parte del dise\u00f1o llev\u00f3 m\u00e1s tiempo del esperado porque quer\u00edamos algunos detalles espec\u00edficos de los que estamos muy orgullosos ahora que est\u00e1 hecho. Las largas jornadas de trabajo divididas entre las tareas cotidianas de la nueva secci\u00f3n, el cambio de los antiguos modales en el antiguo gimnasio y la renovaci\u00f3n de la antigua secci\u00f3n, todo al mismo tiempo, consumieron tiempo y energ\u00eda. Al final, todo el duro trabajo mereci\u00f3 la pena porque ahora tenemos m\u00e1s escaladores que nunca, el ambiente es impresionante y el futuro parece brillante para nuestro tan amado deporte. Al final, los retos no son m\u00e1s que situaciones en las que tienes que encontrar las soluciones para pasar a la siguiente&#8230; Es muy parecido a proyectar algo duro en la escalada; una vez que te has fijado un objetivo, \u00a1tienes que encontrar la forma de conseguirlo!    <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=\u00bbWT: \u00bfC\u00f3mo fue la noche anterior a la inauguraci\u00f3n oficial? Y luego, \u00bfc\u00f3mo fue el gran d\u00eda siguiente? \u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jon:  <\/strong><em>Al principio nos hicimos cargo de la gesti\u00f3n del antiguo gimnasio, as\u00ed que el objetivo principal era renovar lo mejor posible esa parte envejecida del gimnasio. En cuanto a la nueva secci\u00f3n de b\u00falder, la inauguraci\u00f3n ser\u00e1 a finales de febrero, as\u00ed que ahora mismo no puedo decir qu\u00e9 se siente, pero con s\u00f3lo mirar las paredes del primer piso que est\u00e1n hechas, \u00a1dir\u00eda que me siento como un ni\u00f1o en Nochebuena! \u00a1Estoy impaciente por probar estos flamantes juguetes!  <\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_custom_heading text=\u00bbWT: Mirando atr\u00e1s, \u00bfcambiar\u00edas algo?\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jon:<\/strong> Yo<em>  Intento vivir sin arrepentimientos. Las decisiones que tom\u00e9 en el pasado me trajeron aqu\u00ed y es m\u00e1s o menos donde pensaba estar&#8230; As\u00ed que, para ser sincero, dir\u00eda que no. <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=\u00bbWT: \u00bfAlg\u00fan consejo para la gente que est\u00e1 pensando en seguir tu camino?\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jon:<\/strong> <em>\u00a1M\u00e1s vale que te gusten los d\u00edas largos! El trabajo duro tiene su recompensa alg\u00fan d\u00eda&#8230; <\/em><\/p>\n[\/vc_column_text][vc_custom_heading text=\u00bbWT: En tres palabras, \u00bfqu\u00e9 significa para ti poseer y dirigir un gimnasio de escalada?\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23ed2020|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Jon:<\/strong> <em>\u00a1La vida es buena!<\/em><\/p>\n[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb22103&#8243; img_size=\u00bbfull\u00bb onclick=\u00bblink_image\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1624257428267{padding-top: 2% !important;}\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Jonathan Poitras, Le Crux en Boisbriand, QC, Canad\u00e1<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb width=\u00bb1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.facebook.com\/centredescaladelecrux\/\" target=\"_blank\">Le Crux Facebook<\/a><\/div>[\/vc_column][vc_column css_animation=\u00bbfadeInUp\u00bb width=\u00bb1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.youtube.com\/watch?v=ixDCNpgs_t8\" target=\"_blank\">Le Crux YouTube<\/a><\/div>[\/vc_column][vc_column css_animation=\u00bbfadeInUp\u00bb width=\u00bb1\/3&#8243;]<div class=\"link-button-container block width-100  text-align-left\"><a class=\"wt-link \" href=\"https:\/\/www.lecrux.com\/\" target=\"_blank\">Le Crux Website<\/a><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00bbUna idea. Una idea que se convierte en un sue\u00f1o. Y un sue\u00f1o que se convierte en un proyecto&#8230;.","protected":false},"author":10,"featured_media":22097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[935],"tags":[2258,2259],"class_list":["post-183364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-entrevista","tag-gimnasio-de-escalada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Crux - del sue\u00f1o a la realidad | Walltopia<\/title>\n<meta name=\"description\" content=\"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Crux - del sue\u00f1o a la realidad\" \/>\n<meta property=\"og:description\" content=\"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-21T06:49:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Le Crux &#8211; del sue\u00f1o a la realidad\",\"datePublished\":\"2021-06-21T06:49:54+00:00\",\"dateModified\":\"2026-01-15T14:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/\"},\"wordCount\":1374,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085816\\\/Picture4.jpg\",\"keywords\":[\"entrevista\",\"gimnasio de escalada\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/\",\"name\":\"Le Crux - del sue\u00f1o a la realidad | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085816\\\/Picture4.jpg\",\"datePublished\":\"2021-06-21T06:49:54+00:00\",\"dateModified\":\"2026-01-15T14:00:16+00:00\",\"description\":\"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085816\\\/Picture4.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085816\\\/Picture4.jpg\",\"width\":738,\"height\":553},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/le-crux-del-sueno-a-la-realidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Crux &#8211; del sue\u00f1o a la realidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Crux - del sue\u00f1o a la realidad | Walltopia","description":"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/","og_locale":"es_ES","og_type":"article","og_title":"Le Crux - del sue\u00f1o a la realidad","og_description":"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.","og_url":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-21T06:49:54+00:00","article_modified_time":"2026-01-15T14:00:16+00:00","og_image":[{"width":738,"height":553,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Le Crux &#8211; del sue\u00f1o a la realidad","datePublished":"2021-06-21T06:49:54+00:00","dateModified":"2026-01-15T14:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/"},"wordCount":1374,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg","keywords":["entrevista","gimnasio de escalada"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/","url":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/","name":"Le Crux - del sue\u00f1o a la realidad | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg","datePublished":"2021-06-21T06:49:54+00:00","dateModified":"2026-01-15T14:00:16+00:00","description":"Conoce a Jonathan, de Le Crux, un gimnasio que cuenta con 16.000 pies cuadrados de escalada en cuerda superior y en plomo. Jon comparte lo que significa convertir un sue\u00f1o en realidad.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085816\/Picture4.jpg","width":738,"height":553},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/le-crux-del-sueno-a-la-realidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Le Crux &#8211; del sue\u00f1o a la realidad"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/183364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=183364"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/183364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/22097"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=183364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=183364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=183364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}