{"id":184311,"date":"2021-06-18T13:53:24","date_gmt":"2021-06-18T10:53:24","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/"},"modified":"2026-01-15T17:02:35","modified_gmt":"2026-01-15T14:02:35","slug":"walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/","title":{"rendered":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbWalltopia expone en la Feria Outdoor de Friedrichshafen del 13 al 16 de julio.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Echa un vistazo a nuestros \u00faltimos productos e innovaciones en <strong>el stand 505 (Pabell\u00f3n B2)<\/strong>. Te presentaremos la pr\u00f3xima gran novedad en entretenimiento activo: <a href=\"https:\/\/adventure.walltopia.com\/products\/ninja-course\/\">Ninja Course<\/a>. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00a1Tambi\u00e9n nos hace mucha ilusi\u00f3n mostrarte algunos de nuestros proyectos en 3D! Pide nuestras gafas de realidad virtual y ver\u00e1s c\u00f3mo nuestros productos cobran vida. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>\u00a1Hasta pronto!<\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00bbWalltopia expone en la Feria Outdoor de Friedrichshafen del 13 al 16 de julio.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb] Echa&#8230;","protected":false},"author":10,"featured_media":21875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[935],"tags":[2386,2231],"class_list":["post-184311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-espectaculo-al-aire-libre","tag-espectaculo-al-aire-libre-en-friedrichshafen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen | Walltopia<\/title>\n<meta name=\"description\" content=\"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen\" \/>\n<meta property=\"og:description\" content=\"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T10:53:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:02:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen\",\"datePublished\":\"2021-06-18T10:53:24+00:00\",\"dateModified\":\"2026-01-15T14:02:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090201\\\/os.jpg\",\"keywords\":[\"Espect\u00e1culo al aire libre\",\"Espect\u00e1culo al aire libre en Friedrichshafen\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/\",\"name\":\"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090201\\\/os.jpg\",\"datePublished\":\"2021-06-18T10:53:24+00:00\",\"dateModified\":\"2026-01-15T14:02:35+00:00\",\"description\":\"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090201\\\/os.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090201\\\/os.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen | Walltopia","description":"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/","og_locale":"es_ES","og_type":"article","og_title":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen","og_description":"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.","og_url":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T10:53:24+00:00","article_modified_time":"2026-01-15T14:02:35+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen","datePublished":"2021-06-18T10:53:24+00:00","dateModified":"2026-01-15T14:02:35+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/"},"wordCount":120,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg","keywords":["Espect\u00e1culo al aire libre","Espect\u00e1culo al aire libre en Friedrichshafen"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/","url":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/","name":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg","datePublished":"2021-06-18T10:53:24+00:00","dateModified":"2026-01-15T14:02:35+00:00","description":"\u00danete a nosotros y conoce nuestro nuevo producto de entretenimiento activo: Ninja Course, y experimenta nuestros proyectos a trav\u00e9s de gafas de realidad virtual.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090201\/os.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-exposicion-al-aire-libre-de-friedrichshafen-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Walltopia en la Exposici\u00f3n al Aire Libre de Friedrichshafen"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/184311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=184311"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/184311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/21875"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=184311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=184311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=184311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}