{"id":184911,"date":"2021-06-18T11:38:08","date_gmt":"2021-06-18T08:38:08","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/"},"modified":"2026-01-15T17:04:16","modified_gmt":"2026-01-15T14:04:16","slug":"walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/","title":{"rendered":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbPor cuarto a\u00f1o consecutivo, Walltopia es el patrocinador principal de la Cumbre Anual de Roc\u00f3dromos de la CWA.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb link=\u00bburl:https%3A%2F%2Fwww.cwapro.org%2F|title:CWA|target:_blank|\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Este a\u00f1o realizaremos dos presentaciones durante la cumbre, que te ayudar\u00e1n a comprender todo el proceso de construcci\u00f3n de un roc\u00f3dromo, as\u00ed como a esbozar las \u00faltimas innovaciones de Walltopia en el dise\u00f1o de roc\u00f3dromos. Nuestro equipo abordar\u00e1 los problemas que se plantean con frecuencia durante la planificaci\u00f3n de una zona de escalada y te mostrar\u00e1 c\u00f3mo cosas tan sencillas como los colores personalizados, los vol\u00famenes de logotipos escalables y otros nuevos avances en dise\u00f1o te har\u00e1n destacar. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Este a\u00f1o la cumbre se celebrar\u00e1 en <strong>Loveland, Colorado, <\/strong><strong> del 19 al 21 de mayo<\/strong>.<\/p>\n[\/vc_column_text][vc_gallery interval=\u00bb3&#8243; images=\u00bb21839,21845&#8243; img_size=\u00bbfull\u00bb css_animation=\u00bbfadeInUp\u00bb][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00bbPor cuarto a\u00f1o consecutivo, Walltopia es el patrocinador principal de la Cumbre Anual de Roc\u00f3dromos de la CWA.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243;&#8230;","protected":false},"author":10,"featured_media":21833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[935],"tags":[2080],"class_list":["post-184911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-cwa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo | Walltopia<\/title>\n<meta name=\"description\" content=\"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo\" \/>\n<meta property=\"og:description\" content=\"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T08:38:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo\",\"datePublished\":\"2021-06-18T08:38:08+00:00\",\"dateModified\":\"2026-01-15T14:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090501\\\/CWA.jpg\",\"keywords\":[\"CWA\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/\",\"name\":\"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090501\\\/CWA.jpg\",\"datePublished\":\"2021-06-18T08:38:08+00:00\",\"dateModified\":\"2026-01-15T14:04:16+00:00\",\"description\":\"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090501\\\/CWA.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026090501\\\/CWA.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo | Walltopia","description":"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/","og_locale":"es_ES","og_type":"article","og_title":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo","og_description":"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.","og_url":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-18T08:38:08+00:00","article_modified_time":"2026-01-15T14:04:16+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo","datePublished":"2021-06-18T08:38:08+00:00","dateModified":"2026-01-15T14:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/"},"wordCount":203,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg","keywords":["CWA"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/","url":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/","name":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg","datePublished":"2021-06-18T08:38:08+00:00","dateModified":"2026-01-15T14:04:16+00:00","description":"Descubre la construcci\u00f3n de gimnasios de escalada y las \u00faltimas innovaciones en dise\u00f1o de Walltopia en nuestras presentaciones informativas.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026090501\/CWA.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/walltopia-patrocina-la-cwa-por-cuarto-ano-consecutivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Walltopia patrocina la CWA por cuarto a\u00f1o consecutivo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/184911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=184911"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/184911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/21833"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=184911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=184911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=184911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}