{"id":185832,"date":"2021-06-22T16:51:26","date_gmt":"2021-06-22T13:51:26","guid":{"rendered":"https:\/\/walltopia.com\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/"},"modified":"2026-01-15T17:30:39","modified_gmt":"2026-01-15T14:30:39","slug":"revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/","title":{"rendered":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbPuede que no siempre llegue con un estruendo instant\u00e1neo, como lo hacen los terremotos, los tornados y los huracanes, pero este silencioso y lento destructor cuesta a la econom\u00eda estadounidense m\u00e1s que todas las dem\u00e1s cat\u00e1strofes naturales juntas, sumando 437.000 millones de d\u00f3lares anuales o el 3 % del PIB de Estados Unidos.\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00bfLo has adivinado ya? \u00bfNo? Ok, aqu\u00ed tienes otra pista: Esta amenaza omnipresente convierte en \u00f3xido una tonelada de acero cada 90 segundos, en todo el mundo. \u00a1Exacto! \u00a1Es la corrosi\u00f3n!    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosi\u00f3n afecta a la vida \u00fatil de nuestras posesiones, aumenta los costes de reparaci\u00f3n y mantenimiento. Adem\u00e1s, derrumba edificios y cierra plantas industriales, provoca explosiones, fugas t\u00f3xicas e incendios. La protecci\u00f3n contra la corrosi\u00f3n est\u00e1 relacionada con muchas industrias y sectores, como el transporte, los equipos energ\u00e9ticos, el suministro de agua y la ingenier\u00eda de infraestructuras. De hecho, casi no hay empresa de Fortune 500, aparte de las de finanzas, seguros o banca, lo bastante privilegiada como para no tratar directamente con la corrosi\u00f3n. Aqu\u00ed es donde los costes en que incurren los productores y proveedores de bienes y servicios se trasladan a los clientes.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La corrosi\u00f3n podr\u00eda definirse en sentido amplio como cualquier interacci\u00f3n qu\u00edmica o electroqu\u00edmica entre un material y su entorno, que provoca el deterioro del material y sus propiedades. Al igual que el agua fluye hacia el nivel m\u00e1s bajo, los procesos naturales tienen tendencia a derivar hacia los estados de energ\u00eda m\u00e1s bajos posibles. Para la mayor\u00eda de los metales, excepto los nobles, el estado energ\u00e9tico m\u00e1s bajo resulta ser la forma de \u00f3xidos, igual que el mineral met\u00e1lico del que fueron procesados. As\u00ed pues, los metales est\u00e1n destinados a volver lentamente a este estado si no se toman las precauciones necesarias. La velocidad de ataque corrosivo de un determinado elemento met\u00e1lico depende de las propiedades qu\u00edmicas inherentes al propio metal y de la corrosividad del entorno en el que se encuentra. En general, los entornos h\u00famedos, industrialmente contaminados y saturados de agua salada son ambientes especialmente agresivos para las estructuras met\u00e1licas.     <\/p>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb22718&#8243; img_size=\u00bbfull\u00bb onclick=\u00bblink_image\u00bb css_animation=\u00bbfadeInUp\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb22706&#8243; img_size=\u00bbfull\u00bb onclick=\u00bblink_image\u00bb css_animation=\u00bbfadeInUp\u00bb][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1729251757312{padding-top: 2% !important;}\u00bb]\n<h4>C\u00f3mo ralentizar la corrosi\u00f3n<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Sin embargo, existen varios m\u00e9todos para ralentizar la corrosi\u00f3n. Uno de ellos es la aplicaci\u00f3n de un revestimiento met\u00e1lico de sacrificio, que a\u00edsle el metal subyacente del medio corrosivo. Esto puede conseguirse mediante la galvanizaci\u00f3n, que consiste en sumergir elementos de acero cuidadosamente preparados en zinc fundido. El resultado es una capa protectora de zinc, unida metal\u00fargicamente al sustrato de acero mediante una aleaci\u00f3n de hierro y zinc. Este tipo de protecci\u00f3n contra la corrosi\u00f3n prolonga la vida \u00fatil de las estructuras de acero al menos de 20 a 40 a\u00f1os en entornos industriales y hasta 100 a\u00f1os en zonas poco contaminadas. Los revestimientos polim\u00e9ricos, o simplemente pinturas, tienen la misma finalidad que los revestimientos met\u00e1licos, pero son capaces de prolongar la vida \u00fatil hasta 10 a\u00f1os.     <\/p>\n<h4>Nuestros sistemas d\u00faplex<\/h4>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Las estructuras de acero son una parte esencial de la ingenier\u00eda estructural realizada en Walltopia. Por eso nos vemos obligados a evitar generar costes evitables relacionados con la corrosi\u00f3n. Nuestra forma de hacerlo es ofreciendo todas nuestras estructuras de acero para exteriores con un \u00abrevestimiento d\u00faplex\u00bb: una capa de pintura polim\u00e9rica sobre la capa de zinc. Debido al efecto sin\u00e9rgico, los sistemas d\u00faplex tienen una vida \u00fatil entre 1,2 y 1,5 veces mayor que los periodos de protecci\u00f3n combinados de la galvanizaci\u00f3n en caliente y las capas de pintura.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Puede que nuestra contribuci\u00f3n a un mundo menos oxidado no resuelva ning\u00fan problema global de corrosi\u00f3n, pero protege las inversiones de nuestros clientes y garantiza la seguridad de los suyos prolongando la vida \u00fatil de las construcciones de acero exteriores de las atracciones e instalaciones que construimos.<\/p>\n[\/vc_column_text][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 15px; line-height: 1.8em;\">*\u00bbOxida la guerra m\u00e1s larga\u00bb por Jonathan Waldman<\/p>\n[\/vc_column_text][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 15px; line-height: 1.8em;\">FUENTES<br \/>\n\u00abCorrosion Protection\u00bb de ArcelorMittal Europe<br \/>\n\u00abCorrosion: Understanding the Basics\u00bb de ASM International<br \/>\n\u00abRust: The longest war\u00bb de Jonathan Waldman<br \/>\n\u00abThe Cost of Corrosion in China\u00bb de Baorong Hou, Instituto de Oceanolog\u00eda, Academia China de Ciencias, Qingdao, Shandong, China<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo. ","protected":false},"author":10,"featured_media":22712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936,935],"tags":[2591,2597],"class_list":["post-185832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","category-redaccion","tag-innovacion","tag-revestimiento-duplex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n | Walltopia<\/title>\n<meta name=\"description\" content=\"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T13:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n\",\"datePublished\":\"2021-06-22T13:51:26+00:00\",\"dateModified\":\"2026-01-15T14:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/\"},\"wordCount\":842,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"keywords\":[\"innovaci\u00f3n\",\"Revestimiento d\u00faplex\"],\"articleSection\":[\"Entretenimiento activo\",\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/\",\"name\":\"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"datePublished\":\"2021-06-22T13:51:26+00:00\",\"dateModified\":\"2026-01-15T14:30:39+00:00\",\"description\":\"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084201\\\/DuplexCoating.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n | Walltopia","description":"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/","og_locale":"es_ES","og_type":"article","og_title":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n","og_description":"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.","og_url":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-22T13:51:26+00:00","article_modified_time":"2026-01-15T14:30:39+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n","datePublished":"2021-06-22T13:51:26+00:00","dateModified":"2026-01-15T14:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/"},"wordCount":842,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","keywords":["innovaci\u00f3n","Revestimiento d\u00faplex"],"articleSection":["Entretenimiento activo","Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/","url":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/","name":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","datePublished":"2021-06-22T13:51:26+00:00","dateModified":"2026-01-15T14:30:39+00:00","description":"La corrosi\u00f3n afecta a la vida \u00fatil de los equipos, por lo que Walltopia utiliza zinc y pintura polim\u00e9rica para combatirla. Para saber c\u00f3mo, lee el art\u00edculo completo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084201\/DuplexCoating.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/revestimiento-duplex-walltopia-nuestra-solucion-contra-la-corrosion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Revestimiento d\u00faplex Walltopia: nuestra soluci\u00f3n contra la corrosi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/185832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=185832"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/185832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/22712"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=185832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=185832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=185832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}