{"id":185970,"date":"2021-06-22T16:33:43","date_gmt":"2021-06-22T13:33:43","guid":{"rendered":"https:\/\/walltopia.com\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/"},"modified":"2026-01-15T17:30:56","modified_gmt":"2026-01-15T14:30:56","slug":"la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/","title":{"rendered":"La sede de Walltopia en Bulgaria sufre un incendio provocado"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00bbEl 5 de julio de 2020, hacia las 3 de la noche, se produjo un intento de incendio en la sede central de Walltopia, empresa l\u00edder mundial en la fabricaci\u00f3n de roc\u00f3dromos y atracciones de ocio activo, situada en Sof\u00eda (Bulgaria).\u00bb font_container=\u00bbtag:h2|font_size:18|text_align:left|color:%23000000|line_height:1.5&#8243; use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Los culpables utilizaron l\u00edquido incendiario para prender fuego a una instalaci\u00f3n temporal de banderas con los colores del arco iris en la fachada del edificio de Walltopia.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">El crimen grabado por las c\u00e1maras de seguridad puede definirse sin duda como un incendio provocado. El motivo de los 4 atacantes est\u00e1 claro: el odio al movimiento del Orgullo, a los miembros de la comunidad LGBTQI y a sus simpatizantes frente a Walltopia. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">La bandera arco iris es un s\u00edmbolo de la sociedad LGBTQI, y con su instalaci\u00f3n anual en la fachada del edificio de Walltopia, la empresa expresa su solidaridad con las personas de distintas orientaciones sexuales e identidades de g\u00e9nero que viven con limitaciones de sus derechos.<\/p>\n[\/vc_column_text][vc_column_text css_animation=\u00bbfadeInUp\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Tanto en Bulgaria como en el resto del mundo, suelen ser objeto de discriminaci\u00f3n y agresiones f\u00edsicas y verbales, delitos inherentes al odio.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">En Walltopia creemos en el derecho de todo ser humano a ser quien es y defendemos firmemente su derecho a ser libre y feliz, independientemente de su sexo, orientaci\u00f3n sexual, raza u origen \u00e9tnico. Por eso vemos el delito cometido contra nosotros como un delito contra todos los que se identifican con los mismos valores. Mantenemos la esperanza de que los agentes de la ley encuentren a los autores y asuman la responsabilidad de sus actos.  <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00bbEl 5 de julio de 2020, hacia las 3 de la noche, se produjo un intento de incendio en&#8230;","protected":false},"author":10,"featured_media":22700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[935],"tags":[2625,2624],"class_list":["post-185970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaccion","tag-incendio-provocado","tag-sede-de-walltopia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La sede de Walltopia en Bulgaria sufre un incendio provocado | Walltopia<\/title>\n<meta name=\"description\" content=\"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sede de Walltopia en Bulgaria sufre un incendio provocado\" \/>\n<meta property=\"og:description\" content=\"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T13:33:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"La sede de Walltopia en Bulgaria sufre un incendio provocado\",\"datePublished\":\"2021-06-22T13:33:43+00:00\",\"dateModified\":\"2026-01-15T14:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/\"},\"wordCount\":325,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084210\\\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg\",\"keywords\":[\"incendio provocado\",\"sede de walltopia\"],\"articleSection\":[\"Redacci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/\",\"name\":\"La sede de Walltopia en Bulgaria sufre un incendio provocado | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084210\\\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg\",\"datePublished\":\"2021-06-22T13:33:43+00:00\",\"dateModified\":\"2026-01-15T14:30:56+00:00\",\"description\":\"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084210\\\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026084210\\\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg\",\"width\":900,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La sede de Walltopia en Bulgaria sufre un incendio provocado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La sede de Walltopia en Bulgaria sufre un incendio provocado | Walltopia","description":"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/","og_locale":"es_ES","og_type":"article","og_title":"La sede de Walltopia en Bulgaria sufre un incendio provocado","og_description":"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","og_url":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-22T13:33:43+00:00","article_modified_time":"2026-01-15T14:30:56+00:00","og_image":[{"width":900,"height":592,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"La sede de Walltopia en Bulgaria sufre un incendio provocado","datePublished":"2021-06-22T13:33:43+00:00","dateModified":"2026-01-15T14:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/"},"wordCount":325,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg","keywords":["incendio provocado","sede de walltopia"],"articleSection":["Redacci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/","url":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/","name":"La sede de Walltopia en Bulgaria sufre un incendio provocado | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg","datePublished":"2021-06-22T13:33:43+00:00","dateModified":"2026-01-15T14:30:56+00:00","description":"El fabricante de roc\u00f3dromos y equipos de ocio activo sufri\u00f3 un conato de incendio de la bandera con los colores del arco iris. Obtenga m\u00e1s informaci\u00f3n aqu\u00ed.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026084210\/4ff28a9823b64d31d17bd0411c6126bd_XL.jpg","width":900,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/la-sede-de-walltopia-en-bulgaria-sufre-un-incendio-provocado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"La sede de Walltopia en Bulgaria sufre un incendio provocado"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/185970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=185970"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/185970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/22700"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=185970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=185970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=185970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}