{"id":189783,"date":"2017-03-07T15:31:53","date_gmt":"2017-03-07T12:31:53","guid":{"rendered":"https:\/\/walltopia.com\/aventura-walltopia-en-sms-bangkok\/"},"modified":"2026-01-15T17:41:07","modified_gmt":"2026-01-15T14:41:07","slug":"aventura-walltopia-en-sms-bangkok","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/","title":{"rendered":"Aventura Walltopia en SMS Bangkok"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb][vc_column_text]\n<h4>Descubre c\u00f3mo el ocio activo cambia las reglas del juego de la industria minorista y del ocio.<\/h4>\n<p style=\"font-size:18px; line-height: 1.8em;\">Walltopia se unir\u00e1 a la 7\u00aa Cumbre Anual de Centros <a href=\"https:\/\/staging-3.walltopia.com\/industries\/shopping-malls\/\" target=\"_blank\" rel=\"noopener\">Comerciales<\/a> en Bangkok para compartir experiencias de primera mano sobre <a href=\"https:\/\/staging-3.walltopia.com\/\" target=\"_blank\" rel=\"noopener\">las tendencias del ocio activo<\/a> y los hitos que atraviesan los centros comerciales en su camino para convertirse en centros de destino.<\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Hemos visto que las experiencias bien dise\u00f1adas atraen a los visitantes, hacen que se queden m\u00e1s tiempo, gasten m\u00e1s y vuelvan de nuevo. Ven a escuchar a nuestro copropietario y Director General, el Sr. Ivaylo Penchev, predecir las tendencias futuras y revelar las lecciones aprendidas del pasado. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\"><strong>  \u00bfTema?<\/strong>  \u00abEl cambio de juego en el ocio minorista: Lo que hemos aprendido de m\u00e1s de 100 proyectos de ocio activo\u00bb<\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\"><strong>  \u00bfCu\u00e1ndo?<\/strong>  Mi\u00e9rcoles 29 de marzo a las 9:00<\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\"><strong>  \u00bfD\u00f3nde?  <\/strong>  Centara Grand y Centro de Convenciones de Bangkok en Centralworld<\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Si no puedes asistir a la presentaci\u00f3n, a\u00fan tienes la oportunidad de reunirte con nosotros en la zona de exposici\u00f3n.<\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Si prefieres aprovechar tu tiempo, no dejes que la fortuna decida si nos tropezamos. Reserva una cita en <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com.<\/a> <\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia participar\u00e1 en la 7\u00aa Cumbre Anual de Centros Comerciales de Bangkok para compartir experiencias de primera mano sobre las tendencias del ocio activo.","protected":false},"author":5,"featured_media":95418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936],"tags":[3323],"class_list":["post-189783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","tag-sms-bangkok"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aventura Walltopia en SMS Bangkok | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aventura Walltopia en SMS Bangkok\" \/>\n<meta property=\"og:description\" content=\"Walltopia participar\u00e1 en la 7\u00aa Cumbre Anual de Centros Comerciales de Bangkok para compartir experiencias de primera mano sobre las tendencias del ocio activo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-07T12:31:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Aventura Walltopia en SMS Bangkok\",\"datePublished\":\"2017-03-07T12:31:53+00:00\",\"dateModified\":\"2026-01-15T14:41:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145556\\\/Walltopia-SMS-Bangkok.jpg\",\"keywords\":[\"SMS Bangkok\"],\"articleSection\":[\"Entretenimiento activo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/\",\"name\":\"Aventura Walltopia en SMS Bangkok | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145556\\\/Walltopia-SMS-Bangkok.jpg\",\"datePublished\":\"2017-03-07T12:31:53+00:00\",\"dateModified\":\"2026-01-15T14:41:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145556\\\/Walltopia-SMS-Bangkok.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145556\\\/Walltopia-SMS-Bangkok.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-sms-bangkok\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aventura Walltopia en SMS Bangkok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aventura Walltopia en SMS Bangkok | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/","og_locale":"es_ES","og_type":"article","og_title":"Aventura Walltopia en SMS Bangkok","og_description":"Walltopia participar\u00e1 en la 7\u00aa Cumbre Anual de Centros Comerciales de Bangkok para compartir experiencias de primera mano sobre las tendencias del ocio activo.","og_url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-03-07T12:31:53+00:00","article_modified_time":"2026-01-15T14:41:07+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Aventura Walltopia en SMS Bangkok","datePublished":"2017-03-07T12:31:53+00:00","dateModified":"2026-01-15T14:41:07+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg","keywords":["SMS Bangkok"],"articleSection":["Entretenimiento activo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/","url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/","name":"Aventura Walltopia en SMS Bangkok | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg","datePublished":"2017-03-07T12:31:53+00:00","dateModified":"2026-01-15T14:41:07+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145556\/Walltopia-SMS-Bangkok.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-sms-bangkok\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Aventura Walltopia en SMS Bangkok"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/189783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=189783"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/189783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/95418"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=189783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=189783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=189783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}