{"id":191695,"date":"2018-04-03T08:51:10","date_gmt":"2018-04-03T05:51:10","guid":{"rendered":"https:\/\/walltopia.com\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/"},"modified":"2026-01-15T17:45:37","modified_gmt":"2026-01-15T14:45:37","slug":"salon-internacional-del-desarrollo-de-las-montanas-en-grenoble","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/","title":{"rendered":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia estar\u00e1 presente en la feria internacional de desarrollo de la monta\u00f1a, <a href=\"https:\/\/www.mountain-planet.com\/en\/\" target=\"_blank\" rel=\"noopener\">Mountain Planet<\/a>, para ayudar a las estaciones de monta\u00f1a y esqu\u00ed a redise\u00f1arse y convertirse en un destino para todas las estaciones.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Organizaremos una presentaci\u00f3n en la <b>Sala \u00c1gora<\/b> el <b>18 de abril a las 11.00 h<\/b> para contar a los visitantes m\u00e1s cosas sobre nuestra atracci\u00f3n para todo el a\u00f1o, el <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider<\/a>, y c\u00f3mo ha sido un \u00e9xito para nuestros clientes de todo el mundo.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Los visitantes tendr\u00e1n la oportunidad de conocer al equipo de expertos en ventas y desarrollo de productos de Walltopia en <b>el stand 766<\/b>, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n gracias a nuestra primera muestra de producto suspendido.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia estar\u00e1 presente en la feria internacional de desarrollo de la monta\u00f1a, Mountain Planet, para ayudar a las estaciones de monta\u00f1a y esqu\u00ed a redise\u00f1arse y convertirse en un destino para todas las estaciones.","protected":false},"author":5,"featured_media":95427,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936],"tags":[2631],"class_list":["post-191695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","tag-planeta-montana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble | Walltopia<\/title>\n<meta name=\"description\" content=\"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble\" \/>\n<meta property=\"og:description\" content=\"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-03T05:51:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:45:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble\",\"datePublished\":\"2018-04-03T05:51:10+00:00\",\"dateModified\":\"2026-01-15T14:45:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/\"},\"wordCount\":154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145547\\\/Walltopia-Mountain-Planet-2018.jpg\",\"keywords\":[\"Planeta Monta\u00f1a\"],\"articleSection\":[\"Entretenimiento activo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/\",\"name\":\"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145547\\\/Walltopia-Mountain-Planet-2018.jpg\",\"datePublished\":\"2018-04-03T05:51:10+00:00\",\"dateModified\":\"2026-01-15T14:45:37+00:00\",\"description\":\"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145547\\\/Walltopia-Mountain-Planet-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145547\\\/Walltopia-Mountain-Planet-2018.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble | Walltopia","description":"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/","og_locale":"es_ES","og_type":"article","og_title":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble","og_description":"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.","og_url":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2018-04-03T05:51:10+00:00","article_modified_time":"2026-01-15T14:45:37+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble","datePublished":"2018-04-03T05:51:10+00:00","dateModified":"2026-01-15T14:45:37+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/"},"wordCount":154,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg","keywords":["Planeta Monta\u00f1a"],"articleSection":["Entretenimiento activo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/","url":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/","name":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg","datePublished":"2018-04-03T05:51:10+00:00","dateModified":"2026-01-15T14:45:37+00:00","description":"Los visitantes tendr\u00e1n la oportunidad de conocer a nuestros expertos en Ventas y Desarrollo de Productos, donde tambi\u00e9n podr\u00e1n ver el Rollglider en acci\u00f3n.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145547\/Walltopia-Mountain-Planet-2018.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/salon-internacional-del-desarrollo-de-las-montanas-en-grenoble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Sal\u00f3n Internacional del Desarrollo de las Monta\u00f1as en Grenoble"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/191695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=191695"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/191695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/95427"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=191695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=191695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=191695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}