{"id":192666,"date":"2018-01-17T12:55:30","date_gmt":"2018-01-17T09:55:30","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-en-la-conferencia-anual-de-la-acct\/"},"modified":"2026-01-15T17:47:24","modified_gmt":"2026-01-15T14:47:24","slug":"walltopia-en-la-conferencia-anual-de-la-acct","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/","title":{"rendered":"Walltopia en la Conferencia Anual de la ACCT"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia ser\u00e1 expositor oficial en la Conferencia Anual de la ACCT por tercer a\u00f1o consecutivo. El evento tendr\u00e1 lugar en el <b>Centro de Convenciones <\/b> de <b>Fort Worth, Texas.<\/b> Los visitantes podr\u00e1n conocer mejor los <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\" target=\"_blank\" rel=\"noopener\">elementos de los circuitos de cuerdas<\/a> y los <a href=\"https:\/\/staging-3.walltopia.com\/products\/adventure-trail\/\" target=\"_blank\" rel=\"noopener\">recorridos a\u00e9reos<\/a> de Walltopia pas\u00e1ndose por <b>el stand 303<\/b> del <b>1 al 4 de febrero<\/b>. Nuestro equipo de expertos en recorridos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos m\u00e1s recientes en todo el mundo, as\u00ed como nuestras \u00faltimas innovaciones.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">\u00bfTe interesa concertar una reuni\u00f3n con uno de nuestros representantes durante la conferencia? Escr\u00edbenos a <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com.<\/a> <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">M\u00e1s informaci\u00f3n sobre <a href=\"https:\/\/staging-3.walltopia.com\/products\/\" target=\"_blank\" rel=\"noopener\">los productos de Walltopia<\/a> aqu\u00ed.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia ser\u00e1 expositor oficial en la Conferencia Anual de la ACCT por tercer a\u00f1o consecutivo.","protected":false},"author":5,"featured_media":95544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936],"tags":[1869],"class_list":["post-192666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","tag-acct"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia en la Conferencia Anual de la ACCT | Walltopia<\/title>\n<meta name=\"description\" content=\"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia en la Conferencia Anual de la ACCT\" \/>\n<meta property=\"og:description\" content=\"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-17T09:55:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia en la Conferencia Anual de la ACCT\",\"datePublished\":\"2018-01-17T09:55:30+00:00\",\"dateModified\":\"2026-01-15T14:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/\"},\"wordCount\":141,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145400\\\/Walltopia-ACCT-2018.jpg\",\"keywords\":[\"ACCT\"],\"articleSection\":[\"Entretenimiento activo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/\",\"name\":\"Walltopia en la Conferencia Anual de la ACCT | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145400\\\/Walltopia-ACCT-2018.jpg\",\"datePublished\":\"2018-01-17T09:55:30+00:00\",\"dateModified\":\"2026-01-15T14:47:24+00:00\",\"description\":\"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145400\\\/Walltopia-ACCT-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145400\\\/Walltopia-ACCT-2018.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/walltopia-en-la-conferencia-anual-de-la-acct\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia en la Conferencia Anual de la ACCT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia en la Conferencia Anual de la ACCT | Walltopia","description":"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/","og_locale":"es_ES","og_type":"article","og_title":"Walltopia en la Conferencia Anual de la ACCT","og_description":"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.","og_url":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2018-01-17T09:55:30+00:00","article_modified_time":"2026-01-15T14:47:24+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia en la Conferencia Anual de la ACCT","datePublished":"2018-01-17T09:55:30+00:00","dateModified":"2026-01-15T14:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/"},"wordCount":141,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg","keywords":["ACCT"],"articleSection":["Entretenimiento activo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/","url":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/","name":"Walltopia en la Conferencia Anual de la ACCT | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg","datePublished":"2018-01-17T09:55:30+00:00","dateModified":"2026-01-15T14:47:24+00:00","description":"Nuestro equipo de expertos en cursos a\u00e9reos estar\u00e1 all\u00ed para compartir detalles sobre nuestros proyectos e innovaciones m\u00e1s recientes. Escr\u00edbenos para concertar una reuni\u00f3n.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145400\/Walltopia-ACCT-2018.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/walltopia-en-la-conferencia-anual-de-la-acct\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Walltopia en la Conferencia Anual de la ACCT"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/192666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=192666"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/192666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/95544"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=192666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=192666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=192666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}