{"id":192791,"date":"2017-09-27T07:40:21","date_gmt":"2017-09-27T04:40:21","guid":{"rendered":"https:\/\/walltopia.com\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/"},"modified":"2026-01-15T17:47:49","modified_gmt":"2026-01-15T14:47:49","slug":"conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/","title":{"rendered":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Walltopia volver\u00e1 a exponer en la <a href=\"http:\/\/www.iaapa.org\/expos\/iaapa-attractions-expo\/home\" target=\"_blank\" rel=\"noopener\">IAAPA Attractions Expo<\/a> de <b>Orlando<\/b>, y este a\u00f1o tenemos un mont\u00f3n de novedades que compartir.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Uno de nuestros \u00faltimos productos, el <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider<\/a>, se est\u00e1 desarrollando r\u00e1pidamente. Tenemos en el mercado un nuevo sistema de transici\u00f3n de carritos (Elevador de Cadena Inclinada), que no s\u00f3lo disminuye el tiempo de espera de la atracci\u00f3n, sino que tambi\u00e9n reduce el n\u00famero de miembros del personal necesarios para las operaciones. El Elevador de Cadena Inclinada transporta a varios participantes simult\u00e1neamente, y permite engancharlos y desengancharlos de una misma plataforma.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">El <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\" target=\"_blank\" rel=\"noopener\">Rollglider<\/a> tiene un tercer sistema de transici\u00f3n muy pronto, tambi\u00e9n destinado a garantizar unas operaciones m\u00e1s fluidas, \u00a1y estamos deseando cont\u00e1rtelo todo en Orlando!<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Hablando de operaciones sin problemas, una de las filiales de Walltopia, <a href=\"https:\/\/safetyeng.eu\/\" target=\"_blank\" rel=\"noopener\">Safety Engineering<\/a>, ha lanzado un nuevo conector de escalada que aumenta la seguridad en los centros de escalada y aventura. El <a href=\"https:\/\/safetyeng.eu\/self-belay\/\" target=\"_blank\" rel=\"noopener\">Self Belay<\/a> permite a los usuarios escalar s\u00f3lo cuando est\u00e1n correctamente sujetos al dispositivo.  El conector no puede abrirse accidentalmente o a prop\u00f3sito durante la escalada: los usuarios s\u00f3lo pueden conectarse y desconectarse del dispositivo cuando est\u00e1n en el suelo. El <a href=\"https:\/\/safetyeng.eu\/self-belay\/\" target=\"_blank\" rel=\"noopener\">dispositivo de autoaseguramiento<\/a> no s\u00f3lo contribuye a la seguridad en la escalada, sino que tambi\u00e9n ayuda a reducir el n\u00famero de miembros del personal necesarios, dado que los participantes de tan s\u00f3lo 5 a\u00f1os pueden utilizar el dispositivo por s\u00ed mismos. Es un complemento perfecto para nuestros roc\u00f3dromos interactivos, <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\" target=\"_blank\" rel=\"noopener\">Fun Walls<\/a>. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">No queremos estropearlo todo, por eso te recomendamos que te pases por <b>el stand 654<\/b> para saber m\u00e1s. Concierta una reuni\u00f3n con antelaci\u00f3n poni\u00e9ndote en contacto con nosotros en <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com.<\/a> \u00a1Nos vemos en el <b>Centro de Convenciones del Condado de<\/b> Orange, <b>del 14 al 17 de noviembre de 2017<\/b>!  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Consulta el resto de nuestros productos <a href=\"https:\/\/staging-3.walltopia.com\/products\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia volver\u00e1 a exponer en la IAAPA Attractions Expo de Orlando, y este a\u00f1o tenemos un mont\u00f3n de novedades que compartir.","protected":false},"author":5,"featured_media":95526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936],"tags":[3905,3073,973,1036],"class_list":["post-192791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","tag-exposicion-de-atracciones","tag-exposicion-de-atracciones-iaapa","tag-iaapa-es","tag-planeador"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo | Walltopia<\/title>\n<meta name=\"description\" content=\"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo\" \/>\n<meta property=\"og:description\" content=\"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T04:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo\",\"datePublished\":\"2017-09-27T04:40:21+00:00\",\"dateModified\":\"2026-01-15T14:47:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145419\\\/Walltopia-IAAPA-Attractions-Expo-2017.jpg\",\"keywords\":[\"Exposici\u00f3n de atracciones\",\"Exposici\u00f3n de Atracciones IAAPA\",\"IAAPA\",\"Planeador\"],\"articleSection\":[\"Entretenimiento activo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/\",\"name\":\"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145419\\\/Walltopia-IAAPA-Attractions-Expo-2017.jpg\",\"datePublished\":\"2017-09-27T04:40:21+00:00\",\"dateModified\":\"2026-01-15T14:47:49+00:00\",\"description\":\"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145419\\\/Walltopia-IAAPA-Attractions-Expo-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145419\\\/Walltopia-IAAPA-Attractions-Expo-2017.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo | Walltopia","description":"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo","og_description":"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.","og_url":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-09-27T04:40:21+00:00","article_modified_time":"2026-01-15T14:47:49+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo","datePublished":"2017-09-27T04:40:21+00:00","dateModified":"2026-01-15T14:47:49+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg","keywords":["Exposici\u00f3n de atracciones","Exposici\u00f3n de Atracciones IAAPA","IAAPA","Planeador"],"articleSection":["Entretenimiento activo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/","url":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/","name":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg","datePublished":"2017-09-27T04:40:21+00:00","dateModified":"2026-01-15T14:47:49+00:00","description":"Rollglider se est\u00e1 desarrollando r\u00e1pidamente. Tenemos un nuevo sistema de transici\u00f3n de carros en el mercado. Lee el art\u00edculo para saber m\u00e1s.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145419\/Walltopia-IAAPA-Attractions-Expo-2017.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/conoce-las-ultimas-innovaciones-de-walltopia-en-la-iaapa-attractions-expo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Conoce las \u00faltimas innovaciones de Walltopia en la IAAPA Attractions Expo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/192791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=192791"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/192791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/95526"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=192791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=192791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=192791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}