{"id":193616,"date":"2017-05-12T13:16:01","date_gmt":"2017-05-12T10:16:01","guid":{"rendered":"https:\/\/walltopia.com\/aventura-walltopia-en-aae-singapur\/"},"modified":"2026-01-15T17:50:36","modified_gmt":"2026-01-15T14:50:36","slug":"aventura-walltopia-en-aae-singapur","status":"publish","type":"post","link":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/","title":{"rendered":"Aventura Walltopia en AAE Singapur"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00bbfadeInUp\u00bb][vc_column_text]\n<p style=\"font-size:18px; line-height: 1.8em;\">Walltopia Adventure es expositor oficial en la <a href=\"https:\/\/www.iaapa.org\/expos\/asian-attractions-expo\/home\" target=\"_blank\" rel=\"noopener\">Exposici\u00f3n de Atracciones Asi\u00e1ticas<\/a> de Singapur. Re\u00fanete con nosotros en <b>el stand L238<\/b> para descubrir nuevas y emocionantes formas de diversificar tu centro de entretenimiento. Queremos mostrarte lo que hemos hecho en Asia hasta ahora, y c\u00f3mo se puede conseguir en tu centro.  <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Sabemos que est\u00e1s ocupado, por eso te instamos a que conciertes una reuni\u00f3n con un miembro de nuestro equipo con antelaci\u00f3n. Ponte en contacto con nosotros en <a href=\"mailto:adventure@walltopia.com\">adventure@walltopia.com<\/a> y fijaremos una hora que se adapte a tu horario. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">El acto tendr\u00e1 lugar en <b>Marina Bay Sands<\/b> del <b>13 al 16 de junio<\/b>. \u00a1Esperamos verte all\u00ed! <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">M\u00e1s informaci\u00f3n sobre nuestros <a href=\"https:\/\/staging-3.walltopia.com\/products\/\" target=\"_blank\" rel=\"noopener\">productos de entretenimiento activo<\/a>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Walltopia Adventure es expositor oficial de la Exposici\u00f3n de Atracciones Asi\u00e1ticas de Singapur.","protected":false},"author":5,"featured_media":95445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[936],"tags":[4197],"class_list":["post-193616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento-activo","tag-exposicion-de-atracciones-asiaticas-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aventura Walltopia en AAE Singapur | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aventura Walltopia en AAE Singapur\" \/>\n<meta property=\"og:description\" content=\"Walltopia Adventure es expositor oficial de la Exposici\u00f3n de Atracciones Asi\u00e1ticas de Singapur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-12T10:16:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Aventura Walltopia en AAE Singapur\",\"datePublished\":\"2017-05-12T10:16:01+00:00\",\"dateModified\":\"2026-01-15T14:50:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145531\\\/Walltopia-Asian-Attractions-Expo.jpg\",\"keywords\":[\"Exposici\u00f3n de Atracciones Asi\u00e1ticas\"],\"articleSection\":[\"Entretenimiento activo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/\",\"name\":\"Aventura Walltopia en AAE Singapur | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145531\\\/Walltopia-Asian-Attractions-Expo.jpg\",\"datePublished\":\"2017-05-12T10:16:01+00:00\",\"dateModified\":\"2026-01-15T14:50:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145531\\\/Walltopia-Asian-Attractions-Expo.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145531\\\/Walltopia-Asian-Attractions-Expo.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/aventura-walltopia-en-aae-singapur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aventura Walltopia en AAE Singapur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aventura Walltopia en AAE Singapur | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/","og_locale":"es_ES","og_type":"article","og_title":"Aventura Walltopia en AAE Singapur","og_description":"Walltopia Adventure es expositor oficial de la Exposici\u00f3n de Atracciones Asi\u00e1ticas de Singapur.","og_url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-05-12T10:16:01+00:00","article_modified_time":"2026-01-15T14:50:36+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Aventura Walltopia en AAE Singapur","datePublished":"2017-05-12T10:16:01+00:00","dateModified":"2026-01-15T14:50:36+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg","keywords":["Exposici\u00f3n de Atracciones Asi\u00e1ticas"],"articleSection":["Entretenimiento activo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/","url":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/","name":"Aventura Walltopia en AAE Singapur | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg","datePublished":"2017-05-12T10:16:01+00:00","dateModified":"2026-01-15T14:50:36+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145531\/Walltopia-Asian-Attractions-Expo.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/aventura-walltopia-en-aae-singapur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Aventura Walltopia en AAE Singapur"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/es\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/193616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/comments?post=193616"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/posts\/193616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/95445"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=193616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/categories?post=193616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/tags?post=193616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}