{"id":204889,"date":"2025-02-13T11:52:52","date_gmt":"2025-02-13T08:52:52","guid":{"rendered":"https:\/\/walltopia.com\/products\/sin categor\u00eda\/cubbies-banco-180\/"},"modified":"2025-02-13T11:52:52","modified_gmt":"2025-02-13T08:52:52","slug":"cubbies-banco-180","status":"publish","type":"product","link":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/","title":{"rendered":"Cubbies Banco 180"},"content":{"rendered":"<p><strong>Los bancos Cubby<\/strong> de Walltopia combinan asientos duraderos de madera contrachapada con almacenamiento integrado, ofreciendo a los escaladores una soluci\u00f3n pr\u00e1ctica que ahorra espacio para descansar y organizar el equipo. Disponible en tama\u00f1os de <strong>120 cm<\/strong> y <strong>180 cm<\/strong>, el banco de 120 cm dispone de dos cub\u00edculos, mientras que el de 180 cm ofrece tres. Puedes encontrar el de 120 cm <a href=\"https:\/\/store.walltopia.com\/?post_type=product&amp;p=5259&amp;preview=true\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.  <\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<ul>\n<li>Longitud: 180 cm<\/li>\n<li>Anchura: 40 cm<\/li>\n<li>Altura: 40 cm<\/li>\n<\/ul>\n<p><strong>Caracter\u00edsticas<\/strong><\/p>\n<ul>\n<li><strong>Almacenamiento integrado<\/strong>: Los cubos integrados proporcionan un espacio pr\u00e1ctico para que los escaladores guarden zapatos, bolsas de tiza u objetos personales.<\/li>\n<li><strong>Materiales duraderos<\/strong>: Fabricado con madera contrachapada de alta calidad para un uso duradero en entornos muy transitados.<\/li>\n<li><strong>Acabados<\/strong>: Disponibles en acabados de primera calidad, como <strong>Barniz Transparente<\/strong>, <strong>Nogal Te\u00f1ido<\/strong>, <strong>Pintura Grafito<\/strong> y <strong>Chapa de Piedra Natural<\/strong>, que garantizan un aspecto pulido a juego con el interior de tu gimnasio.<\/li>\n<\/ul>\n<p><strong>Recomendaciones de colocaci\u00f3n<\/strong><br \/>\nColoca los bancos Cubby en zonas de espera, vestuarios o zonas de escalada para crear espacios organizados y funcionales. Ideales para mantener las zonas de escalada despejadas y proporcionar al mismo tiempo asientos c\u00f3modos. <\/p>\n<p><strong>Env\u00edo y montaje<\/strong><\/p>\n<ul>\n<li>Se env\u00eda premontado para su uso inmediato.<\/li>\n<\/ul>\n<p><strong>Opciones adicionales<\/strong><br \/>\nCombina los bancos Cubby con otros muebles de gimnasio de escalada Walltopia, como las plataformas Cubby o los bancos de espuma de vinilo, para crear un entorno de gimnasio cohesivo y acogedor que favorezca tanto la comodidad como la organizaci\u00f3n del escalador.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"flex flex-col items-start\">\n<div class=\"flex items-center text-xs rounded p-3 text-gray-900 bg-gray-100\">\n<div>\n<div class=\"flex items-center gap-3\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"657a2499-85b3-44fc-80ac-df77e319da55\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n\n&nbsp;\n\n<\/div>\n<\/div>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[5478],"product_tag":[],"class_list":["post-204889","product","type-product","status-publish","product_cat-muebles-para-gimnasios-de-escalada","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cubbies Banco 180 | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cubbies Banco 180\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213115346\/walltopia_climbing-gym-furniture_cubbies-bench_180.1-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/muebles-para-gimnasios-de-escalada\\\/cubbies-banco-180\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/muebles-para-gimnasios-de-escalada\\\/cubbies-banco-180\\\/\",\"name\":\"Cubbies Banco 180 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"datePublished\":\"2025-02-13T08:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/muebles-para-gimnasios-de-escalada\\\/cubbies-banco-180\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/muebles-para-gimnasios-de-escalada\\\/cubbies-banco-180\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/muebles-para-gimnasios-de-escalada\\\/cubbies-banco-180\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cubbies Banco 180\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cubbies Banco 180 | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/","og_locale":"es_ES","og_type":"article","og_title":"Cubbies Banco 180","og_description":"&nbsp;","og_url":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1200,"height":900,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250213115346\/walltopia_climbing-gym-furniture_cubbies-bench_180.1-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/","url":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/","name":"Cubbies Banco 180 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"datePublished":"2025-02-13T08:52:52+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/product\/muebles-para-gimnasios-de-escalada\/cubbies-banco-180\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/walltopia.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Cubbies Banco 180"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/204889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/204889\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=204889"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_brand?post=204889"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat?post=204889"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_tag?post=204889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}