{"id":206435,"date":"2025-02-17T12:13:56","date_gmt":"2025-02-17T09:13:56","guid":{"rendered":"https:\/\/walltopia.com\/products\/sin categor\u00eda\/pulpo\/"},"modified":"2025-02-17T12:13:56","modified_gmt":"2025-02-17T09:13:56","slug":"pulpo","status":"publish","type":"product","link":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/","title":{"rendered":"Pulpo"},"content":{"rendered":"<p>*Las rutas est\u00e1n predeterminadas y tienen un tercer nivel de dificultad<\/p>\n<p><strong>Especificaciones t\u00e9cnicas:<\/strong><\/p>\n<h4>Tipo de estructura<\/h4>\n<p>Octopus viene con nuestra estructura de acero autoportante est\u00e1ndar, que debe anclarse al suelo. La estructura para exteriores viene galvanizada en caliente, lo que garantiza su durabilidad y resistencia a las condiciones meteorol\u00f3gicas de todo el mundo. <\/p>\n<h4>Anclaje<\/h4>\n<p>Necesitas anclar tres placas de acero de base, cada una con cuatro anclajes en la parte inferior. La estructura debe anclarse en una losa de hormig\u00f3n maciza con un grosor m\u00ednimo de 15 cm. Para asegurarte de que tu suelo puede soportar el Octopus <strong>, adjunta los c\u00e1lculos est\u00e1ticos de las cargas<\/strong> <em>Archivo de Cargas Est\u00e1ndar Walltopia<\/em> <strong>en la secci\u00f3n de descargas y consulta siempre con tu ingeniero o un profesional cualificado.<\/strong>  <\/p>\n<h4>Colocaci\u00f3n<\/h4>\n<p>El Pulpo debe colocarse lejos de objetos duros, como columnas de edificios, barandillas, muebles u otros. Las dimensiones de la zona de seguridad se definen en las im\u00e1genes del producto. Esta es la zona que es obligatorio mantener alejada de cualquier obst\u00e1culo  <\/p>\n<h4>Suelos<\/h4>\n<p>Recomendamos encarecidamente instalar suelo de seguridad en la zona de seguridad alrededor de cada roc\u00f3dromo. Puedes comprar Alfombra de Pared de Cuerda de 15 cm de grosor con acabado de moqueta gris o Suelo de Seguridad Una Vida M\u00e1s en Walltopia o instalar otro tipo de suelo amortiguador. <\/p>\n<h4>Productos adicionales<\/h4>\n<p>\u00a1Este producto no puede utilizarse sin un sistema de auto-retardo!<\/p>\n<p>Nuestras estructuras Fun Walls son compatibles con el dispositivo de autoaseguramiento Tru Blue de Headrush y el dispositivo de autoaseguramiento Perfect Descend<\/p>\n<p>No olvides consultar aqu\u00ed nuestros accesorios de seguridad. Las Puertas de Seguridad facilitan el manejo y mitigan el riesgo de escalada no asegurada. Las cintas de autoaseguramiento se fijan a ellas cuando nadie est\u00e1 escalando. Las cintas de autoaseguramiento se fijan a ellas cuando nadie est\u00e1 escalando.   <\/p>\n<p>Elige instalar nuestra Puerta Inteligente y reduce al m\u00ednimo el riesgo de incidentes. Tambi\u00e9n recomendamos nuestro sistema de autoaseguramiento, que no s\u00f3lo contribuye a la seguridad en la escalada, sino que tambi\u00e9n ayuda en las operaciones al reducir el n\u00famero de miembros del personal necesarios: \u00a1los participantes de tan s\u00f3lo 5 a\u00f1os pueden utilizar el dispositivo por s\u00ed solos, sin supervisi\u00f3n! <\/p>\n<h4>Opciones de env\u00edo<\/h4>\n<p>Este producto se enviar\u00e1 en grandes piezas premontadas que requerir\u00e1n montaje en el momento de la entrega. Todos los componentes est\u00e1n dise\u00f1ados para facilitar el montaje. Se proporcionan instrucciones detalladas para garantizar que el producto final funcione con seguridad y tenga un aspecto y un acabado excelentes.  <\/p>\n<h4>Maquinaria necesaria para el montaje<\/h4>\n<p>Lista de herramientas: Destornillador de impacto, Taladradora, Amoladora angular, Pistola de impacto &#8211; vasos 17\/ 19, Sierra de calar, Llaves manuales &#8211; 13 \/ 17 \/ 19 \/ 24, Pilares, Cintas m\u00e9tricas<\/p>\n<p>Maquinaria: Elevador de tijera capaz de levantar 260 kg hasta 8 metros, Carretilla elevadora de 2T &#8211; para la descarga, Transpaleta<\/p>\n","protected":false},"excerpt":{"rendered":"El Octopus Fun Wall destaca por su exclusivo dise\u00f1o inspirado en los tent\u00e1culos, que ofrece una experiencia de escalada envolvente tanto para interiores como para exteriores. Este cautivador dise\u00f1o no s\u00f3lo sirve como centro visual, sino que tambi\u00e9n proporciona variadas rutas de escalada y desaf\u00edos, adecuados para escaladores de todos los niveles de habilidad. ","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6858],"product_tag":[],"class_list":["post-206435","product","type-product","status-publish","product_cat-paredes-divertidas-en-3d","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pulpo | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pulpo\" \/>\n<meta property=\"og:description\" content=\"El Octopus Fun Wall destaca por su exclusivo dise\u00f1o inspirado en los tent\u00e1culos, que ofrece una experiencia de escalada envolvente tanto para interiores como para exteriores. Este cautivador dise\u00f1o no s\u00f3lo sirve como centro visual, sino que tambi\u00e9n proporciona variadas rutas de escalada y desaf\u00edos, adecuados para escaladores de todos los niveles de habilidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217121537\/FW_octopus_8m_cam2_for_woocommerce_catalog-1-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/paredes-divertidas-en-3d\\\/pulpo\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/paredes-divertidas-en-3d\\\/pulpo\\\/\",\"name\":\"Pulpo | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"datePublished\":\"2025-02-17T09:13:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/paredes-divertidas-en-3d\\\/pulpo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/paredes-divertidas-en-3d\\\/pulpo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/paredes-divertidas-en-3d\\\/pulpo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pulpo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pulpo | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/","og_locale":"es_ES","og_type":"article","og_title":"Pulpo","og_description":"El Octopus Fun Wall destaca por su exclusivo dise\u00f1o inspirado en los tent\u00e1culos, que ofrece una experiencia de escalada envolvente tanto para interiores como para exteriores. Este cautivador dise\u00f1o no s\u00f3lo sirve como centro visual, sino que tambi\u00e9n proporciona variadas rutas de escalada y desaf\u00edos, adecuados para escaladores de todos los niveles de habilidad.","og_url":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":526,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250217121537\/FW_octopus_8m_cam2_for_woocommerce_catalog-1-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/","url":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/","name":"Pulpo | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"datePublished":"2025-02-17T09:13:56+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/product\/paredes-divertidas-en-3d\/pulpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/walltopia.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Pulpo"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/206435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/206435\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=206435"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_brand?post=206435"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat?post=206435"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_tag?post=206435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}