{"id":207133,"date":"2025-02-18T11:21:11","date_gmt":"2025-02-18T08:21:11","guid":{"rendered":"https:\/\/walltopia.com\/products\/sin categor\u00eda\/modulo-caterpillar-para-caterpillar-traverse\/"},"modified":"2025-02-18T11:21:11","modified_gmt":"2025-02-18T08:21:11","slug":"modulo-caterpillar-para-caterpillar-traverse","status":"publish","type":"product","link":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/","title":{"rendered":"M\u00f3dulo Caterpillar para Caterpillar Traverse"},"content":{"rendered":"<p>Los \u0422raverse Walls son una versi\u00f3n compacta de algunos de nuestros elementos est\u00e1ndar. Ofrecen escalada sin arneses a alturas de hasta 2,5 m y son perfectas para aprovechar el espacio de techos bajos dentro de una instalaci\u00f3n. Aunque no se necesitan cuerdas ni arneses, la seguridad del escalador est\u00e1 garantizada por un suelo amortiguador que proporciona un aterrizaje suave en caso de ca\u00edda o salto.  <\/p>\n<p>El Muro de Diversi\u00f3n <strong>Oruga<\/strong> est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido. Sus vibrantes segmentos y su simp\u00e1tica cara invitan a la interacci\u00f3n y lo hacen perfectamente adecuado para los j\u00f3venes aventureros, ofreci\u00e9ndoles una introducci\u00f3n a la escalada que es a la vez divertida y estimulante. <\/p>\n","protected":false},"excerpt":{"rendered":"Los \u0422raverse Walls son una versi\u00f3n compacta de algunos de nuestros elementos est\u00e1ndar. Ofrecen escalada sin arneses a alturas de&#8230;","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[6976],"product_tag":[],"class_list":["post-207133","product","type-product","status-publish","product_cat-atraviesa-paredes-divertidas","first","onbackorder","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>M\u00f3dulo Caterpillar para Caterpillar Traverse | Walltopia<\/title>\n<meta name=\"description\" content=\"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f3dulo Caterpillar para Caterpillar Traverse\" \/>\n<meta property=\"og:description\" content=\"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250218112401\/walltopia-fun-walls-traverse-caterpillar-scaled-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/atraviesa-paredes-divertidas\\\/modulo-caterpillar-para-caterpillar-traverse\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/atraviesa-paredes-divertidas\\\/modulo-caterpillar-para-caterpillar-traverse\\\/\",\"name\":\"M\u00f3dulo Caterpillar para Caterpillar Traverse | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"datePublished\":\"2025-02-18T08:21:11+00:00\",\"description\":\"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/atraviesa-paredes-divertidas\\\/modulo-caterpillar-para-caterpillar-traverse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/atraviesa-paredes-divertidas\\\/modulo-caterpillar-para-caterpillar-traverse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/atraviesa-paredes-divertidas\\\/modulo-caterpillar-para-caterpillar-traverse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00f3dulo Caterpillar para Caterpillar Traverse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00f3dulo Caterpillar para Caterpillar Traverse | Walltopia","description":"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00f3dulo Caterpillar para Caterpillar Traverse","og_description":"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.","og_url":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250218112401\/walltopia-fun-walls-traverse-caterpillar-scaled-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/","url":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/","name":"M\u00f3dulo Caterpillar para Caterpillar Traverse | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"datePublished":"2025-02-18T08:21:11+00:00","description":"El Muro de Diversi\u00f3n Oruga est\u00e1 dise\u00f1ado para inspirar y atraer a los j\u00f3venes escaladores con su aspecto juguet\u00f3n y colorido.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/product\/atraviesa-paredes-divertidas\/modulo-caterpillar-para-caterpillar-traverse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/walltopia.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"M\u00f3dulo Caterpillar para Caterpillar Traverse"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/207133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/207133\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=207133"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_brand?post=207133"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat?post=207133"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_tag?post=207133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}