{"id":215306,"date":"2025-02-20T11:55:16","date_gmt":"2025-02-20T08:55:16","guid":{"rendered":"https:\/\/walltopia.com\/products\/sin%20categor\u00eda\/chimenea-reflectante\/"},"modified":"2026-01-15T22:59:19","modified_gmt":"2026-01-15T19:59:19","slug":"chimenea-reflectante","status":"publish","type":"product","link":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/","title":{"rendered":"Chimenea reflectante"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico presenta presas de escalada espejadas que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo. Los variados tama\u00f1os y texturas de estas presas espejadas fomentan la exploraci\u00f3n y la resoluci\u00f3n de problemas, mientras que la forma de chimenea crea una experiencia de escalada divertida y centrada en el desarrollo de las habilidades motoras y la coordinaci\u00f3n.  ","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7854],"product_tag":[],"class_list":["post-215306","product","type-product","status-publish","product_cat-diversion-variada-paredes","first","onbackorder","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chimenea reflectante | Walltopia<\/title>\n<meta name=\"description\" content=\"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chimenea reflectante\" \/>\n<meta property=\"og:description\" content=\"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T19:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250220115537\/FW_reflective_chimney_8m_cam2_for_woocommerce_catalog-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/diversion-variada-paredes\\\/chimenea-reflectante\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/diversion-variada-paredes\\\/chimenea-reflectante\\\/\",\"name\":\"Chimenea reflectante | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"datePublished\":\"2025-02-20T08:55:16+00:00\",\"dateModified\":\"2026-01-15T19:59:19+00:00\",\"description\":\"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/diversion-variada-paredes\\\/chimenea-reflectante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/diversion-variada-paredes\\\/chimenea-reflectante\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/diversion-variada-paredes\\\/chimenea-reflectante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chimenea reflectante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chimenea reflectante | Walltopia","description":"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/","og_locale":"es_ES","og_type":"article","og_title":"Chimenea reflectante","og_description":"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.","og_url":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-15T19:59:19+00:00","og_image":[{"width":526,"height":1200,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250220115537\/FW_reflective_chimney_8m_cam2_for_woocommerce_catalog-1-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/","url":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/","name":"Chimenea reflectante | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"datePublished":"2025-02-20T08:55:16+00:00","dateModified":"2026-01-15T19:59:19+00:00","description":"\u00a1Despierta la curiosidad y desaf\u00eda a los peque\u00f1os escaladores con el roc\u00f3dromo Chimenea reflectante! Su dise\u00f1o \u00fanico incluye agarres de escalada espejados que distorsionan y retuercen los reflejos de los escaladores, a\u00f1adiendo un elemento l\u00fadico e interactivo.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/product\/diversion-variada-paredes\/chimenea-reflectante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/walltopia.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Chimenea reflectante"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/215306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/215306\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=215306"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_brand?post=215306"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat?post=215306"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_tag?post=215306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}