{"id":220278,"date":"2025-10-07T11:50:08","date_gmt":"2025-10-07T08:50:08","guid":{"rendered":"https:\/\/walltopia.com\/products\/sin%20categor\u00eda\/subida-a-las-nubes-hex\/"},"modified":"2026-01-22T14:30:37","modified_gmt":"2026-01-22T11:30:37","slug":"subida-a-las-nubes-hex","status":"publish","type":"product","link":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/","title":{"rendered":"Subida a las nubes Hex"},"content":{"rendered":"<p>Este producto est\u00e1 disponible en las siguientes combinaciones de colores:<\/p>\n<h4>Bayas<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-107-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">107 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-1375-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1375 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-231-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">231 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-7425-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7425 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-7659-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7659 C<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h4>Cal<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-394-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">394 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-2297-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">2297 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-580-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">580 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-317-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">317 C<\/div>\n<\/div>\n<\/div>\n<div class=\"pantone-card p-7465-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7465 C<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Con plataformas en forma de hex\u00e1gono, el modelo Hex aporta una est\u00e9tica moderna y geom\u00e9trica que puede combinarse perfectamente con entornos arquitect\u00f3nicos o tem\u00e1ticos. El camino de escalada fluye a trav\u00e9s de un ritmo l\u00fadico de subidas y bajadas, ofreciendo una experiencia de movimiento variada mientras los ni\u00f1os suben, bajan y vuelven a subir. Visualmente distintivo y atractivo en movimiento, Hex es tanto un elemento de dise\u00f1o como un viaje de juego activo.  ","protected":false},"featured_media":172737,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7906],"product_tag":[],"class_list":["post-220278","product","type-product","status-publish","has-post-thumbnail","product_cat-subida-a-las-nubes","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Subida a las nubes Hex | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subida a las nubes Hex\" \/>\n<meta property=\"og:description\" content=\"Con plataformas en forma de hex\u00e1gono, el modelo Hex aporta una est\u00e9tica moderna y geom\u00e9trica que puede combinarse perfectamente con entornos arquitect\u00f3nicos o tem\u00e1ticos. El camino de escalada fluye a trav\u00e9s de un ritmo l\u00fadico de subidas y bajadas, ofreciendo una experiencia de movimiento variada mientras los ni\u00f1os suben, bajan y vuelven a subir. Visualmente distintivo y atractivo en movimiento, Hex es tanto un elemento de dise\u00f1o como un viaje de juego activo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002172518\/cloud-climb-hex-berry-01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/\",\"name\":\"Subida a las nubes Hex | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002172518\\\/cloud-climb-hex-berry-01-1.jpg\",\"datePublished\":\"2025-10-07T08:50:08+00:00\",\"dateModified\":\"2026-01-22T11:30:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002172518\\\/cloud-climb-hex-berry-01-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002172518\\\/cloud-climb-hex-berry-01-1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/product\\\/subida-a-las-nubes\\\/subida-a-las-nubes-hex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Subida a las nubes Hex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Subida a las nubes Hex | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/","og_locale":"es_ES","og_type":"article","og_title":"Subida a las nubes Hex","og_description":"Con plataformas en forma de hex\u00e1gono, el modelo Hex aporta una est\u00e9tica moderna y geom\u00e9trica que puede combinarse perfectamente con entornos arquitect\u00f3nicos o tem\u00e1ticos. El camino de escalada fluye a trav\u00e9s de un ritmo l\u00fadico de subidas y bajadas, ofreciendo una experiencia de movimiento variada mientras los ni\u00f1os suben, bajan y vuelven a subir. Visualmente distintivo y atractivo en movimiento, Hex es tanto un elemento de dise\u00f1o como un viaje de juego activo.","og_url":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-22T11:30:37+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002172518\/cloud-climb-hex-berry-01-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/","url":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/","name":"Subida a las nubes Hex | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002172518\/cloud-climb-hex-berry-01-1.jpg","datePublished":"2025-10-07T08:50:08+00:00","dateModified":"2026-01-22T11:30:37+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002172518\/cloud-climb-hex-berry-01-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002172518\/cloud-climb-hex-berry-01-1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/product\/subida-a-las-nubes\/subida-a-las-nubes-hex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/walltopia.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Subida a las nubes Hex"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/220278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product\/220278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/172737"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=220278"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_brand?post=220278"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat?post=220278"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_tag?post=220278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}