{"id":6858,"count":10,"description":"Las paredes 3D de Walltopia llevan la escalada al siguiente nivel. Con elementos interactivos como luces LED, presas m\u00f3viles, temporizadores, mandos y botones, \u00a1cada una de estas paredes premium ofrece una dosis extra de emoci\u00f3n! ","link":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/","name":"Paredes divertidas en 3D","slug":"paredes-divertidas-en-3d","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Paredes divertidas en 3D | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paredes divertidas en 3D Archives\" \/>\n<meta property=\"og:description\" content=\"Las paredes 3D de Walltopia llevan la escalada al siguiente nivel. Con elementos interactivos como luces LED, presas m\u00f3viles, temporizadores, mandos y botones, \u00a1cada una de estas paredes premium ofrece una dosis extra de emoci\u00f3n!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/categoria-producto\\\/paredes-divertidas-en-3d\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/categoria-producto\\\/paredes-divertidas-en-3d\\\/\",\"name\":\"Paredes divertidas en 3D | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/categoria-producto\\\/paredes-divertidas-en-3d\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/categoria-producto\\\/paredes-divertidas-en-3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paredes divertidas en 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paredes divertidas en 3D | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/","og_locale":"es_ES","og_type":"article","og_title":"Paredes divertidas en 3D Archives","og_description":"Las paredes 3D de Walltopia llevan la escalada al siguiente nivel. Con elementos interactivos como luces LED, presas m\u00f3viles, temporizadores, mandos y botones, \u00a1cada una de estas paredes premium ofrece una dosis extra de emoci\u00f3n!","og_url":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/","og_site_name":"Walltopia","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/","url":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/","name":"Paredes divertidas en 3D | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/categoria-producto\/paredes-divertidas-en-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Paredes divertidas en 3D"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat\/6858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/product?product_cat=6858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}