{"id":151817,"date":"2024-12-10T18:21:30","date_gmt":"2024-12-10T15:21:30","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=151817"},"modified":"2025-03-04T17:40:43","modified_gmt":"2025-03-04T14:40:43","slug":"lets-climb","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/","title":{"rendered":"Let&#8217;s Climb"},"content":{"rendered":"<p>Let&#8217;s Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. To upscale the layout desicn, we made a two-storey mezzanine bouldering to best utilize the space available. Natural wood and solid white climbing wall panels create a cosy atmosphere and a creative canvas for the route setting.<\/p>\n<p><iframe loading=\"lazy\" title=\"Happy Walltopia client from Let&#039;s Climb - Beijing, China\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/oolbj4gyhuI?feature=oembed&#038;enablejsapi=1&#038;origin=http:\/\/walltopia.com\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"featured_media":160752,"template":"","wt_project_category":[761],"class_list":["post-151817","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Let&#039;s Climb | Walltopia<\/title>\n<meta name=\"description\" content=\"Let&#039;s Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Let&#039;s Climb\" \/>\n<meta property=\"og:description\" content=\"Let&#039;s Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T14:40:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250304173856\/Lets-Climb-Beijing-China-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/\",\"name\":\"Let's Climb | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250304173856\\\/Lets-Climb-Beijing-China-2-scaled.jpg\",\"datePublished\":\"2024-12-10T15:21:30+00:00\",\"dateModified\":\"2025-03-04T14:40:43+00:00\",\"description\":\"Let's Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250304173856\\\/Lets-Climb-Beijing-China-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250304173856\\\/Lets-Climb-Beijing-China-2-scaled.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Walltopia boulder climbing walls in Let's Climb, Beijing, China\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/lets-climb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Let&#8217;s Climb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Let's Climb | Walltopia","description":"Let's Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/","og_locale":"es_ES","og_type":"article","og_title":"Let's Climb","og_description":"Let's Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.","og_url":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2025-03-04T14:40:43+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250304173856\/Lets-Climb-Beijing-China-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/","url":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/","name":"Let's Climb | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250304173856\/Lets-Climb-Beijing-China-2-scaled.jpg","datePublished":"2024-12-10T15:21:30+00:00","dateModified":"2025-03-04T14:40:43+00:00","description":"Let's Climb is a boulder climbing gym in Beijing, China featuring about 400 sqm climbing surface. We made a two-storey mezzanine bouldering.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250304173856\/Lets-Climb-Beijing-China-2-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250304173856\/Lets-Climb-Beijing-China-2-scaled.jpg","width":1200,"height":800,"caption":"Walltopia boulder climbing walls in Let's Climb, Beijing, China"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/proyectos\/lets-climb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/walltopia.com\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Let&#8217;s Climb"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project\/151817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/160752"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=151817"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project_category?post=151817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}