{"id":16737,"date":"2021-07-09T11:14:11","date_gmt":"2021-07-09T08:14:11","guid":{"rendered":"https:\/\/dev-three.agmastudio.com\/?post_type=wt_project&#038;p=16737"},"modified":"2024-02-26T09:52:57","modified_gmt":"2024-02-26T06:52:57","slug":"high-point-chattannooga","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/","title":{"rendered":"High Point Chattanooga"},"content":{"rendered":"","protected":false},"featured_media":16738,"template":"","wt_project_category":[761],"class_list":["post-16737","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>High Point Chattannooga - Projects | Walltopia Climbing Walls<\/title>\n<meta name=\"description\" content=\"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High Point Chattanooga\" \/>\n<meta property=\"og:description\" content=\"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-26T06:52:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030092956\/176A0719-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/\",\"name\":\"High Point Chattannooga - Projects | Walltopia Climbing Walls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030092956\\\/176A0719-1.jpg\",\"datePublished\":\"2021-07-09T08:14:11+00:00\",\"dateModified\":\"2024-02-26T06:52:57+00:00\",\"description\":\"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030092956\\\/176A0719-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030092956\\\/176A0719-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/high-point-chattannooga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"High Point Chattanooga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"High Point Chattannooga - Projects | Walltopia Climbing Walls","description":"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/","og_locale":"es_ES","og_type":"article","og_title":"High Point Chattanooga","og_description":"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.","og_url":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2024-02-26T06:52:57+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030092956\/176A0719-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/","url":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/","name":"High Point Chattannooga - Projects | Walltopia Climbing Walls","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030092956\/176A0719-1.jpg","datePublished":"2021-07-09T08:14:11+00:00","dateModified":"2024-02-26T06:52:57+00:00","description":"High Point Chattanooga is a Full-Service Climbing Gym with Rope Walls, Boulder Walls and Kids Climbing Walls in Chattanooga, TN, USA.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030092956\/176A0719-1.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030092956\/176A0719-1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/proyectos\/high-point-chattannooga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/walltopia.com\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"High Point Chattanooga"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project\/16737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/16738"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=16737"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project_category?post=16737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}