{"id":69045,"date":"2023-01-08T11:32:43","date_gmt":"2023-01-08T08:32:43","guid":{"rendered":"http:\/\/walltopia.com\/projects\/harrowall\/"},"modified":"2023-05-22T13:41:37","modified_gmt":"2023-05-22T10:41:37","slug":"harrowall","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/","title":{"rendered":"HarroWall"},"content":{"rendered":"","protected":false},"featured_media":69046,"template":"","wt_project_category":[760],"class_list":["post-69045","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HarroWall | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HarroWall\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T10:41:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204700\/walltopia-HarroWall-Indoor-Cave-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/\",\"name\":\"HarroWall | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204700\\\/walltopia-HarroWall-Indoor-Cave-header.jpg\",\"datePublished\":\"2023-01-08T08:32:43+00:00\",\"dateModified\":\"2023-05-22T10:41:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204700\\\/walltopia-HarroWall-Indoor-Cave-header.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027204700\\\/walltopia-HarroWall-Indoor-Cave-header.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/harrowall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HarroWall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HarroWall | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/","og_locale":"es_ES","og_type":"article","og_title":"HarroWall","og_url":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-22T10:41:37+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204700\/walltopia-HarroWall-Indoor-Cave-header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/","url":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/","name":"HarroWall | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204700\/walltopia-HarroWall-Indoor-Cave-header.jpg","datePublished":"2023-01-08T08:32:43+00:00","dateModified":"2023-05-22T10:41:37+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/proyectos\/harrowall\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204700\/walltopia-HarroWall-Indoor-Cave-header.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027204700\/walltopia-HarroWall-Indoor-Cave-header.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/proyectos\/harrowall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/walltopia.com\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"HarroWall"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project\/69045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/69046"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=69045"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project_category?post=69045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}