{"id":98837,"date":"2023-03-31T21:37:44","date_gmt":"2023-03-31T18:37:44","guid":{"rendered":"http:\/\/walltopia.com\/?post_type=wt_project&#038;p=98837"},"modified":"2023-05-18T11:49:58","modified_gmt":"2023-05-18T08:49:58","slug":"klatreverket-lokka","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/","title":{"rendered":"Klatreverket L\u00f8kka"},"content":{"rendered":"","protected":false},"featured_media":98860,"template":"","wt_project_category":[8780],"class_list":["post-98837","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Klatreverket L\u00f8kka | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klatreverket L\u00f8kka\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T08:49:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027135914\/Klatreverkt-Lokka-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/\",\"name\":\"Klatreverket L\u00f8kka | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027135914\\\/Klatreverkt-Lokka-4.webp\",\"datePublished\":\"2023-03-31T18:37:44+00:00\",\"dateModified\":\"2023-05-18T08:49:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027135914\\\/Klatreverkt-Lokka-4.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027135914\\\/Klatreverkt-Lokka-4.webp\",\"width\":1040,\"height\":780,\"caption\":\"Walltopia bouldering climbing walls\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/klatreverket-lokka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Klatreverket L\u00f8kka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Klatreverket L\u00f8kka | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/","og_locale":"es_ES","og_type":"article","og_title":"Klatreverket L\u00f8kka","og_url":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-18T08:49:58+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027135914\/Klatreverkt-Lokka-4.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/","url":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/","name":"Klatreverket L\u00f8kka | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027135914\/Klatreverkt-Lokka-4.webp","datePublished":"2023-03-31T18:37:44+00:00","dateModified":"2023-05-18T08:49:58+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027135914\/Klatreverkt-Lokka-4.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027135914\/Klatreverkt-Lokka-4.webp","width":1040,"height":780,"caption":"Walltopia bouldering climbing walls"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/proyectos\/klatreverket-lokka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/walltopia.com\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Klatreverket L\u00f8kka"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project\/98837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/98860"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=98837"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_project_category?post=98837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}