{"id":118467,"date":"2021-03-07T17:14:51","date_gmt":"2021-03-07T14:14:51","guid":{"rendered":"http:\/\/walltopia.com\/testimonials\/ken-houliston\/"},"modified":"2021-03-07T17:14:51","modified_gmt":"2021-03-07T14:14:51","slug":"ken-houliston","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/","title":{"rendered":"Ken Houliston"},"featured_media":0,"template":"","testimonial_category":[828],"class_list":["post-118467","wt_testimonial","type-wt_testimonial","status-publish","hentry","testimonial_category-climbing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ken Houliston | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ken Houliston\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/ken-houliston\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/ken-houliston\\\/\",\"name\":\"Ken Houliston | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"datePublished\":\"2021-03-07T14:14:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/ken-houliston\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/ken-houliston\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/ken-houliston\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ken Houliston\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ken Houliston | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/","og_locale":"es_ES","og_type":"article","og_title":"Ken Houliston","og_url":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/","url":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/","name":"Ken Houliston | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"datePublished":"2021-03-07T14:14:51+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/testimonials\/ken-houliston\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/es\/testimonials\/"},{"@type":"ListItem","position":3,"name":"Ken Houliston"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_testimonial\/118467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=118467"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/testimonial_category?post=118467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}