{"id":147213,"date":"2023-01-19T14:47:55","date_gmt":"2023-01-19T11:47:55","guid":{"rendered":"http:\/\/walltopia.com\/products\/diapositivas\/"},"modified":"2026-02-10T11:44:37","modified_gmt":"2026-02-10T08:44:37","slug":"toboganes","status":"publish","type":"wt_wall_type","link":"https:\/\/walltopia.com\/es\/products\/toboganes\/","title":{"rendered":"Tobog\u00e1n"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Dise\u00f1os vers\u00e1tiles de toboganes independientes o integrados en atracciones como Cloud Climb y Adventure Trails. Ya sea recto o retorcido, abierto o cerrado, un tobog\u00e1n es la mejor forma de bajar de cualquier atracci\u00f3n de escalada.   ","protected":false},"featured_media":176947,"template":"","wall_category":[946],"class_list":["post-147213","wt_wall_type","type-wt_wall_type","status-publish","has-post-thumbnail","hentry","wall_category-entretenimiento-activo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tobog\u00e1n | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/es\/products\/toboganes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tobog\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/es\/products\/toboganes\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T08:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210104112\/walltopia-adrenark-slides-02.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/\",\"name\":\"Tobog\u00e1n | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210104112\\\/walltopia-adrenark-slides-02.webp\",\"datePublished\":\"2023-01-19T11:47:55+00:00\",\"dateModified\":\"2026-02-10T08:44:37+00:00\",\"description\":\"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210104112\\\/walltopia-adrenark-slides-02.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251210104112\\\/walltopia-adrenark-slides-02.webp\",\"width\":1920,\"height\":1127},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/products\\\/toboganes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/inicio-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia products\",\"item\":\"https:\\\/\\\/walltopia.com\\\/es\\\/climbing-walls-types\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tobog\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tobog\u00e1n | Walltopia","description":"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/es\/products\/toboganes\/","og_locale":"es_ES","og_type":"article","og_title":"Tobog\u00e1n","og_description":"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.","og_url":"https:\/\/walltopia.com\/es\/products\/toboganes\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-02-10T08:44:37+00:00","og_image":[{"width":1920,"height":1127,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210104112\/walltopia-adrenark-slides-02.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/","url":"https:\/\/walltopia.com\/es\/products\/toboganes\/","name":"Tobog\u00e1n | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210104112\/walltopia-adrenark-slides-02.webp","datePublished":"2023-01-19T11:47:55+00:00","dateModified":"2026-02-10T08:44:37+00:00","description":"Walltopia dise\u00f1a y fabrica toboganes de acero inoxidable que promueven la actividad f\u00edsica y animan a ni\u00f1os y adultos a mantenerse activos.","breadcrumb":{"@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/es\/products\/toboganes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210104112\/walltopia-adrenark-slides-02.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251210104112\/walltopia-adrenark-slides-02.webp","width":1920,"height":1127},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/es\/products\/toboganes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/es\/inicio-es\/"},{"@type":"ListItem","position":2,"name":"Walltopia products","item":"https:\/\/walltopia.com\/es\/climbing-walls-types\/"},{"@type":"ListItem","position":3,"name":"Tobog\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/es\/#website","url":"https:\/\/walltopia.com\/es\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/es\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_wall_type\/147213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wt_wall_type"}],"about":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/types\/wt_wall_type"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media\/176947"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/media?parent=147213"}],"wp:term":[{"taxonomy":"wall_category","embeddable":true,"href":"https:\/\/walltopia.com\/es\/wp-json\/wp\/v2\/wall_category?post=147213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}