{"id":116134,"date":"2023-02-16T14:21:44","date_gmt":"2023-02-16T11:21:44","guid":{"rendered":"http:\/\/walltopia.com\/non-classifiee\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/"},"modified":"2026-01-15T18:06:30","modified_gmt":"2026-01-15T15:06:30","slug":"la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/","title":{"rendered":"La derni\u00e8re ligne droite vers le sommet &#8211; les succ\u00e8s de l&rsquo;escalade sportive bulgare en 2022"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_single_image image=\u00a0\u00bb96176&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_column_text]La distance qui s\u00e9pare les meilleurs comp\u00e9titeurs des finales d&rsquo;escalade de bloc et d&rsquo;escalade sportive est \u00e0 port\u00e9e de main. L&rsquo;objectif est d&rsquo;\u00eatre premier et de remonter dans le classement mondial.[\/vc_column_text][vc_column_text]On glisse, on grimpe, on tombe et on pers\u00e9v\u00e8re &#8211; et c&rsquo;est l\u00e0 le secret de toutes les victoires. C&rsquo;est aussi le secret des enfants de l&rsquo;\u00e9quipe nationale bulgare d&rsquo;escalade. Alex, Niki, Boyan et Slav ont grandi sous mes yeux. J&rsquo;\u00e9tais dans le hall lorsqu&rsquo;ils se sont attach\u00e9s pour la premi\u00e8re fois au harnais de s\u00e9curit\u00e9 et j&rsquo;\u00e9tais l\u00e0 lorsqu&rsquo;ils ont escalad\u00e9 leurs premi\u00e8res voies rocheuses. Il ne se passe pas un jour sans qu&rsquo;ils ne fassent de l&rsquo;escalade, qu&rsquo;ils n&rsquo;essaient de nouveaux mouvements et qu&rsquo;ils ne tentent de vaincre la gravit\u00e9.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbAlex Totkova\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]L&rsquo;\u00e9quipe bulgare d&rsquo;escalade sportive a atteint de nouveaux sommets en 2022.[\/vc_column_text][vc_column_text]Cette ann\u00e9e, Alex Totkova est devenue championne du monde d&rsquo;escalade dans la discipline \u00ab\u00a0difficult\u00e9\u00a0\u00bb lors des championnats du monde d&rsquo;escalade sportive pour juniors et filles \u00e0 Dallas (\u00c9tats-Unis). Elle est \u00e9galement la premi\u00e8re femme bulgare \u00e0 traverser la voie extr\u00eamement difficile \u00ab\u00a0Victims del futur\u00a0\u00bb de cat\u00e9gorie de difficult\u00e9 9a \u00e0 Margalef, en Espagne. Pour les personnes \u00e9clair\u00e9es, apr\u00e8s cette cat\u00e9gorie, il ne reste plus que 4 cat\u00e9gories avant la fin du tableau. Pour ceux qui ne le savent pas, il s&rsquo;agit d&rsquo;un rocher si impitoyablement surplombant et si d\u00e9sesp\u00e9r\u00e9ment lisse que la plupart des gens ne peuvent m\u00eame pas s&rsquo;imaginer l&rsquo;escalader.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb96183&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbBoyan Kirov\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Boyan Kirov est devenu champion d&rsquo;Europe junior aux championnats de Graz, en Autriche, et Nikolay Rusev a remport\u00e9 une m\u00e9daille d&rsquo;argent lors de la m\u00eame comp\u00e9tition.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb96169&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbNiki Rusev\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Niki Rusev est devenu le premier Bulgare \u00e0 remporter une m\u00e9daille d&rsquo;or dans la discipline junior de l&rsquo;escalade de bloc aux Championnats du monde d&rsquo;escalade \u00e0 Voronezh, Russie, 2021. Les comp\u00e9titions d&rsquo;escalade de blocs se d\u00e9roulent sur des itin\u00e9raires courts construits sur des murs sp\u00e9cialement con\u00e7us, d&rsquo;une hauteur maximale de 4,5 m\u00e8tres. L&rsquo;objectif est que les concurrents atteignent la prise finale dans le temps le plus court possible et avec le moins de tentatives possible. Chaque bloc a un point de d\u00e9part et un point d&rsquo;arriv\u00e9e clairement indiqu\u00e9s, qui comptent lorsque les deux mains sont stables sur la prise d&rsquo;arriv\u00e9e d\u00e9sign\u00e9e. Selon le r\u00e8glement de la F\u00e9d\u00e9ration internationale de l&rsquo;escalade sportive, le nombre maximum de prises par bloc doit \u00eatre de 12, et le nombre moyen de prises par bloc dans chaque tour doit \u00eatre compris entre 4 et 8.[\/vc_column_text][vc_column_text]Cet automne, Niki a facilement r\u00e9alis\u00e9 la deuxi\u00e8me ascension du \u00ab\u00a0Fake Hero\u00a0\u00bb, une voie 9a sur le Great Hole, \u00e0 Vratsa. L&rsquo;auteur de la ligne est son entra\u00eeneur Ivaylo Radkov &#8211; Fazata, qui a effectu\u00e9 sa premi\u00e8re travers\u00e9e.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb96190&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbSlav Kirov\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Slav Kirov a remport\u00e9 la m\u00e9daille d&rsquo;argent aux Championnats d&rsquo;Europe d&rsquo;Augsbourg, en Allemagne. L&rsquo;ann\u00e9e derni\u00e8re, il s&rsquo;est class\u00e9 troisi\u00e8me dans l&rsquo;\u00e9preuve de difficult\u00e9 aux Championnats d&rsquo;Europe juniors d&rsquo;escalade sportive \u00e0 \u017dilina, en Slovaquie.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb96197&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbAtteindre le sommet\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]Le temps est pr\u00e9cieux, et le temps que l&rsquo;on passe \u00e0 grimper est bien plus pr\u00e9cieux que le temps que l&rsquo;on ne passe pas \u00e0 grimper, disait un ami. Mais pour bien grimper, il faut de la force, du dynamisme, de la souplesse, de l&rsquo;\u00e9quilibre, du courage, de la motivation et de la t\u00e9nacit\u00e9. Il s&rsquo;agit de l&rsquo;\u00e9quilibre d\u00e9licat entre l&rsquo;escalade et l&rsquo;entra\u00eenement. Et la derni\u00e8re ligne droite de la victoire a \u00e9t\u00e9 marqu\u00e9e par le soutien de toute l&rsquo;\u00e9quipe, des entra\u00eeneurs, de la <a href=\"https:\/\/bfka.org\/\" target=\"_blank\" rel=\"noopener\">F\u00e9d\u00e9ration bulgare d&rsquo;escalade et d&rsquo;alpinisme<\/a>. Et <a href=\"http:\/\/walltopia.com\" target=\"_blank\" rel=\"noopener\">Walltopia<\/a>.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb96204&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_gallery interval=\u00a0\u00bb3&Prime; images=\u00a0\u00bb96302,96295,96239,96324,96246,96331,96253,96317,96260,96267,96274,96281,96288,96232,96225,96218,96310&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<em>Lors d&rsquo;une c\u00e9r\u00e9monie solennelle le 13 octobre 2022, le minist\u00e8re bulgare de la jeunesse et des sports a remis les prix aux champions et m\u00e9daill\u00e9s des championnats du monde et d&rsquo;Europe. Leurs entra\u00eeneurs Ivaylo Radkov, Stanimir Zhelyazkov, Georgi Penev et Vasil Kirov ont \u00e9galement re\u00e7u des r\u00e9compenses bien m\u00e9rit\u00e9es.<\/em>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_column_text]<em><strong>Par Elitsa Pavlova<\/strong>, instructrice d&rsquo;escalade et d&rsquo;alpinisme qualifi\u00e9e \u00e0 l&rsquo;Acad\u00e9mie nationale des sports \u00ab\u00a0Vassil Levski\u00a0\u00bb et membre du comit\u00e9 d&rsquo;alpinisme de la F\u00e9d\u00e9ration bulgare d&rsquo;escalade et d&rsquo;alpinisme, actuellement instructrice au <a href=\"https:\/\/walltopiaclimbingcenter.eu\/\">Centre d&rsquo;escalade Walltopia<\/a>.  <\/em>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_single_image image=\u00a0\u00bb96176&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb][vc_column_text]La distance qui s\u00e9pare les meilleurs comp\u00e9titeurs des finales d&rsquo;escalade de bloc et d&rsquo;escalade sportive&#8230;","protected":false},"author":31,"featured_media":96310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[844,845],"tags":[],"class_list":["post-116134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-escalade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La derni\u00e8re ligne droite vers le sommet - les succ\u00e8s de l&#039;escalade sportive bulgare en 2022 | Walltopia<\/title>\n<meta name=\"description\" content=\"L&#039;\u00e9quipe bulgare d&#039;escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La derni\u00e8re ligne droite vers le sommet - Les succ\u00e8s de l&#039;escalade sportive bulgare en 2022\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00e9quipe bulgare d&#039;escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T11:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T15:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/walltopia.com\/wp-content\/uploads\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022-1024x683.webp\" \/>\n<meta name=\"author\" content=\"milena.boyadjiyska@walltopia.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La derni\u00e8re ligne droite vers le sommet - Les succ\u00e8s de l&#039;escalade sportive bulgare en 2022\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;\u00e9quipe bulgare d&#039;escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/walltopia.com\/wp-content\/uploads\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022-1024x683.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/\"},\"author\":{\"name\":\"milena.boyadjiyska@walltopia.com\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/846dc9ef13ae483793f27b8261a3aac5\"},\"headline\":\"La derni\u00e8re ligne droite vers le sommet &#8211; les succ\u00e8s de l&rsquo;escalade sportive bulgare en 2022\",\"datePublished\":\"2023-02-16T11:21:44+00:00\",\"dateModified\":\"2026-01-15T15:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/\"},\"wordCount\":1129,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027143508\\\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp\",\"articleSection\":[\"Actualit\u00e9s\",\"Escalade\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/\",\"name\":\"La derni\u00e8re ligne droite vers le sommet - les succ\u00e8s de l'escalade sportive bulgare en 2022 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027143508\\\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp\",\"datePublished\":\"2023-02-16T11:21:44+00:00\",\"dateModified\":\"2026-01-15T15:06:30+00:00\",\"description\":\"L'\u00e9quipe bulgare d'escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027143508\\\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027143508\\\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La derni\u00e8re ligne droite vers le sommet &#8211; les succ\u00e8s de l&#8217;escalade sportive bulgare en 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/846dc9ef13ae483793f27b8261a3aac5\",\"name\":\"milena.boyadjiyska@walltopia.com\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La derni\u00e8re ligne droite vers le sommet - les succ\u00e8s de l'escalade sportive bulgare en 2022 | Walltopia","description":"L'\u00e9quipe bulgare d'escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"La derni\u00e8re ligne droite vers le sommet - Les succ\u00e8s de l'escalade sportive bulgare en 2022","og_description":"L'\u00e9quipe bulgare d'escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.","og_url":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-02-16T11:21:44+00:00","article_modified_time":"2026-01-15T15:06:30+00:00","og_image":[{"url":"http:\/\/walltopia.com\/wp-content\/uploads\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022-1024x683.webp","type":"","width":"","height":""}],"author":"milena.boyadjiyska@walltopia.com","twitter_card":"summary_large_image","twitter_title":"La derni\u00e8re ligne droite vers le sommet - Les succ\u00e8s de l'escalade sportive bulgare en 2022","twitter_description":"L'\u00e9quipe bulgare d'escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.","twitter_image":"http:\/\/walltopia.com\/wp-content\/uploads\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022-1024x683.webp","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/"},"author":{"name":"milena.boyadjiyska@walltopia.com","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/846dc9ef13ae483793f27b8261a3aac5"},"headline":"La derni\u00e8re ligne droite vers le sommet &#8211; les succ\u00e8s de l&rsquo;escalade sportive bulgare en 2022","datePublished":"2023-02-16T11:21:44+00:00","dateModified":"2026-01-15T15:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/"},"wordCount":1129,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143508\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp","articleSection":["Actualit\u00e9s","Escalade"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/","url":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/","name":"La derni\u00e8re ligne droite vers le sommet - les succ\u00e8s de l'escalade sportive bulgare en 2022 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143508\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp","datePublished":"2023-02-16T11:21:44+00:00","dateModified":"2026-01-15T15:06:30+00:00","description":"L'\u00e9quipe bulgare d'escalade sportive a atteint de nouveaux sommets en 2022. D\u00e9couvrez les succ\u00e8s de ces jeunes et des personnes qui les soutiennent.","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143508\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027143508\/Alex_Totkova_02_Bulgarian-national-climbing-team_2022.webp","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/la-derniere-ligne-droite-vers-le-sommet-les-succes-de-lescalade-sportive-bulgare-en-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"La derni\u00e8re ligne droite vers le sommet &#8211; les succ\u00e8s de l&#8217;escalade sportive bulgare en 2022"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/846dc9ef13ae483793f27b8261a3aac5","name":"milena.boyadjiyska@walltopia.com"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/116134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=116134"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/116134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/96310"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=116134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=116134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=116134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}