{"id":186734,"date":"2021-06-22T16:14:20","date_gmt":"2021-06-22T13:14:20","guid":{"rendered":"https:\/\/walltopia.com\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/"},"modified":"2026-09-01T11:09:31","modified_gmt":"2026-09-01T08:09:31","slug":"et-le-gagnant-dun-mur-descalade-a-domicile-est","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/","title":{"rendered":"Et le gagnant d&rsquo;un mur d&rsquo;escalade \u00e0 domicile est&#8230;"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbUn mur d&apos;escalade \u00e0 domicile va&#8230;\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:20|text_align:left|color:%23ed2020|line_height:1.5&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb][vc_column_text css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Si vous \u00eates comme nous, votre routine d&rsquo;escalade vous manque plus que le trajet pour vous rendre au travail. Il est facile d&rsquo;installer une station de travail \u00e0 domicile, \u00e0 condition que votre Wi-Fi fonctionne bien. Mais l&rsquo;escalade, c&rsquo;est diff\u00e9rent. Notre motivation va au-del\u00e0 du maintien de la forme physique et l&rsquo;achat d&rsquo;un nouvel \u00e9quipement d&rsquo;entra\u00eenement n&rsquo;est pas une alternative. La question est donc la suivante : comment pouvez-vous continuer \u00e0 grimper lorsque votre salle de sport pr\u00e9f\u00e9r\u00e9e est ferm\u00e9e ? O\u00f9 faire de l&rsquo;escalade en cette p\u00e9riode de distanciation sociale ?     <\/p>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/1&Prime;][vc_column_text css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nous avons une r\u00e9ponse \u00e0 ces questions, mais cette histoire est celle d&rsquo;une personne qui a cess\u00e9 de s&rsquo;inqui\u00e9ter de sa routine d&rsquo;escalade et qui a gagn\u00e9 un <strong>mur d&rsquo;escalade Walltopia Home<\/strong>!<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">L&rsquo;heureux gagnant est <strong>Matthaios Valsamidis<\/strong>, qui nous a montr\u00e9 bien plus que sa passion pour l&rsquo;escalade. Son histoire nous montre \u00e0 quel point rester \u00e0 la maison peut \u00eatre difficile pour des personnes qui avaient l&rsquo;habitude d&rsquo;\u00eatre physiquement actives. Bien s\u00fbr, un bon sens de l&rsquo;humour peut \u00eatre utile, mais cela ne rend pas les choses plus faciles.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Mais nous savons qu&rsquo;un mur d&rsquo;escalade serait bien utile ! Nous avons h\u00e2te de voir Matthaios et ses amis profiter du beau temps grec pour continuer \u00e0 grimper depuis chez eux. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nous avons appr\u00e9ci\u00e9 toutes les contributions au concours et nous avons eu du mal \u00e0 n&rsquo;en choisir qu&rsquo;une seule. Nous esp\u00e9rons cependant que tous les participants se sont amus\u00e9s en tournant les histoires, car pendant ces jours o\u00f9 nous en avons besoin, les efforts devraient en avoir valu la peine. Pour voir toutes les histoires, suivez les <strong>#WalltopiaHomeClimbing<\/strong> et <strong>#MyWalltopiaWall Wall<\/strong> sur <em>Instagram<\/em>.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>Encore une fois, f\u00e9licitations \u00e0 Matthaios !<\/strong><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb]\n<p style=\"font-size: 18px; line-height: 1.8em;\"><strong>P.S.<\/strong> <em>N&rsquo;oubliez pas de <a href=\"mailto:sales@walltopia.com\">nous \u00e9crire<\/a> si vous avez envie d&rsquo;avoir votre propre mur d&rsquo;escalade \u00e0 domicile !<\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbUn mur d&apos;escalade \u00e0 domicile va&#8230;\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:20|text_align:left|color:%23ed2020|line_height:1.5&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb][vc_column_text css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb] Si vous \u00eates comme nous, votre routine d&rsquo;escalade vous&#8230;","protected":false},"author":10,"featured_media":22555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[844,845],"tags":[2656,2768,2654],"class_list":["post-186734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-escalade","tag-concours-de-mur-descalade","tag-mur-denceinte","tag-mur-descalade-a-domicile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Et le gagnant d&#039;un mur d&#039;escalade \u00e0 domicile est... | Walltopia<\/title>\n<meta name=\"description\" content=\"Walltopia annonce le gagnant d&#039;un nouveau syst\u00e8me d&#039;escalade \u00e0 domicile, dans le cadre de notre objectif d&#039;aider les grimpeurs \u00e0 conserver leur routine d&#039;escalade tout en restant chez eux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Et le gagnant d&#039;un mur d&#039;escalade \u00e0 domicile est...\" \/>\n<meta property=\"og:description\" content=\"Walltopia annonce le gagnant d&#039;un nouveau syst\u00e8me d&#039;escalade \u00e0 domicile, dans le cadre de notre objectif d&#039;aider les grimpeurs \u00e0 conserver leur routine d&#039;escalade tout en restant chez eux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T13:14:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T08:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"the_id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/\"},\"author\":{\"name\":\"the_id\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\"},\"headline\":\"Et le gagnant d&rsquo;un mur d&rsquo;escalade \u00e0 domicile est&#8230;\",\"datePublished\":\"2021-06-22T13:14:20+00:00\",\"dateModified\":\"2026-09-01T08:09:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/\"},\"wordCount\":415,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085019\\\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg\",\"keywords\":[\"concours de mur d'escalade\",\"mur d'enceinte\",\"mur d'escalade \u00e0 domicile\"],\"articleSection\":[\"Actualit\u00e9s\",\"Escalade\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/\",\"name\":\"Et le gagnant d'un mur d'escalade \u00e0 domicile est... | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085019\\\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg\",\"datePublished\":\"2021-06-22T13:14:20+00:00\",\"dateModified\":\"2026-09-01T08:09:31+00:00\",\"description\":\"Walltopia annonce le gagnant d'un nouveau syst\u00e8me d'escalade \u00e0 domicile, dans le cadre de notre objectif d'aider les grimpeurs \u00e0 conserver leur routine d'escalade tout en restant chez eux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085019\\\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231026085019\\\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg\",\"width\":400,\"height\":266},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/et-le-gagnant-dun-mur-descalade-a-domicile-est\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Et le gagnant d&#8217;un mur d&#8217;escalade \u00e0 domicile est&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/b30506c6570e8fcee537c66f40da51ff\",\"name\":\"the_id\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Et le gagnant d'un mur d'escalade \u00e0 domicile est... | Walltopia","description":"Walltopia annonce le gagnant d'un nouveau syst\u00e8me d'escalade \u00e0 domicile, dans le cadre de notre objectif d'aider les grimpeurs \u00e0 conserver leur routine d'escalade tout en restant chez eux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/","og_locale":"fr_FR","og_type":"article","og_title":"Et le gagnant d'un mur d'escalade \u00e0 domicile est...","og_description":"Walltopia annonce le gagnant d'un nouveau syst\u00e8me d'escalade \u00e0 domicile, dans le cadre de notre objectif d'aider les grimpeurs \u00e0 conserver leur routine d'escalade tout en restant chez eux.","og_url":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2021-06-22T13:14:20+00:00","article_modified_time":"2026-09-01T08:09:31+00:00","og_image":[{"width":400,"height":266,"url":"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg","type":"image\/jpeg"}],"author":"the_id","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/"},"author":{"name":"the_id","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff"},"headline":"Et le gagnant d&rsquo;un mur d&rsquo;escalade \u00e0 domicile est&#8230;","datePublished":"2021-06-22T13:14:20+00:00","dateModified":"2026-09-01T08:09:31+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/"},"wordCount":415,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg","keywords":["concours de mur d'escalade","mur d'enceinte","mur d'escalade \u00e0 domicile"],"articleSection":["Actualit\u00e9s","Escalade"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/","url":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/","name":"Et le gagnant d'un mur d'escalade \u00e0 domicile est... | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg","datePublished":"2021-06-22T13:14:20+00:00","dateModified":"2026-09-01T08:09:31+00:00","description":"Walltopia annonce le gagnant d'un nouveau syst\u00e8me d'escalade \u00e0 domicile, dans le cadre de notre objectif d'aider les grimpeurs \u00e0 conserver leur routine d'escalade tout en restant chez eux.","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231026085019\/f66da0157e88ccf3deb2fbdbfc220fe0_M.jpg","width":400,"height":266},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/et-le-gagnant-dun-mur-descalade-a-domicile-est\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Et le gagnant d&#8217;un mur d&#8217;escalade \u00e0 domicile est&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/b30506c6570e8fcee537c66f40da51ff","name":"the_id"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/186734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=186734"}],"version-history":[{"count":3,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/186734\/revisions"}],"predecessor-version":[{"id":393954,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/186734\/revisions\/393954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/22555"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=186734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=186734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=186734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}