{"id":189191,"date":"2015-06-18T13:03:40","date_gmt":"2015-06-18T10:03:40","guid":{"rendered":"https:\/\/walltopia.com\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/"},"modified":"2026-01-15T17:39:54","modified_gmt":"2026-01-15T14:39:54","slug":"walltopia-a-lasian-attraction-expo-a-hong-kong-2","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/","title":{"rendered":"Walltopia \u00e0 l&rsquo;Asian Attraction Expo \u00e0 Hong Kong"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Venez nous rencontrer au Hong Kong Convention and Exhibition Centre, stand #1147 et d\u00e9couvrez les <a href=\"https:\/\/staging-3.walltopia.com\/products\/\">produits Walltopia Active Entertainment !<\/a><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Les <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\">Fun Walls<\/a>, les <a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\">Ropes Courses<\/a>, les <a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\">Walltopia Caves<\/a> et les <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\">Rollglider<\/a> offrent tous un excellent m\u00e9lange de sport sain, d&rsquo;activit\u00e9s d&rsquo;apprentissage et d&rsquo;amusement. Au cours des trois derni\u00e8res ann\u00e9es, nous avons men\u00e9 \u00e0 bien <a href=\"https:\/\/staging-3.walltopia.com\/projects\/\">des projets de divertissement<\/a> aux \u00c9tats-Unis, au Canada, en Malaisie, en Russie, en Irlande, au Royaume-Uni, en Bulgarie et dans les \u00c9mirats arabes unis. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nous vous en dirons plus en personne \ud83d\ude09<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre, stand #1147.","protected":false},"author":5,"featured_media":95071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[868],"tags":[3224,3223],"class_list":["post-189191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement-actif","tag-asian-attraction-expo","tag-asian-attraction-expo-a-hong-kong"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Walltopia \u00e0 l&#039;Asian Attraction Expo \u00e0 Hong Kong | Walltopia<\/title>\n<meta name=\"description\" content=\"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walltopia \u00e0 l&#039;Asian Attraction Expo \u00e0 Hong Kong\" \/>\n<meta property=\"og:description\" content=\"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-18T10:03:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:39:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Walltopia \u00e0 l&rsquo;Asian Attraction Expo \u00e0 Hong Kong\",\"datePublished\":\"2015-06-18T10:03:40+00:00\",\"dateModified\":\"2026-01-15T14:39:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/\"},\"wordCount\":115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150139\\\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg\",\"keywords\":[\"Asian Attraction Expo\",\"Asian Attraction Expo \u00e0 Hong Kong\"],\"articleSection\":[\"Divertissement actif\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/\",\"name\":\"Walltopia \u00e0 l'Asian Attraction Expo \u00e0 Hong Kong | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150139\\\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg\",\"datePublished\":\"2015-06-18T10:03:40+00:00\",\"dateModified\":\"2026-01-15T14:39:54+00:00\",\"description\":\"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150139\\\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027150139\\\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg\",\"width\":900,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia \u00e0 l&#8217;Asian Attraction Expo \u00e0 Hong Kong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Walltopia \u00e0 l'Asian Attraction Expo \u00e0 Hong Kong | Walltopia","description":"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Walltopia \u00e0 l'Asian Attraction Expo \u00e0 Hong Kong","og_description":"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !","og_url":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2015-06-18T10:03:40+00:00","article_modified_time":"2026-01-15T14:39:54+00:00","og_image":[{"width":900,"height":479,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Walltopia \u00e0 l&rsquo;Asian Attraction Expo \u00e0 Hong Kong","datePublished":"2015-06-18T10:03:40+00:00","dateModified":"2026-01-15T14:39:54+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg","keywords":["Asian Attraction Expo","Asian Attraction Expo \u00e0 Hong Kong"],"articleSection":["Divertissement actif"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/","url":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/","name":"Walltopia \u00e0 l'Asian Attraction Expo \u00e0 Hong Kong | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg","datePublished":"2015-06-18T10:03:40+00:00","dateModified":"2026-01-15T14:39:54+00:00","description":"Venez nous rencontrer au Hong Kong Convention and Exhibition Centre et d\u00e9couvrez les produits Walltopia Active Entertainment !","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027150139\/Walltopia-Asian-Attraction-Expo-Hong-Kong.jpg","width":900,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/walltopia-a-lasian-attraction-expo-a-hong-kong-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Walltopia \u00e0 l&#8217;Asian Attraction Expo \u00e0 Hong Kong"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/189191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=189191"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/189191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/95071"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=189191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=189191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=189191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}