{"id":191458,"date":"2016-06-22T10:49:17","date_gmt":"2016-06-22T07:49:17","guid":{"rendered":"https:\/\/walltopia.com\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/"},"modified":"2026-01-15T17:44:52","modified_gmt":"2026-01-15T14:44:52","slug":"le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/","title":{"rendered":"Le premier centre d&rsquo;aventure Walltopia ouvre ses portes en octobre 2016"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb][vc_column_text]\n<h4>L&rsquo;aventure int\u00e9rieure est sur le point de prendre de l&rsquo;ampleur !<\/h4>\n<p style=\"font-size:18px; line-height: 1.8em;\">Le prochain grand projet de l&rsquo;industrie du divertissement verra le jour en octobre prochain. Le premier <strong>Walltopia Adventure Hub<\/strong> verra le jour au Lavina Mall de Kiev, en Ukraine, dans le cadre du <a href=\"https:\/\/staging-3.walltopia.com\/projects\/galaxy-park\/\">Galaxy Family Entertainment Centre.<\/a> Les attractions du centre offriront aux enfants et aux adultes des d\u00e9fis passionnants et amusants. <\/p>\n<p style=\"font-size:18px; line-height: 1.8em;\">Pour offrir une exp\u00e9rience d&rsquo;aventure ultime, nous avons combin\u00e9 une vari\u00e9t\u00e9 d&rsquo;attractions dans une station de divertissement massive, y compris<\/p>\n<ul style=\"font-size:18px; line-height: 1.8em;\">\n<li><a href=\"https:\/\/staging-3.walltopia.com\/products\/ropes-course\/\"><strong>Parcours de cordes :<\/strong><\/a> parcours de cordes en hauteur et en contrebas avec 23 d\u00e9fis diff\u00e9rents<\/li>\n<li>154m <a href=\"https:\/\/staging-3.walltopia.com\/products\/rollglider\/\"><strong>Rollglider :<\/strong><\/a> une tyrolienne a\u00e9rienne de montagnes russes passionnante<\/li>\n<li>Plus de 20 murs interactifs <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/\"><strong>murs d&rsquo;escalade<\/strong><\/a> d\u00e9fis d&rsquo;escalade<\/li>\n<li>Un toboggan <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/parabolic-slide\/\"><strong>toboggan parabolique<\/strong><\/a> pour faire battre tous les c\u0153urs<\/li>\n<li><a href=\"https:\/\/staging-3.walltopia.com\/products\/walltopia-caves\/\"><strong>Grotte Walltopia :<\/strong><\/a> syst\u00e8me de sp\u00e9l\u00e9ologie artificielle pour les explorateurs aventureux<\/li>\n<li>A <a href=\"https:\/\/staging-3.walltopia.com\/products\/fun-walls\/jump-in-the-air\/\"><strong>Quick Jump<\/strong><\/a> dispositif de chute libre qui reproduit en toute s\u00e9curit\u00e9 l&rsquo;exp\u00e9rience du BASE jumping.<\/li>\n<li>Et 84 m de <a href=\"https:\/\/staging-3.walltopia.com\/products\/adventure-trail\/\"><strong>Sentiers d&rsquo;aventure<\/strong><\/a> avec 12 maisons de l&rsquo;aventure le long du parcours.<\/li>\n<\/ul>\n[vc_gallery type=\u00a0\u00bbflexslider_slide\u00a0\u00bb interval=\u00a0\u00bb3&Prime; images=\u00a0\u00bb12002,12001,12000&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][vc_column_text]\n<p style=\"font-size:18px; line-height: 1.8em;\">Le tout premier <a href=\"https:\/\/staging-3.walltopia.com\/products\/adventure-hub\/\">centre d&rsquo;aventure Walltopia<\/a>, d&rsquo;une superficie de 450 m2 et d&rsquo;une hauteur de 20 m, offrira des divertissements actifs et des tonnes de plaisir \u00e0 700 personnes par heure, ce qui repr\u00e9sente un flux de visiteurs de plus de 5 000 personnes par jour !<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Le premier Walltopia Adventure Hub verra le jour au centre commercial Lavina Mall \u00e0 Kiev, en Ukraine.","protected":false},"author":5,"featured_media":95242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[868],"tags":[3669],"class_list":["post-191458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement-actif","tag-adventure-hub"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le premier centre d&#039;aventure Walltopia ouvre ses portes en octobre 2016 | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le premier centre d&#039;aventure Walltopia ouvre ses portes en octobre 2016\" \/>\n<meta property=\"og:description\" content=\"Le premier Walltopia Adventure Hub verra le jour au centre commercial Lavina Mall \u00e0 Kiev, en Ukraine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-22T07:49:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:44:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Le premier centre d&rsquo;aventure Walltopia ouvre ses portes en octobre 2016\",\"datePublished\":\"2016-06-22T07:49:17+00:00\",\"dateModified\":\"2026-01-15T14:44:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145943\\\/First-Walltopia-Adventure-Hub.jpg\",\"keywords\":[\"Adventure Hub\"],\"articleSection\":[\"Divertissement actif\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/\",\"name\":\"Le premier centre d'aventure Walltopia ouvre ses portes en octobre 2016 | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145943\\\/First-Walltopia-Adventure-Hub.jpg\",\"datePublished\":\"2016-06-22T07:49:17+00:00\",\"dateModified\":\"2026-01-15T14:44:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145943\\\/First-Walltopia-Adventure-Hub.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145943\\\/First-Walltopia-Adventure-Hub.jpg\",\"width\":900,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le premier centre d&#8217;aventure Walltopia ouvre ses portes en octobre 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le premier centre d'aventure Walltopia ouvre ses portes en octobre 2016 | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/","og_locale":"fr_FR","og_type":"article","og_title":"Le premier centre d'aventure Walltopia ouvre ses portes en octobre 2016","og_description":"Le premier Walltopia Adventure Hub verra le jour au centre commercial Lavina Mall \u00e0 Kiev, en Ukraine.","og_url":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2016-06-22T07:49:17+00:00","article_modified_time":"2026-01-15T14:44:52+00:00","og_image":[{"width":900,"height":441,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Le premier centre d&rsquo;aventure Walltopia ouvre ses portes en octobre 2016","datePublished":"2016-06-22T07:49:17+00:00","dateModified":"2026-01-15T14:44:52+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg","keywords":["Adventure Hub"],"articleSection":["Divertissement actif"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/","url":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/","name":"Le premier centre d'aventure Walltopia ouvre ses portes en octobre 2016 | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg","datePublished":"2016-06-22T07:49:17+00:00","dateModified":"2026-01-15T14:44:52+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145943\/First-Walltopia-Adventure-Hub.jpg","width":900,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/le-premier-centre-daventure-walltopia-ouvre-ses-portes-en-octobre-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Le premier centre d&#8217;aventure Walltopia ouvre ses portes en octobre 2016"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/191458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=191458"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/191458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/95242"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=191458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=191458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=191458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}