{"id":193692,"date":"2017-05-04T05:45:05","date_gmt":"2017-05-04T02:45:05","guid":{"rendered":"https:\/\/walltopia.com\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/"},"modified":"2026-01-15T17:50:45","modified_gmt":"2026-01-15T14:50:45","slug":"wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/","title":{"rendered":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column css_animation=\u00a0\u00bbfadeInUp\u00a0\u00bb][vc_column_text]\n<p style=\"font-size: 18px; line-height: 1.8em;\">Le mois de mai sera tr\u00e8s charg\u00e9 pour Walltopia Adventure. Cinq salons diff\u00e9rents et passionnants nous attendent, dans diff\u00e9rentes parties du monde, et notre \u00e9quipe d&rsquo;experts se r\u00e9jouit de vous y retrouver ! <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nous commen\u00e7ons par la <a href=\"https:\/\/www.nsaa.org\" target=\"_blank\" rel=\"noopener\"><strong>Convention nationale et salon professionnel de la NSAA <\/strong><\/a> \u00e0 Scottsdale, en Arizona, o\u00f9 nous vous montrerons les avantages du Rollglider pour les stations de montagne et de ski. Il s&rsquo;agit non seulement d&rsquo;une attraction qui peut attirer des clients tout au long de l&rsquo;ann\u00e9e, mais aussi d&rsquo;un produit qui s&rsquo;int\u00e8gre parfaitement \u00e0 l&rsquo;environnement naturel. Venez nous voir au <strong>stand 21<\/strong> de l&rsquo;h\u00f4tel <strong>Fairmont Scottsdale Princess<\/strong>. L&rsquo;\u00e9v\u00e9nement aura lieu du <strong>5 au 8 mai.<\/strong>   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Notre prochaine destination est Duba\u00ef, o\u00f9 nous participerons au <strong>Theme Parks &amp; Entertainment Development Forum du<\/strong> <strong>9 au 11 mai.<\/strong> M. Ivaylo Penchev, PDG et cofondateur de Walltopia, sera pr\u00e9sent pour partager sa vision du concept de divertissement actif. Rejoignez-nous pour notre pr\u00e9sentation lors du panel principal (9 mai, 9h30), et apprenez comment utiliser de petits espaces tout en maintenant une gamme vari\u00e9e d&rsquo;attractions. Passez \u00e9galement \u00e0 notre stand dans le foyer de l&rsquo;<strong>h\u00f4tel Meydan<\/strong> et renseignez-vous sur nos derni\u00e8res innovations.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Apr\u00e8s notre visite \u00e0 Duba\u00ef, notre \u00e9quipe se rendra en Australie pour la <a href=\"https:\/\/aalara.com.au\/\" target=\"_blank\" rel=\"noopener\"><strong>conf\u00e9rence de l&rsquo;Australian Amusement Leisure &amp; Recreation Association<\/strong> (AALARA)<\/a>. Le salon se tiendra au <strong>Gold Coast Convention &amp; Exhibition Centre du<\/strong> <strong>15 au 18 mai<\/strong>. Arr\u00eatez-vous aux <strong>stands 57 et 58<\/strong> pour en savoir plus sur nos concepts de divertissement actif, ainsi que sur ce que nous avons fait sur le march\u00e9 australien jusqu&rsquo;\u00e0 pr\u00e9sent.  <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Le prochain rendez-vous de notre calendrier est <a href=\"https:\/\/www.icsc.com\/\" target=\"_blank\" rel=\"noopener\"><strong>RECon<\/strong><\/a> \u00e0 Las Vegas. Rejoignez-nous au <strong>Las Vegas Convention Center<\/strong> du <strong>22 au 24 mai<\/strong>, et laissez-nous vous montrer comment nous changeons la donne dans le domaine du \u00ab\u00a0Retailtainment\u00a0\u00bb. Les exp\u00e9riences sont ce qui ram\u00e8ne les visiteurs dans les centres commerciaux, et ce n&rsquo;est pas un myst\u00e8re que les centres commerciaux consacrent plus de 15 % de leur surface aux divertissements. Nous voulons vous parler des \u00e9tapes importantes de la refonte des centres commerciaux et de leur transformation en centres de destination avec l&rsquo;aide de nos produits de divertissement actif. Venez nous rencontrer sur le <strong> stand N1231<\/strong>.    <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Enfin, nous nous rendrons \u00e0 Londres pour la premi\u00e8re conf\u00e9rence et le premier salon europ\u00e9en de l <strong>&lsquo;Association internationale des parcs \u00e0 trampolines<\/strong>. Les <strong> 22 et 23 mai<\/strong>, nous nous rendrons \u00e0 l&rsquo;h\u00f4tel <strong>Hilton London Paddington<\/strong>. Ne nous manquez pas \u00e0 la session \u00ab\u00a0Novel Activities &#8211; Adding Attractions to your Park\u00a0\u00bb, le 22 mai \u00e0 11h00, pour en savoir plus sur l&rsquo;avenir du divertissement actif. Vous pouvez \u00e9galement nous rencontrer au <strong> stand 33<\/strong> o\u00f9 nous pourrons mettre en lumi\u00e8re de nouvelles fa\u00e7ons de diversifier les parcs de trampolines.   <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\"><img decoding=\"async\" src=\"http:\/\/walltopia.com\/images\/shows_may1.jpg\" alt=\"\" width=\"100%\"><\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Si vous vous rendez \u00e0 l&rsquo;un des \u00e9v\u00e9nements mentionn\u00e9s, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter pour fixer un rendez-vous \u00e0 l&rsquo;avance. Nous nous ferons un plaisir de r\u00e9pondre \u00e0 vos questions et de vous mettre en contact avec un membre de notre \u00e9quipe. <\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Pour en savoir plus sur nos produits, cliquez ici.<\/p>\n<p style=\"font-size: 18px; line-height: 1.8em;\">Nous esp\u00e9rons vous voir bient\u00f4t !<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Le mois de mai sera tr\u00e8s charg\u00e9 pour Walltopia Adventure. Cinq salons diff\u00e9rents et passionnants nous attendent. ","protected":false},"author":5,"featured_media":95432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[868],"tags":[4210,4082],"class_list":["post-193692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement-actif","tag-attractions-salons-professionnels","tag-salons-professionnels"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni\" \/>\n<meta property=\"og:description\" content=\"Le mois de mai sera tr\u00e8s charg\u00e9 pour Walltopia Adventure. Cinq salons diff\u00e9rents et passionnants nous attendent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-04T02:45:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni\",\"datePublished\":\"2017-05-04T02:45:05+00:00\",\"dateModified\":\"2026-01-15T14:50:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145538\\\/Walltopia-Trade-Shows-2017.jpg\",\"keywords\":[\"Attractions Salons professionnels\",\"salons professionnels\"],\"articleSection\":[\"Divertissement actif\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/\",\"name\":\"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145538\\\/Walltopia-Trade-Shows-2017.jpg\",\"datePublished\":\"2017-05-04T02:45:05+00:00\",\"dateModified\":\"2026-01-15T14:50:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145538\\\/Walltopia-Trade-Shows-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231027145538\\\/Walltopia-Trade-Shows-2017.jpg\",\"width\":900,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/","og_locale":"fr_FR","og_type":"article","og_title":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni","og_description":"Le mois de mai sera tr\u00e8s charg\u00e9 pour Walltopia Adventure. Cinq salons diff\u00e9rents et passionnants nous attendent.","og_url":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2017-05-04T02:45:05+00:00","article_modified_time":"2026-01-15T14:50:45+00:00","og_image":[{"width":900,"height":478,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg","type":"image\/jpeg"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni","datePublished":"2017-05-04T02:45:05+00:00","dateModified":"2026-01-15T14:50:45+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg","keywords":["Attractions Salons professionnels","salons professionnels"],"articleSection":["Divertissement actif"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/","url":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/","name":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg","datePublished":"2017-05-04T02:45:05+00:00","dateModified":"2026-01-15T14:50:45+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027145538\/Walltopia-Trade-Shows-2017.jpg","width":900,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/wallltopia-adventure-participera-a-des-salons-professionnels-aux-etats-unis-au-moyen-orient-en-australie-et-au-royaume-uni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Wallltopia Adventure participera \u00e0 des salons professionnels aux \u00c9tats-Unis, au Moyen-Orient, en Australie et au Royaume-Uni"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/193692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=193692"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/193692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/95432"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=193692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=193692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=193692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}