{"id":198190,"date":"2023-10-30T12:54:45","date_gmt":"2023-10-30T09:54:45","guid":{"rendered":"https:\/\/walltopia.com\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/"},"modified":"2026-06-16T14:02:17","modified_gmt":"2026-06-16T11:02:17","slug":"rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/","title":{"rendered":"Rencontrez-nous \u00e0 l&rsquo;IAAPA Expo Orlando du 14 au 17 novembre 2023"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]IAAPA Expo Orlando est le premier \u00e9v\u00e9nement international pour Walltopia. Notre \u00e9quipe d&rsquo;experts en divertissement actif comprendra nos cadres sup\u00e9rieurs ainsi que les responsables du d\u00e9veloppement de produits. Ils seront heureux de vous rencontrer au stand 4636 et de discuter de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d&rsquo;aventure et d&rsquo;attraction.  <\/p>\n<p>Cette ann\u00e9e, nous avons \u00e9largi notre gamme de <a href=\"http:\/\/walltopia.com\/walltopia-active-entertainment\/\">divertissements actifs<\/a> avec des aires de jeux, des toboggans, de nouvelles configurations de parcours de cordes et des trampolines.<\/p>\n<h3>Nouvelles attractions non ma\u00eetris\u00e9es<\/h3>\n<p>\u00ab\u00a0\u00a0\u00bb\u00a0\u00bb \u00c9largissez votre groupe cible<\/p>\n<p>\u00ab\u00a0\u00a0\u00bb\u00a0\u00bb Activit\u00e9s ludiques suppl\u00e9mentaires pour le commerce de d\u00e9tail et les centres de loisirs familiaux<\/p>\n<p>\u00ab\u00a0\u00a0\u00bb\u00a0\u00bb Minimiser les co\u00fbts de maintenance et les effectifs[\/vc_column_text][vc_empty_space][vc_column_text]\n<h4><a href=\"https:\/\/walltopia.com\/fr\/products\/terrains-de-jeux\/\">Terrains de jeux<\/a><\/h4>\n<ul>\n<li>le moyen id\u00e9al d&rsquo;augmenter la capacit\u00e9 tout en optimisant l&rsquo;utilisation de l&rsquo;espace<\/li>\n<li>Les mod\u00e8les disponibles sont Soft Play, Bloc Play, Puff Play et Signature Playgrounds,<\/li>\n<li>nouveaux mod\u00e8les \u00e0 venir &#8211; aires de jeux \u00e0 filets courbes, tours de toboggans et aires de jeux mobiles r\u00e9am\u00e9nageables<\/li>\n<li>peut \u00eatre enrichi par des th\u00e9matisations et des produits suppl\u00e9mentaires : Escalade de nuages, toboggans, labyrinthe de filets, trampolines et maisons et tunnels de parcours d&rsquo;aventure.<\/li>\n<li>Assemblage \u00ab\u00a0Do-It-Yourself\u00a0\u00bb et composants modulaires<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb79847&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/playgrounds\/\u00a0\u00bb][vc_column_text]\n<h4><a href=\"https:\/\/walltopia.com\/fr\/products\/tobbogans\/\">Tobbogans<\/a><\/h4>\n<ul>\n<li>Con\u00e7u sur mesure par notre \u00e9quipe d&rsquo;architectes pour tirer le meilleur parti de votre espace et s&rsquo;int\u00e9grer harmonieusement aux autres attractions.<\/li>\n<li>Diff\u00e9rentes hauteurs et mod\u00e8les sont propos\u00e9s : toboggans d&rsquo;\u00e9vacuation \/ ludiques \/ paraboliques \/ de vitesse, avec de vastes possibilit\u00e9s de th\u00e9matisation.<\/li>\n<li>Applications polyvalentes dans un large \u00e9ventail de lieux tels que les centres commerciaux, les bureaux, les h\u00f4tels et centres de vill\u00e9giature, les zoos, les parcs aquatiques, etc.<\/li>\n<li>Pas besoin de harnais, juste le frisson des hauteurs et de la vitesse.<\/li>\n<li>Solution optimale pour minimiser le personnel op\u00e9rationnel<\/li>\n<li>Installation rapide et sans souci<\/li>\n<li>Mat\u00e9riaux et production de haute qualit\u00e9 conformes aux normes de s\u00e9curit\u00e9 de l&rsquo;UE<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb81783&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/slides\/\u00a0\u00bb][vc_empty_space][vc_column_text]\n<h3>Nouvelles configurations de parcours de cordes<\/h3>\n<h4><a href=\"http:\/\/walltopia.com\/products\/ropes-courses\/circle-ropes-course\/\">Le parcours de cordes du cercle<\/a><\/h4>\n<ul>\n<li>un design spectaculaire avec une forme circulaire unique<\/li>\n<li>conception modulaire &#8211; extension verticale facile<\/li>\n<li>Syst\u00e8me de s\u00e9curit\u00e9 enti\u00e8rement nouveau avec des chariots pour un fonctionnement plus facile et une exp\u00e9rience plus fluide<\/li>\n<li>option pour le compl\u00e9ment Zip Rail &#8211; Walltopia innovation<\/li>\n<li>diverses combinaisons de couleurs standard avec des possibilit\u00e9s de personnalisation<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb103352&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/ropes-courses\/circle-ropes-course\/\u00a0\u00bb][vc_column_text]\n<h4><a href=\"http:\/\/walltopia.com\/products\/ropes-courses\/unharnessed-hex\/\">L&rsquo;hexagone non harnach\u00e9<\/a><\/h4>\n<ul>\n<li>libert\u00e9 de mouvement &#8211; pas de harnais, pas de composants m\u00e9caniques<\/li>\n<li>un nombre r\u00e9duit de personnel op\u00e9rationnel<\/li>\n<li>une grande attraction autonome pour les enfants<\/li>\n<li>le plus grand nombre d&rsquo;h\u00f4tes par rapport \u00e0 l&#8217;empreinte au sol<\/li>\n<li>conception modulaire pour une expansion horizontale et verticale ais\u00e9e<\/li>\n<li>disposition multidirectionnelle<\/li>\n<li>sortie facile par un toboggan pour plus de plaisir<\/li>\n<li>diverses combinaisons de couleurs standard avec des possibilit\u00e9s de personnalisation<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb96767&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/ropes-courses\/unharnessed-hex\/\u00a0\u00bb][vc_column_text]\n<h4><a href=\"http:\/\/walltopia.com\/products\/ropes-courses\/family-hex\/\">Family Hex Ropes Course<\/a><\/h4>\n<ul>\n<li>conception modulaire &#8211; extension horizontale facile<\/li>\n<li>deux lignes d&rsquo;obstacles parall\u00e8les, diff\u00e9rentes ou identiques &#8211; pour une exp\u00e9rience partag\u00e9e, id\u00e9ale pour les activit\u00e9s familiales<\/li>\n<li>la meilleure disposition multidirectionnelle<\/li>\n<li>une grande attraction autonome<\/li>\n<li>le plus grand nombre d&rsquo;h\u00f4tes par rapport \u00e0 l&#8217;empreinte au sol<\/li>\n<li>diverses combinaisons de couleurs standard avec des possibilit\u00e9s de personnalisation<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb97349&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/ropes-courses\/family-hex\/\u00a0\u00bb][vc_column_text]\n<h4><a href=\"https:\/\/walltopia.com\/fr\/products\/trampolines\/\">Trampolines<\/a><\/h4>\n<ul>\n<li>de simples tapis de saut \u00e0 une large gamme de jeux et d&rsquo;obstacles diff\u00e9rents pour une dose ultime d&rsquo;amusement<\/li>\n<li>disponible en trois th\u00e8mes de couleurs standard<\/li>\n<li>compl\u00e9ments : \u00c9l\u00e9ments de Parkour, plates-formes de saut, coussins d&rsquo;air, fosses de mousse, murs d&rsquo;escalade, poutres de combat, toboggans, lits trampolines.<\/li>\n<\/ul>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb96415&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/walltopia.com\/products\/trampolines\/\u00a0\u00bb][vc_empty_space][vc_column_text]<strong>Walltopia est le premier fabricant cl\u00e9 en main avec le plus grand portefeuille de solutions de <a href=\"http:\/\/walltopia.com\/walltopia-active-entertainment\/\">divertissement actif.<\/a> \u00c0 ce jour, nous avons r\u00e9alis\u00e9 plus de 2200 projets dans 80 pays du monde entier. Notre passion pour la science et la technologie et notre obsession pour l&rsquo;excellence et la s\u00e9curit\u00e9 nous permettent d&rsquo;obtenir les meilleurs r\u00e9sultats pour nos clients.  <\/strong><\/p>\n<p><strong>Walltopia apporte le meilleur \u00e0 l&rsquo;IAAPA Expo Orlando. Au plaisir de vous y voir ! <\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text]IAAPA Expo Orlando est le premier \u00e9v\u00e9nement international pour Walltopia. Notre \u00e9quipe d&rsquo;experts en divertissement actif comprendra nos cadres sup\u00e9rieurs&#8230;","protected":false},"author":5,"featured_media":109923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[844,868],"tags":[859,863,861,37,700,853,360,880,875,860],"class_list":["post-198190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-divertissement-actif","tag-circle-ropes-course","tag-family-entertainment-centers","tag-family-hex-ropes-course","tag-iaapa","tag-innovation","tag-playgrounds","tag-ropes-course","tag-slides","tag-trampolines","tag-unharnessed-hex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rencontrez-nous \u00e0 l&#039;IAAPA Expo Orlando du 14 au 17 novembre 2023<\/title>\n<meta name=\"description\" content=\"Rencontrez-nous \u00e0 l&#039;IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d&#039;aventure et d&#039;attraction.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rencontrez-nous \u00e0 l&#039;IAAPA Expo Orlando du 14 au 17 novembre 2023\" \/>\n<meta property=\"og:description\" content=\"Rencontrez-nous \u00e0 l&#039;IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d&#039;aventure et d&#039;attraction.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T09:54:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T11:02:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"walltopia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/\"},\"author\":{\"name\":\"walltopia\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\"},\"headline\":\"Rencontrez-nous \u00e0 l&rsquo;IAAPA Expo Orlando du 14 au 17 novembre 2023\",\"datePublished\":\"2023-10-30T09:54:45+00:00\",\"dateModified\":\"2026-06-16T11:02:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/\"},\"wordCount\":896,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030120744\\\/IAAPA_Orlando-2023_2.png\",\"keywords\":[\"Circle Ropes Course\",\"Family Entertainment Centers\",\"Family Hex Ropes Course\",\"IAAPA\",\"innovation\",\"Playgrounds\",\"ropes course\",\"slides\",\"Trampolines\",\"Unharnessed Hex\"],\"articleSection\":[\"Actualit\u00e9s\",\"Divertissement actif\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/\",\"name\":\"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030120744\\\/IAAPA_Orlando-2023_2.png\",\"datePublished\":\"2023-10-30T09:54:45+00:00\",\"dateModified\":\"2026-06-16T11:02:17+00:00\",\"description\":\"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d'aventure et d'attraction.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030120744\\\/IAAPA_Orlando-2023_2.png\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030120744\\\/IAAPA_Orlando-2023_2.png\",\"width\":1200,\"height\":790},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rencontrez-nous \u00e0 l&#8217;IAAPA Expo Orlando du 14 au 17 novembre 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/59be8396ecd46ad663730305c2e802db\",\"name\":\"walltopia\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023","description":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d'aventure et d'attraction.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023","og_description":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d'aventure et d'attraction.","og_url":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-10-30T09:54:45+00:00","article_modified_time":"2026-06-16T11:02:17+00:00","og_image":[{"width":1200,"height":790,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png","type":"image\/png"}],"author":"walltopia","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/"},"author":{"name":"walltopia","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db"},"headline":"Rencontrez-nous \u00e0 l&rsquo;IAAPA Expo Orlando du 14 au 17 novembre 2023","datePublished":"2023-10-30T09:54:45+00:00","dateModified":"2026-06-16T11:02:17+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/"},"wordCount":896,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"image":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png","keywords":["Circle Ropes Course","Family Entertainment Centers","Family Hex Ropes Course","IAAPA","innovation","Playgrounds","ropes course","slides","Trampolines","Unharnessed Hex"],"articleSection":["Actualit\u00e9s","Divertissement actif"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/","url":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/","name":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png","datePublished":"2023-10-30T09:54:45+00:00","dateModified":"2026-06-16T11:02:17+00:00","description":"Rencontrez-nous \u00e0 l'IAAPA Expo Orlando du 14 au 17 novembre 2023, et discutons de la mani\u00e8re dont nous pouvons satisfaire au mieux vos besoins en mati\u00e8re de solutions d'aventure et d'attraction.","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030120744\/IAAPA_Orlando-2023_2.png","width":1200,"height":790},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-expo-orlando-du-14-au-17-novembre-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Rencontrez-nous \u00e0 l&#8217;IAAPA Expo Orlando du 14 au 17 novembre 2023"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/59be8396ecd46ad663730305c2e802db","name":"walltopia"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/198190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=198190"}],"version-history":[{"count":6,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/198190\/revisions"}],"predecessor-version":[{"id":391983,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/198190\/revisions\/391983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media\/109923"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=198190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=198190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=198190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}