{"id":198915,"date":"2023-06-07T23:59:40","date_gmt":"2023-06-07T20:59:40","guid":{"rendered":"https:\/\/walltopia.com\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/"},"modified":"2026-01-15T18:05:47","modified_gmt":"2026-01-15T15:05:47","slug":"rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement","status":"publish","type":"post","link":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/","title":{"rendered":"Rencontrez-nous \u00e0 l&rsquo;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement."},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686225873841{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p><strong>Quatre longues ann\u00e9es se sont \u00e9coul\u00e9es depuis la derni\u00e8re fois que nous avons eu la chance de nous rencontrer \u00e0 IAAPA Asia et d&rsquo;\u00e9changer des id\u00e9es sur les d\u00e9veloppements commerciaux et les innovations, de nous inspirer mutuellement et d&rsquo;explorer les moyens de collaborer et de faire cro\u00eetre l&rsquo;industrie des loisirs ensemble.<\/strong><\/p>\n<p>Notre \u00e9quipe est impatiente de vous rencontrer \u00e0 <strong>Marina Bay Sands, Singapour, du 14 au 16 juin au stand L1122<\/strong> o\u00f9 nous pr\u00e9senterons nos derniers produits et technologies dans le domaine des attractions de divertissement actif.<\/p>\n<p>Au cours des quatre derni\u00e8res ann\u00e9es, nous avons travaill\u00e9 dur pour \u00e9largir notre portefeuille de produits au-del\u00e0 de nos attractions classiques \u00e0 haute adr\u00e9naline, sur la base de notre exp\u00e9rience dans l&rsquo;industrie de l&rsquo;escalade. Nous proposons d\u00e9sormais une large gamme de produits non harnach\u00e9s destin\u00e9s \u00e0 un public plus jeune et\/ou \u00e0 des lieux \u00e0 plafond bas, tout en restant fid\u00e8les \u00e0 notre valeur fondamentale : \u00eatre actif. Notre objectif est de fournir des solutions cl\u00e9s en main aux entreprises de toute taille. Venez nous voir et nous identifierons la bonne combinaison de produits de divertissement actif pour votre site, en fonction de la d\u00e9mographie et du d\u00e9bit souhait\u00e9s, et en fonction de la hauteur de plafond et de l&rsquo;encombrement disponibles.   <\/p>\n<p>&nbsp;<\/p>\n[\/vc_column_text][vc_column_text]Nous sommes impatients de vous rencontrer et d&rsquo;entendre vos t\u00e9moignages sur les trois derni\u00e8res ann\u00e9es &#8211; les d\u00e9fis auxquels chacun a \u00e9t\u00e9 confront\u00e9, les id\u00e9es que vous avez sur les d\u00e9veloppements futurs et, bien s\u00fbr, la mani\u00e8re dont nous pouvons vous aider \u00e0 faire passer votre entreprise et vos r\u00eaves \u00e0 la vitesse sup\u00e9rieure.<\/p>\n<p><strong>Nous pouvons vous fournir un badge d&rsquo;entr\u00e9e gratuit pour vous et votre \u00e9quipe, <a href=\"http:\/\/walltopia.com\/contact-us\/\">contactez-nous pour r\u00e9server votre r\u00e9union !<\/a><\/strong><\/p>\n<p>Nous avons travaill\u00e9 dur pour d\u00e9velopper de nouveaux ajouts \u00e0 notre portefeuille de divertissements actifs ainsi que pour am\u00e9liorer nos produits bien connus. L&rsquo;introduction de la gamification dans les lieux d\u00e9j\u00e0 construits et dans les nouveaux lieux est \u00e9galement un point central afin d&rsquo;augmenter le nombre de visites r\u00e9p\u00e9t\u00e9es dans les centres de divertissement que vous facilitez. Lisez la suite pour d\u00e9couvrir quelques-uns de nos derniers d\u00e9veloppements, mais gardez \u00e0 l&rsquo;esprit notre devise &#8211; sky is the limit &#8211; si vous avez une id\u00e9e non conventionnelle, nos concepteurs et ing\u00e9nieurs sont toujours pr\u00eats \u00e0 relever le d\u00e9fi.<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686151797137{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbRopes Course\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_single_image image=\u00a0\u00bb98925&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686236441659{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Les <a href=\"http:\/\/walltopia.com\/products\/ropes-course\/\">parcours d&rsquo;escalade<\/a> ont \u00e9t\u00e9 le premier produit de divertissement actif que Walltopia a commenc\u00e9 \u00e0 produire, bien avant que nous n&rsquo;ayons l&rsquo;id\u00e9e de d\u00e9velopper une gamme compl\u00e8te de produits de divertissement actif. Nos clients de murs d&rsquo;escalade nous demandaient des parcours de cordes et nous avions les capacit\u00e9s de production et les connaissances techniques n\u00e9cessaires pour les r\u00e9aliser, ce que nous avons fait. Depuis lors, c&rsquo;est l&rsquo;un de nos principaux produits de divertissement actif, que nous nous effor\u00e7ons constamment d&rsquo;am\u00e9liorer et de d\u00e9velopper pour r\u00e9pondre aux besoins de nos clients. \u00c0 l&rsquo;origine, il s&rsquo;agissait d&rsquo;une activit\u00e9 qui faisait monter l&rsquo;adr\u00e9naline et qui avait \u00e9t\u00e9 invent\u00e9e pour initier les gens au plaisir des hauteurs sans qu&rsquo;ils aient re\u00e7u une formation sp\u00e9cifique \u00e0 l&rsquo;escalade. Nous avons cr\u00e9\u00e9 quelques variantes de parcours de cordes qui invitent tous les membres de la famille \u00e0 profiter de l&rsquo;activit\u00e9 ensemble.<\/p>\n[\/vc_column_text][vc_custom_heading text=\u00a0\u00bbParcours d&apos;h\u00e9bertisme non harnach\u00e9\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686233213309{margin-top: 50px !important;}\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_single_image image=\u00a0\u00bb96774&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_column_text css=\u00a0\u00bb.vc_custom_1686236747651{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Un parcours de cordes avec un syst\u00e8me de s\u00e9curit\u00e9 collective, cette attraction n&rsquo;exige pas que les participants portent un harnais, ce qui r\u00e9duit le personnel n\u00e9cessaire pour le fonctionnement. Le parcours de cordes sans harnais se combine id\u00e9alement avec le <a href=\"http:\/\/walltopia.com\/products\/adventure-trail\/\">sentier d&rsquo;aventure, le<\/a> <a href=\"http:\/\/walltopia.com\/products\/cloud-climb\/\">Cloud Climb<\/a> et les <a href=\"http:\/\/walltopia.com\/products\/slides\/\">toboggans<\/a>. Cr\u00e9ez un centre d&rsquo;aventure sans harnais avec une vari\u00e9t\u00e9 d&rsquo;activit\u00e9s et un d\u00e9bit \u00e9lev\u00e9 en combinant ces \u00e9l\u00e9ments.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=\u00a0\u00bbParcours de cordes pour les familles\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686236535138{margin-top: 50px !important;}\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_column_text css=\u00a0\u00bb.vc_custom_1686235979510{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Le Family Ropes Course dispose d&rsquo;une double ligne permettant aux parents et aux enfants de profiter du frisson des hauteurs, \u00e9paule contre \u00e9paule. La ligne int\u00e9rieure est con\u00e7ue avec des obstacles plus faciles pour les jeunes participants, tandis que la ligne ext\u00e9rieure comporte une version plus difficile, ce qui garantit que les adultes ne seront pas laiss\u00e9s sans d\u00e9fi.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_single_image image=\u00a0\u00bb97384&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=\u00a0\u00bbCombinaison parcours acrobatique + Rollglider\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686236051349{margin-top: 50px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686236317481{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Combinaison ultime pour les amateurs de sensations fortes, l&rsquo;attraction combin\u00e9e Rollglider et parcours de cordes utilise une ligne de Rollglider comme syst\u00e8me d&rsquo;assurage, ce qui permet un syst\u00e8me d&rsquo;assurage continu pour les deux activit\u00e9s et ne n\u00e9cessite pas de personnel suppl\u00e9mentaire pour faciliter le changement. Les participants se poussent \u00e0 travers les obstacles d&rsquo;un parcours de cordes nivel\u00e9 jusqu&rsquo;\u00e0 une plate-forme finale d&rsquo;o\u00f9 ils sautent sur la piste de Rollglider avec des boucles et des courbes.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686151797137{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbROLLGLIDER\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_single_image image=\u00a0\u00bb100625&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686152476426{margin-bottom: 30px !important;}\u00a0\u00bb]Apr\u00e8s avoir pr\u00e9sent\u00e9 le premier <a href=\"http:\/\/walltopia.com\/products\/rollglider\/\">Rollglider <\/a>au monde en 2014, nous avons d\u00e9velopp\u00e9 des variantes de l&rsquo;attraction qui conviendraient \u00e0 une vari\u00e9t\u00e9 de lieux et aux caprices de chacun.<\/p>\n<p>En commen\u00e7ant par un man\u00e8ge a\u00e9rien bas\u00e9 sur la gravit\u00e9, disponible en une seule couleur, nous avons \u00e9largi notre gamme pour inclure des chariots \u00e9lectriques pour les lieux qui n&rsquo;ont pas la hauteur de plafond permettant un man\u00e8ge \u00e0 gravit\u00e9 (il n\u00e9cessite une certaine diff\u00e9rence d&rsquo;\u00e9l\u00e9vation entre le d\u00e9part et l&rsquo;arriv\u00e9e pour fonctionner sans heurts). Avec le man\u00e8ge \u00e9lectrique, le participant peut \u00e9galement contr\u00f4ler la vitesse et la maintenir dans sa zone de confort, qu&rsquo;elle soit plus rapide ou plus lente ! Une s\u00e9lection de couleurs pour la piste est \u00e9galement disponible afin de s&rsquo;adapter au th\u00e8me de votre centre. Les rollgliders peuvent \u00eatre extr\u00eames ou panoramiques, rapides ou lents &#8211; vous pouvez voler ou planer, seul ou en tandem &#8211; les choix sont infinis !   <\/p>\n<p>Pour vous donner un avant-go\u00fbt, voici l&rsquo;un de nos derniers d\u00e9veloppements :<\/p>\n[\/vc_column_text][vc_custom_heading text=\u00a0\u00bbJump&amp;Run Rollglider Ride\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686151819579{margin-top: 50px !important;}\u00a0\u00bb][vc_column_text]Le <a href=\"https:\/\/rollglider.com\/jump-and-run\/\">Jump&amp;Run<\/a> est n\u00e9 du d\u00e9sir de combiner le meilleur de deux mondes &#8211; le divertissement actif et les man\u00e8ges \u00e0 sensations fortes. Pour atteindre cet objectif, cette aventure combine une piste de course de Rollglider \u00e0 double ligne avec des obstacles inspir\u00e9s des parcours d&rsquo;aventure.[\/vc_column_text][vc_single_image image=\u00a0\u00bb79385&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686224714139{margin-top: 30px !important;margin-bottom: 30px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686151884151{margin-bottom: 30px !important;}\u00a0\u00bb]Avec des obstacles inspir\u00e9s des parcours de d\u00e9fi et une bonne dose de sensations fortes, le Jump&amp;Run est une comp\u00e9tition unique en son genre qui exige une bonne condition physique et la volont\u00e9 de se d\u00e9passer.<\/p>\n<p>Le concept s&rsquo;av\u00e8re attrayant pour les jeunes visiteurs car il s&rsquo;inspire de jeux vid\u00e9o tels que Super Mario et permet de s&rsquo;immerger totalement dans l&rsquo;id\u00e9e d&rsquo;\u00eatre un super-h\u00e9ros en chair et en os. L&rsquo;aspect ludique de l&rsquo;attraction permet de comptabiliser les points et peut jouer un r\u00f4le dans les programmes de fid\u00e9lisation en r\u00e9compensant les participants les plus d\u00e9vou\u00e9s.<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686151797137{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbCLOUD CLIMB\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686152683329{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>L&rsquo;<a href=\"http:\/\/walltopia.com\/products\/cloud-climb\/\">escalade des nuages<\/a> fait partie de notre portefeuille depuis un certain temps &#8211; une activit\u00e9 amusante sans harnais pour les plus jeunes participants. Nous l&rsquo;avons port\u00e9 \u00e0 un autre niveau en lui donnant une touche cr\u00e9ative. D\u00e9sormais, non seulement nous pouvons donner diff\u00e9rentes formes aux \u00ab\u00a0feuilles\u00a0\u00bb du Cloud Climb gr\u00e2ce \u00e0 nos machines CnC pr\u00e9cises, mais nous ajoutons \u00e9galement des lumi\u00e8res LED sur les bords. Nous le savons tous : les enfants adorent les lumi\u00e8res color\u00e9es et les \u00e9l\u00e9ments lumineux ! Le Cloud Climb est une attraction autoportante qui peut \u00eatre con\u00e7ue pour s&rsquo;adapter \u00e0 n&rsquo;importe quelle hauteur de plafond et qui convient aux centres commerciaux, aux aires de jeux int\u00e9rieures et ext\u00e9rieures, aux FEC et \u00e0 bien d&rsquo;autres endroits encore.    <\/p>\n<p>Le Cloud Climb peut prendre de nombreuses formes et tailles :<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686153906660{margin-bottom: 30px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_column_text css=\u00a0\u00bb.vc_custom_1686153793225{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Le <a href=\"http:\/\/walltopia.com\/projects\/woo-hoo-museum-uae-dubai\/\">mus\u00e9e Woohoo<\/a> aux \u00c9mirats arabes unis a pr\u00e9sent\u00e9 l&rsquo;attraction dans un espace bas de plafond, ce qui lui conf\u00e8re un aspect color\u00e9 et amusant.<\/p>\n[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb3\/4&Prime;][vc_single_image image=\u00a0\u00bb100679&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686153913941{margin-bottom: 30px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_single_image image=\u00a0\u00bb100686&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text css=\u00a0\u00bb.vc_custom_1686152933236{margin-bottom: 30px !important;}\u00a0\u00bb]<a href=\"http:\/\/walltopia.com\/projects\/la-tete-dans-les-nuages-2\/\">LA T\u00caTE DANS LES NUAGES<\/a> \u00e0 Nice, France, a utilis\u00e9 l&rsquo;espace libre juste \u00e0 c\u00f4t\u00e9 des escaliers m\u00e9caniques du centre commercial avec un design en hauteur d&rsquo;un Cloud Climb qui offre un moyen amusant de descendre &#8211; \u00e0 travers notre nouveau <a href=\"http:\/\/walltopia.com\/products\/slides\/\">toboggan Walltopia<\/a> en acier inoxydable. Les bords \u00e9clair\u00e9s par des LED attirent les visiteurs de loin.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686153921278{margin-bottom: 30px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_column_text css=\u00a0\u00bb.vc_custom_1686153148717{margin-bottom: 30px !important;}\u00a0\u00bb]Le mus\u00e9e des enfants <a href=\"http:\/\/walltopia.com\/projects\/phaeno\/\">Phaeno <\/a>de Wolfsburg, en Allemagne, a fait les choses en grand avec le Cloud Climb, en ajoutant des attractions amusantes le long du parcours qui font participer les jeunes participants et les aident \u00e0 apprendre tout en d\u00e9veloppant leur mobilit\u00e9.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb3\/4&Prime;][vc_single_image image=\u00a0\u00bb81540&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb add_caption=\u00a0\u00bbyes\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686155262937{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbDIAPORAMA\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686239390624{margin-top: 50px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686154271738{margin-bottom: 30px !important;}\u00a0\u00bb]<a href=\"http:\/\/walltopia.com\/products\/slides\/\">Walltopia Slides<\/a> est un nouveau bijou dans le portefeuille de Walltopia. Qu&rsquo;il soit droit ou tordu, ouvert ou ferm\u00e9, un toboggan est la meilleure fa\u00e7on de descendre d&rsquo;une attraction grimpante (ou non, d&rsquo;ailleurs). Soyons honn\u00eates, nous avons tous secr\u00e8tement aim\u00e9 accompagner nos enfants sur un toboggan pour adultes, n&rsquo;est-ce pas ?<\/p>\n<p>Les glissi\u00e8res sont disponibles en deux types diff\u00e9rents &#8211; glissi\u00e8re \u00e0 tube ferm\u00e9 ou glissi\u00e8re transparente, en acier inoxydable combin\u00e9 \u00e0 des panneaux panoramiques en polycarbonate. Le rev\u00eatement permet de peindre dans n&rsquo;importe quelle couleur RAL. Ils peuvent \u00e9galement \u00eatre combin\u00e9s avec des effets d&rsquo;\u00e9clairage LED \u00e0 l&rsquo;ext\u00e9rieur pour obtenir le th\u00e8me d\u00e9sir\u00e9. Les toboggans font sourire les gens dans tout type d&rsquo;espace public.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_single_image image=\u00a0\u00bb81846&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb100735&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686155275304{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbNET MAZE\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=\u00a0\u00bb97692&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686154453329{margin-bottom: 30px !important;}\u00a0\u00bb]<a href=\"http:\/\/walltopia.com\/products\/net-maze\/\">Les labyrinthes Walltopia Net<\/a> sont une nouvelle gamme de produits de divertissement actif pour les enfants les plus jeunes. Sans harnais et en toute s\u00e9curit\u00e9, gr\u00e2ce \u00e0 notre vaste exp\u00e9rience dans le domaine de l&rsquo;escalade, nous avons con\u00e7u la gamme parfaite d&rsquo;attractions pour que les enfants soient en s\u00e9curit\u00e9, actifs et pleins de joie.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1686155281202{margin-top: 50px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbTRAMPOLINES\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686154991454{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p><a href=\"http:\/\/walltopia.com\/products\/trampolines\/\">Les trampolines <\/a> ne sont peut-\u00eatre pas un nouveau produit dans l&rsquo;industrie du divertissement actif, mais ils sont nouveaux pour notre portefeuille de production. Avec une large gamme de produits, nous avons fait \u00e9voluer notre offre d&rsquo;activit\u00e9s ax\u00e9es sur l&rsquo;escalade \u00e0 un v\u00e9ritable fournisseur cl\u00e9 en main d&rsquo;attractions de divertissement actif destin\u00e9es \u00e0 des clients de tous horizons. Il y a peu de temps encore, nous devions confier la production de trampolines \u00e0 une autre soci\u00e9t\u00e9, avant de nous rendre compte que nous disposions non seulement des capacit\u00e9s de production n\u00e9cessaires, mais aussi d&rsquo;une vaste exp\u00e9rience dans le travail des mat\u00e9riaux qui composent un parc de trampolines. Les trampolines disposent d\u00e9sormais d&rsquo;un espace d\u00e9di\u00e9 dans notre usine, ce qui permet \u00e0 nos clients de faire exp\u00e9dier toutes leurs attractions depuis la m\u00eame usine dans le m\u00eame conteneur !<\/p>\n[\/vc_column_text][vc_single_image image=\u00a0\u00bb80205&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686224778065{margin-bottom: 30px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686155001350{margin-bottom: 30px !important;}\u00a0\u00bb]\n<p>Les trampolines sont pass\u00e9s de simples tapis de saut \u00e0 une large gamme de jeux et d&rsquo;obstacles diff\u00e9rents.<\/p>\n<ul>\n<li>Ajoutez un coussin gonflable, une poutre de combat, une fosse en mousse, des obstacles souples de parkour ou m\u00eame un mur d&rsquo;escalade pour une dose ultime de plaisir.<\/li>\n<li>Les trampolines pour activit\u00e9s de groupe sont un ajout passionnant \u00e0 chaque zone de saut. Ajouter un terrain de basket-ball ou de balle au prisonnier<\/li>\n<li>Ajoutez de l&rsquo;interactivit\u00e9 avec Valo Jump<\/li>\n<li>Choisissez entre diff\u00e9rents types de trampolines tels que : les trampolines \u00e0 long couloir, les trampolines \u00e0 glissi\u00e8re, les trampolines \u00e0 angle et autres.<\/li>\n<li>N&rsquo;oubliez pas de d\u00e9signer une zone pour les plus jeunes sauteurs : le Kids Court.<\/li>\n<\/ul>\n[\/vc_column_text][vc_custom_heading text=\u00a0\u00bbCe n&apos;est qu&apos;un aper\u00e7u de ce sur quoi nous avons travaill\u00e9. Venez visiter notre stand \u00e0 IAAPA Asia pour en savoir plus sur les nouveaux murs d&apos;escalade, le parcours d&apos;escalade et les grottes, et bien plus encore. <\/p>\n<p>Nous nous r\u00e9jouissons de vous voir \u00e0 Singapour la semaine prochaine !\u00a0\u00bb font_container=\u00a0\u00bbtag:h6|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686171493915{margin-top: 50px !important;}\u00a0\u00bb]<div class=\"link-button-container block width-100  text-align-center\"><a class=\"wt-link \" href=\"https:\/\/walltopia.com\/contact-us\/\" target=\"_blank\">Book a meeting<\/a><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=\u00a0\u00bbProjets Walltopia \u00e0 Singapour\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686172457111{margin-top: 50px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1686172360819{margin-bottom: 30px !important;}\u00a0\u00bb]Si vous avez un peu de temps libre \u00e0 Singapour pendant la visite de l&rsquo;IAAPA Asia, vous pouvez visiter quelques-uns des sites que nous avons r\u00e9alis\u00e9s et vous familiariser avec notre travail de premi\u00e8re main.<\/p>\n<p>Vous pouvez visiter le site :<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"http:\/\/walltopia.com\/projects\/hometeamns\/\">Le QG de l&rsquo;aventure de Hometeam NS<\/a> comprend un centre d&rsquo;aventure Walltopia &#8211; une attraction massive combinant le Rollglider, un parcours de cordes autoportant, un sentier d&rsquo;aventure, des grottes, une escalade de nuages, un parcours Ninja et des murs d&rsquo;amusement ;<\/li>\n<li><a href=\"http:\/\/walltopia.com\/projects\/nerf-action-xperience\/\">Nerf Action Xperience<\/a> avec des murs d&rsquo;amusement et un parcours de cordes suspendu au plafond<\/li>\n<li><a href=\"http:\/\/walltopia.com\/projects\/climb-central\/\">Climb Central<\/a> &#8211; une vitrine parfaite pour l&rsquo;utilisation de l&rsquo;espace libre \u00e0 haut plafond dans le hall d&rsquo;un centre commercial pour un centre d&rsquo;escalade.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n[\/vc_column_text]<div class=\"related-projects-container info-block-container info-block shdw carousel-on margin-bottom-100\"><h2 class=\"title\">Nos projets<\/h2><div class=\"related-projects-carousel\"><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027134347\/AHQ-Khatib-1-800x450.webp&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/hometeamns\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">HomeTeamNS<\/h3><p class=\"item-location\"><\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027134327\/nerf-action-xperience-04-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/nerf-action-xperience\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Nerf Action Xperience<\/h3><p class=\"item-location\">Singapore<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030094059\/climb-central-2-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/climb-central\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Climb Central<\/h3><p class=\"item-location\">Singapore<\/p><\/a><\/div><\/div><div class=\"width-100 block float-left text-align-center\"><a href=\"https:\/\/walltopia.com\/fr\/projects\/\" class=\"wt-link hover-effect-fast margin-top-25 margin-bottom-25\">Voir tous les projets<\/a><\/div><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text css_animation=\u00a0\u00bbslideInLeft\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1686225873841{margin-bottom: 30px !important;}\u00a0\u00bb] Quatre longues ann\u00e9es se sont \u00e9coul\u00e9es depuis la derni\u00e8re fois que nous avons eu la&#8230;","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[844,868],"tags":[],"class_list":["post-198915","post","type-post","status-publish","format-standard","hentry","category-actualites","category-divertissement-actif"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rencontrez-nous \u00e0 l&#039;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement. | Walltopia<\/title>\n<meta name=\"description\" content=\"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rencontrez-nous \u00e0 l&#039;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement.\" \/>\n<meta property=\"og:description\" content=\"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-07T20:59:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T15:05:47+00:00\" \/>\n<meta name=\"author\" content=\"Ani Manova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@walltopiabg\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/\"},\"author\":{\"name\":\"Ani Manova\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\"},\"headline\":\"Rencontrez-nous \u00e0 l&rsquo;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement.\",\"datePublished\":\"2023-06-07T20:59:40+00:00\",\"dateModified\":\"2026-01-15T15:05:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/\"},\"wordCount\":3010,\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Actualit\u00e9s\",\"Divertissement actif\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/\",\"name\":\"Rencontrez-nous \u00e0 l'IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement. | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-06-07T20:59:40+00:00\",\"dateModified\":\"2026-01-15T15:05:47+00:00\",\"description\":\"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/accueil-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rencontrez-nous \u00e0 l&#8217;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/fr\\\/#\\\/schema\\\/person\\\/12e3d2cc8853cc95d0f08065e0bc93f1\",\"name\":\"Ani Manova\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rencontrez-nous \u00e0 l'IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement. | Walltopia","description":"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/","og_locale":"fr_FR","og_type":"article","og_title":"Rencontrez-nous \u00e0 l'IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement.","og_description":"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !","og_url":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_published_time":"2023-06-07T20:59:40+00:00","article_modified_time":"2026-01-15T15:05:47+00:00","author":"Ani Manova","twitter_card":"summary_large_image","twitter_creator":"@walltopiabg","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/#article","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/"},"author":{"name":"Ani Manova","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1"},"headline":"Rencontrez-nous \u00e0 l&rsquo;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement.","datePublished":"2023-06-07T20:59:40+00:00","dateModified":"2026-01-15T15:05:47+00:00","mainEntityOfPage":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/"},"wordCount":3010,"publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"articleSection":["Actualit\u00e9s","Divertissement actif"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/","url":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/","name":"Rencontrez-nous \u00e0 l'IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement. | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/fr\/#website"},"datePublished":"2023-06-07T20:59:40+00:00","dateModified":"2026-01-15T15:05:47+00:00","description":"Discutons de solutions cl\u00e9s en main pour votre entreprise de divertissement !","breadcrumb":{"@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/fr\/rencontrez-nous-a-liaapa-asia-et-discutez-de-solutions-cles-en-main-pour-votre-entreprise-de-divertissement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/fr\/accueil-fr\/"},{"@type":"ListItem","position":2,"name":"Rencontrez-nous \u00e0 l&#8217;IAAPA Asia et discutez de solutions cl\u00e9s en main pour votre entreprise de divertissement."}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/fr\/#website","url":"https:\/\/walltopia.com\/fr\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/fr\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]},{"@type":"Person","@id":"https:\/\/walltopia.com\/fr\/#\/schema\/person\/12e3d2cc8853cc95d0f08065e0bc93f1","name":"Ani Manova"}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/198915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/comments?post=198915"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/posts\/198915\/revisions"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/media?parent=198915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/categories?post=198915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walltopia.com\/fr\/wp-json\/wp\/v2\/tags?post=198915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}